{"id":7621,"date":"2022-08-30T02:27:41","date_gmt":"2022-08-30T07:27:41","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/como-la-metabolomica-podria-ser-la-ultima-incorporacion-al-conjunto-de-herramientas-de-un-patologo-forense\/"},"modified":"2022-08-30T02:27:41","modified_gmt":"2022-08-30T07:27:41","slug":"como-la-metabolomica-podria-ser-la-ultima-incorporacion-al-conjunto-de-herramientas-de-un-patologo-forense","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/como-la-metabolomica-podria-ser-la-ultima-incorporacion-al-conjunto-de-herramientas-de-un-patologo-forense\/","title":{"rendered":"C\u00f3mo la metabol\u00f3mica podr\u00eda ser la \u00faltima incorporaci\u00f3n al conjunto de herramientas de un pat\u00f3logo forense"},"content":{"rendered":"<p>A. Puntuaci\u00f3n y parcelas de carga de PCA. Se trazan 10 muestras del grupo DM (rojo) y 10 muestras del grupo negativo (Ng) (verde) en funci\u00f3n de 22 iones con significaci\u00f3n estad\u00edstica en el an\u00e1lisis dirigido a sustancias hidrof\u00edlicas. El gr\u00e1fico de carga corresponde al gr\u00e1fico de puntuaci\u00f3n de PCA, con un gr\u00e1fico que representa un solo ion. A partir de este gr\u00e1fico, es posible comprender visualmente cu\u00e1les son los componentes caracter\u00edsticos de los grupos DM y Ng, respectivamente.B. An\u00e1lisis de mapa de calor de metabol\u00f3mica para sustancias hidrof\u00edlicas. La fila muestra los iones y la columna representa las muestras. Los iones con niveles significativamente m\u00e1s bajos se muestran en azul, mientras que los iones con niveles significativamente m\u00e1s altos se muestran en rojo. El brillo de cada color corresponde a la magnitud de la diferencia cuando se compara con el valor promedio. Las muestras forman aproximadamente grupos del grupo DM (rojo) y el grupo Ng (verde). Cr\u00e9dito: Maika Nariai <\/p>\n<p>Determinar la causa de la muerte es una de las partes m\u00e1s cruciales y desafiantes de una investigaci\u00f3n forense. Conocer el historial m\u00e9dico del difunto puede facilitar significativamente esta tarea e incluso ayudar a los pat\u00f3logos forenses a inferir el estado del difunto antes de morir. Sin embargo, esta informaci\u00f3n no siempre est\u00e1 disponible, como en el caso de una enfermedad no diagnosticada. Por ejemplo, la diabetes mellitus (DM), una importante enfermedad cr\u00f3nica con una alta prevalencia global, es notoriamente dif\u00edcil de diagnosticar post mortem como causa de muerte, especialmente cuando el historial m\u00e9dico del difunto no est\u00e1 disponible antes de la autopsia. Las pruebas bioqu\u00edmicas actuales utilizadas para diagnosticar DM despu\u00e9s de la muerte cada uno tiene sus limitaciones. <\/p>\n<p>La metabol\u00f3mica, que es el estudio de metabolitos como az\u00facares, amino\u00e1cidos y l\u00edpidos dentro de los sistemas biol\u00f3gicos, es una herramienta emergente r\u00e1pidamente en el campo de la medicina de precisi\u00f3n. El an\u00e1lisis metabol\u00f3mico se ha utilizado para diagnosticar enfermedades complejas que van desde el c\u00e1ncer colorrectal hasta la depresi\u00f3n. Sin embargo, la mayor\u00eda de los estudios hasta la fecha han utilizado el enfoque metabol\u00f3mico para buscar biomarcadores de enfermedades en muestras de personas vivas. Si bien el an\u00e1lisis metabol\u00f3mico de muestras post mortem no se ha estudiado con tanto detalle, podr\u00eda ofrecer un enfoque mucho m\u00e1s confiable para el diagn\u00f3stico.<\/p>\n<p>Esta posibilidad inst\u00f3 a un grupo de cient\u00edficos, incluida la Sra. Maika Nariai, quien fue un estudiante de medicina en el momento de realizar el estudio en el Departamento de Medicina Forense de la Universidad de Tokio, para usar el an\u00e1lisis metabol\u00f3mico para encontrar biomarcadores post mortem que reflejen la historia de DM de un difunto. El equipo de investigaci\u00f3n tambi\u00e9n estaba formado por el Dr. Yohsuke Makino del Departamento de Medicina Forense de la Universidad de Tokio y la Dra. Hiroko Abe, la Dra. Yumi Hoshioka y el Prof. Hirotaro Iwase del Departamento de Medicina Legal de la Universidad de Chiba. Sus hallazgos se publicaron recientemente en The International Journal of Legal Medicine.<\/p>\n<p>El equipo seleccion\u00f3 10 sujetos con antecedentes de DM y otros 10 sin antecedentes confirmados de DM a los que se les realiz\u00f3 autopsia en un departamento de medicina legal en Jap\u00f3n entre 2014 y 2017. Realizaron un an\u00e1lisis metabol\u00f3mico en muestras de sangre post m\u00f3rtem para encontrar biomarcadores que potencialmente reflejaran un historial de DM. Curiosamente, observaron que dos clases de l\u00edpidos, la esfingomielina y los plasmal\u00f3genos, eran significativamente m\u00e1s bajos, mientras que los lisofosfol\u00edpidos eran m\u00e1s altos en los sujetos con DM que en los sujetos con DM. aquellos sin antecedentes conocidos de DM, lo que sugiere que estos metabolitos podr\u00edan usarse como biomarcadores para el diagn\u00f3stico forense de DM.<\/p>\n<p>Al saludar este resultado, la Sra. Nariai dice: \u00abNuestros hallazgos tienen el potencial de impulsar la investigaci\u00f3n metabol\u00f3mica en ciencia forense y conducir a la mejora de la calidad de las investigaciones forenses al diagnosticar con precisi\u00f3n la diabetes incluso despu\u00e9s de la muerte. Tambi\u00e9n puede ayudar a mejorar la salud p\u00fablica y la r producir acusaciones falsas\u00bb.<\/p>\n<p>Entonces, \u00bfcu\u00e1les son las implicaciones a largo plazo de estos hallazgos?<\/p>\n<p>La Sra. Nariai tiene una respuesta: \u00abLos marcadores de diagn\u00f3stico forense para otras enfermedades y afecciones se pueden encontrar si se realizan m\u00e1s investigaciones sobre metabol\u00f3mica utilizando muestras post mortem. Esto ser\u00e1 \u00fatil para investigar casos en los que la causa de la muerte no est\u00e1 clara. Adem\u00e1s, la metabol\u00f3mica de las muestras post mortem Las muestras tambi\u00e9n pueden proporcionar nuevos conocimientos sobre el diagn\u00f3stico y el tratamiento de varias enfermedades y una mejor comprensi\u00f3n de los cambios despu\u00e9s de la muerte\u00bb.<\/p>\n<p>El equipo de investigaci\u00f3n conf\u00eda en que con m\u00e1s investigaciones que utilicen muestras post mortem, la metabol\u00f3mica se convertir\u00e1 en una valiosa adici\u00f3n. a la caja de herramientas de un pat\u00f3logo forense. \u00abAdem\u00e1s de la sangre, creemos que otras muestras post mortem, como el cabello, la orina y el humor v\u00edtreo, pueden proporcionar resultados \u00fatiles para la identificaci\u00f3n de biomarcadores\u00bb, concluye la Sra. Nariai. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> La interrogaci\u00f3n post mortem de dispositivos card\u00edacos implantables es \u00fatil <strong>M\u00e1s informaci\u00f3n:<\/strong> Maika Nariai et al, Perfiles de biomarcadores de sangre post mortem para diabetes mellitus y debate sobre las posibles aplicaciones de la metabol\u00f3mica para el trabajo de casos forense, Internacional Revista de Medicina Legal (2022). DOI: 10.1007\/s00414-021-02767-w Proporcionado por la Universidad de Chiba <strong>Cita<\/strong>: C\u00f3mo la metabol\u00f3mica podr\u00eda ser la \u00faltima incorporaci\u00f3n al conjunto de herramientas de un pat\u00f3logo forense (2022, 28 de febrero) recuperado el 29 de agosto de 2022 de https:\/ \/medicalxpress.com\/news\/2022-02-metabolomics-addition-forensic-pathologist-toolkit.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A. Puntuaci\u00f3n y parcelas de carga de PCA. Se trazan 10 muestras del grupo DM (rojo) y 10 muestras del grupo negativo (Ng) (verde) en funci\u00f3n de 22 iones con significaci\u00f3n estad\u00edstica en el an\u00e1lisis dirigido a sustancias hidrof\u00edlicas. El gr\u00e1fico de carga corresponde al gr\u00e1fico de puntuaci\u00f3n de PCA, con un gr\u00e1fico que representa &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/como-la-metabolomica-podria-ser-la-ultima-incorporacion-al-conjunto-de-herramientas-de-un-patologo-forense\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abC\u00f3mo la metabol\u00f3mica podr\u00eda ser la \u00faltima incorporaci\u00f3n al conjunto de herramientas de un pat\u00f3logo forense\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7621","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7621"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7621\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}