{"id":7640,"date":"2022-08-30T02:28:13","date_gmt":"2022-08-30T07:28:13","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/la-presion-arterial-alta-puede-aumentar-el-riesgo-futuro-de-enfermedad-renal-en-mujeres-embarazadas\/"},"modified":"2022-08-30T02:28:13","modified_gmt":"2022-08-30T07:28:13","slug":"la-presion-arterial-alta-puede-aumentar-el-riesgo-futuro-de-enfermedad-renal-en-mujeres-embarazadas","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/la-presion-arterial-alta-puede-aumentar-el-riesgo-futuro-de-enfermedad-renal-en-mujeres-embarazadas\/","title":{"rendered":"La presi\u00f3n arterial alta puede aumentar el riesgo futuro de enfermedad renal en mujeres embarazadas"},"content":{"rendered":"<p>Las mujeres con condiciones de presi\u00f3n arterial alta durante el embarazo pueden tener el doble de riesgo de enfermedad renal varios a\u00f1os despu\u00e9s de dar a luz, seg\u00fan un nuevo estudio que encuentra el riesgo sube a casi cuatro veces para las mujeres que ya ten\u00edan presi\u00f3n arterial alta antes del embarazo. <\/p>\n<p>El estudio, publicado el viernes en la revista Hypertension de la Asociaci\u00f3n Estadounidense del Coraz\u00f3n, encontr\u00f3 que el riesgo era mayor para las mujeres negras que para las mujeres blancas.<\/p>\n<p>Aunque investigaciones anteriores han analizado la presi\u00f3n arterial alta y la enfermedad renal relacionadas con el embarazo , los autores del nuevo estudio dijeron que esos an\u00e1lisis no incluyeron una representaci\u00f3n racial diversa, aunque las mujeres negras tienen tasas m\u00e1s altas de estas condiciones que sus pares blancas. Seg\u00fan los Centros para el Control y la Prevenci\u00f3n de Enfermedades, las mujeres negras tambi\u00e9n tienen tres veces m\u00e1s probabilidades de morir por problemas relacionados con el embarazo que las mujeres blancas.<\/p>\n<p>Todo esto subraya la necesidad de una buena atenci\u00f3n prenatal, dijo el estudio co- Dulaney Wilson, profesora asistente de investigaci\u00f3n en el departamento de ciencias de la salud p\u00fablica de la Universidad M\u00e9dica de Carolina del Sur en Charleston.<\/p>\n<p>\u00abQuienquiera que cuide a estas mujeres, debe ser consciente de que la enfermedad renal, aunque la la tasa general sigue siendo baja podr\u00eda ser un problema grave\u00bb, dijo Wilson. \u00abEsto es algo que nos gustar\u00eda prevenir en la medida de lo posible\u00bb.<\/p>\n<p>M\u00e1s del 15 % de las mujeres se ven afectadas por alg\u00fan tipo de hipertensi\u00f3n relacionada con el embarazo durante sus a\u00f1os reproductivos, seg\u00fan un comunicado cient\u00edfico de la AHA. publicado en diciembre. Las condiciones incluyen preeclampsia, que puede afectar los ri\u00f1ones, el h\u00edgado, los pulmones y el cerebro; eclampsia, cuando la preeclampsia progresa a convulsiones o coma; hipertensi\u00f3n gestacional, un aumento de la presi\u00f3n arterial despu\u00e9s de las 20 semanas de embarazo; e hipertensi\u00f3n cr\u00f3nica, presi\u00f3n arterial alta antes o durante las primeras 19 semanas de embarazo y m\u00e1s de 12 semanas despu\u00e9s del nacimiento del beb\u00e9. Estos trastornos pueden provocar la muerte o da\u00f1os en los \u00f3rganos, incluida la enfermedad renal en etapa terminal, cuando los ri\u00f1ones ya no pueden funcionar por s\u00ed solos.<\/p>\n<p>Los investigadores analizaron los registros hospitalarios de 391\u00a0838 mujeres que dieron a luz en Carolina del Sur entre 2004 y 2016, junto con los datos pertinentes de los certificados de nacimiento y defunci\u00f3n. Alrededor del 35% de las mujeres eran negras y el 65% eran blancas. Ten\u00edan entre 12 y 49 a\u00f1os de edad en el momento del parto y se les dio seguimiento a los tres, cinco y 14 a\u00f1os despu\u00e9s del parto.<\/p>\n<p>El riesgo de enfermedad renal despu\u00e9s de tres a\u00f1os fue 2,29 veces mayor en las mujeres que desarrollaron hipertensi\u00f3n relacionada con el embarazo en comparaci\u00f3n con mujeres sin problemas de presi\u00f3n arterial. Pero el riesgo era mayor entre las mujeres que tambi\u00e9n ten\u00edan presi\u00f3n arterial alta antes del embarazo. Estas mujeres ten\u00edan 3,8 veces m\u00e1s probabilidades de desarrollar enfermedad renal dentro de los tres a\u00f1os posteriores al parto que sus pares que no ten\u00edan problemas de presi\u00f3n arterial. A los 14 a\u00f1os despu\u00e9s del parto, disminuy\u00f3 a un riesgo 2,7 veces mayor en comparaci\u00f3n con las mujeres que no tuvieron problemas de presi\u00f3n arterial antes o durante el embarazo.<\/p>\n<p>Cuando los resultados se desglosaron por raza, el riesgo de las mujeres negras fue a\u00fan mayor. Las mujeres negras que ten\u00edan presi\u00f3n arterial alta antes del embarazo y trastornos de hipertensi\u00f3n relacionados con el embarazo ten\u00edan el triple de riesgo de desarrollar enfermedad renal dentro de los 14 a\u00f1os posteriores al parto en comparaci\u00f3n con las mujeres negras sin problemas de presi\u00f3n arterial, mientras que las mujeres blancas ten\u00edan un riesgo 1,97 veces mayor que su sus compa\u00f1eros.<\/p>\n<p>Si bien esperaba encontrar disparidades entre las mujeres negras y blancas, Wilson dijo: \u00abMe sorprendi\u00f3 mucho la magnitud de la diferencia\u00bb.<\/p>\n<p>\u00abEste estudio brinda m\u00e1s apoyo a la idea de que el embarazo puede ser una ventana a su salud futura\u00bb, dijo Judette Louis, profesora asociada y presidenta del departamento de obstetricia y ginecolog\u00eda de la Facultad de Medicina Morsani de la Universidad del Sur de Florida en Tampa.<\/p>\n<p>La mayor\u00eda de los estudios sobre la presi\u00f3n arterial alta durante el embarazo se han centrado en el riesgo cardiovascular subsiguiente para la madre, dijo Louis, que no particip\u00f3 en el estudio. Pero esta nueva investigaci\u00f3n sugiere que el estr\u00e9s del embarazo puede estar exacerbando o sacando a la luz otras condiciones subyacentes.<\/p>\n<p>El estudio, dijo, tambi\u00e9n expone m\u00e1s formas en las que los determinantes sociales de la salud, las condiciones en los lugares donde las personas viven, trabajan y el juego puede estar afectando desproporcionadamente a las mujeres negras.<\/p>\n<p>\u00abAlgunos de los determinantes sociales de la salud, como la falta de acceso a la atenci\u00f3n, pueden predisponerlas a tener un diagn\u00f3stico y tratamiento tard\u00edos para la presi\u00f3n arterial alta, que en a su vez puede conducir a problemas como la enfermedad renal en etapa terminal\u00bb, dijo Louis.<\/p>\n<p>Saber que las mujeres negras pueden enfrentar un mayor riesgo de enfermedad renal despu\u00e9s del embarazo debe hacer que los profesionales de la salud les pregunten sobre su historial de salud durante el embarazo. , ella dijo. \u00abDeben ser agresivos en la b\u00fasqueda de factores de riesgo modificables y asesorar a las mujeres sobre la importancia de continuar con su propia atenci\u00f3n m\u00e9dica despu\u00e9s de dar a luz\u00bb, lo que puede ser un problema para las mujeres con cobertura de seguro limitada o nula.<\/p>\n<p>Los pasos para mantener la presi\u00f3n arterial dentro del rango normal incluyen mantenerse f\u00edsicamente activo, comer una dieta alta en frutas y verduras y baja en grasas saturadas, y limitar el sodio.<\/p>\n<p>Wilson dijo que las mujeres que est\u00e1n en riesgo deben tomar sus propia presi\u00f3n arterial regularmente antes y durante el embarazo.<\/p>\n<p>\u00abEl primer paso es medirla\u00bb, dijo. \u00abNo puedes saber cu\u00e1l es tu presi\u00f3n arterial por c\u00f3mo te sientes, a menos que est\u00e9 muy alta o muy baja. Es \u00fatil llevar un registro de ella con regularidad. La prevenci\u00f3n es mejor que cualquier otra cosa, pero si no puedes prevenirlo, luego detectarlo temprano\u00bb. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> La trayectoria de la PA puede identificar el riesgo de trastornos hipertensivos del embarazo <strong>M\u00e1s informaci\u00f3n:<\/strong> Angela M. Malek et al, Hypertensive Disorders of Pregnancy With and Without Pregnancy Hypertension Are Associated With Incident Maternal Enfermedad renal posterior al parto, hipertensi\u00f3n (2022). DOI: 10.1161\/HYPERTENSIONAHA.121.18451 <strong>Informaci\u00f3n de la revista:<\/strong> Hipertensi\u00f3n <\/p>\n<p> 2022 HealthDay. Reservados todos los derechos. <\/p>\n<p> <strong>Cita<\/strong>: La presi\u00f3n arterial alta puede aumentar el riesgo futuro de enfermedad renal en mujeres embarazadas (28 de febrero de 2022) consultado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-02- presi\u00f3n arterial alta-futuro-ri\u00f1\u00f3n.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las mujeres con condiciones de presi\u00f3n arterial alta durante el embarazo pueden tener el doble de riesgo de enfermedad renal varios a\u00f1os despu\u00e9s de dar a luz, seg\u00fan un nuevo estudio que encuentra el riesgo sube a casi cuatro veces para las mujeres que ya ten\u00edan presi\u00f3n arterial alta antes del embarazo. El estudio, publicado &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/la-presion-arterial-alta-puede-aumentar-el-riesgo-futuro-de-enfermedad-renal-en-mujeres-embarazadas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa presi\u00f3n arterial alta puede aumentar el riesgo futuro de enfermedad renal en mujeres embarazadas\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7640","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7640"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7640\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}