{"id":7668,"date":"2022-08-30T02:29:00","date_gmt":"2022-08-30T07:29:00","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/la-pandemia-de-coronavirus-no-ha-terminado-advierte-el-ministro-de-salud-aleman\/"},"modified":"2022-08-30T02:29:00","modified_gmt":"2022-08-30T07:29:00","slug":"la-pandemia-de-coronavirus-no-ha-terminado-advierte-el-ministro-de-salud-aleman","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/la-pandemia-de-coronavirus-no-ha-terminado-advierte-el-ministro-de-salud-aleman\/","title":{"rendered":"La pandemia de coronavirus no ha terminado, advierte el ministro de salud alem\u00e1n"},"content":{"rendered":"<p>El ministro de Salud alem\u00e1n, Karl Lauterbach, se dirige a los medios de comunicaci\u00f3n durante una conferencia de prensa en Berl\u00edn, Alemania, el viernes 25 de febrero de 2022 sobre la actual pandemia de coronavirus en Alemania. Cr\u00e9dito: AP Photo\/Michael Sohn <\/p>\n<p>El ministro de salud de Alemania advirti\u00f3 el viernes que la pandemia de coronavirus a\u00fan no ha terminado, y se\u00f1al\u00f3 que el pa\u00eds a\u00fan registra infecciones r\u00e9cord y un alto n\u00famero de muertes. <\/p>\n<p>El Instituto Robert Koch, la agencia de control de enfermedades de Alemania, inform\u00f3 210\u00a0743 casos nuevos de COVID-19 confirmados y 226 muertes en las \u00faltimas 24 horas. Las autoridades dicen que los datos de laboratorio sugieren que puede haber una gran cantidad de casos no detectados.<\/p>\n<p>\u00abDebemos tener cuidado de no pensar que la pandemia ha terminado\u00bb, dijo el ministro de Salud, Karl Lauterbach, a los periodistas en Berl\u00edn.<\/p>\n<p>Un subtipo de la variante omicron, denominada BA.2, podr\u00eda conducir a un mayor aumento de los casos, dijo.<\/p>\n<p>Lauterbach inst\u00f3 a los 16 estados de Alemania a no relajar las restricciones m\u00e1s r\u00e1pido de lo acordado recientemente.<\/p>\n<p>Rechaz\u00f3 la idea de declarar el llamado D\u00eda de la Libertad como lo han hecho otros pa\u00edses, diciendo que dar\u00eda a la gente una falsa sensaci\u00f3n de seguridad. A diferencia de muchos pa\u00edses comparables, Alemania tambi\u00e9n tiene una tasa m\u00e1s alta de personas mayores de 60 a\u00f1os no vacunadas que son particularmente vulnerables a enfermedades graves si contraen COVID-19, dijo. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Ministro de Salud: Alemania ha cruzado el pico de omicron <\/p>\n<p> 2022 The Associated Press. Reservados todos los derechos. Este material no puede ser publicado, transmitido, reescrito o redistribuido sin permiso. <\/p>\n<p> <strong>Cita<\/strong>: La pandemia de coronavirus no ha terminado, advierte el ministro de salud alem\u00e1n (2022, 25 de febrero) recuperado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-02-coronavirus-pandemic -german-health-minister.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro de Salud alem\u00e1n, Karl Lauterbach, se dirige a los medios de comunicaci\u00f3n durante una conferencia de prensa en Berl\u00edn, Alemania, el viernes 25 de febrero de 2022 sobre la actual pandemia de coronavirus en Alemania. Cr\u00e9dito: AP Photo\/Michael Sohn El ministro de salud de Alemania advirti\u00f3 el viernes que la pandemia de coronavirus &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/la-pandemia-de-coronavirus-no-ha-terminado-advierte-el-ministro-de-salud-aleman\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa pandemia de coronavirus no ha terminado, advierte el ministro de salud alem\u00e1n\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7668","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7668"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7668\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}