{"id":7672,"date":"2022-08-30T02:29:07","date_gmt":"2022-08-30T07:29:07","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/algoritmo-de-prescripcion-de-antibioticos-reduce-a-la-mitad-el-riesgo-de-resistencia-a-los-antibioticos\/"},"modified":"2022-08-30T02:29:07","modified_gmt":"2022-08-30T07:29:07","slug":"algoritmo-de-prescripcion-de-antibioticos-reduce-a-la-mitad-el-riesgo-de-resistencia-a-los-antibioticos","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/algoritmo-de-prescripcion-de-antibioticos-reduce-a-la-mitad-el-riesgo-de-resistencia-a-los-antibioticos\/","title":{"rendered":"Algoritmo de prescripci\u00f3n de antibi\u00f3ticos reduce a la mitad el riesgo de resistencia a los antibi\u00f3ticos"},"content":{"rendered":"<p>Cr\u00e9dito: Unsplash\/CC0 Public Domain <\/p>\n<p>Los antibi\u00f3ticos son un arma de doble filo: por un lado, los antibi\u00f3ticos son esenciales para curar infecciones bacterianas. Por otro, su uso favorece la aparici\u00f3n y proliferaci\u00f3n de bacterias resistentes a los antibi\u00f3ticos. Utilizando t\u00e9cnicas de secuenciaci\u00f3n gen\u00f3mica y an\u00e1lisis de aprendizaje autom\u00e1tico de registros de pacientes, los investigadores han desarrollado un algoritmo de prescripci\u00f3n de antibi\u00f3ticos que reduce a la mitad el riesgo de aparici\u00f3n de resistencia a los antibi\u00f3ticos. <\/p>\n<p>El art\u00edculo, publicado hoy en Science, es una colaboraci\u00f3n entre el grupo de investigaci\u00f3n del profesor Roy Kishony de la Facultad de Biolog\u00eda del Instituto Tecnol\u00f3gico de TechnionIsrael y la Facultad de Ciencias de la Computaci\u00f3n Henry and Marilyn Taub y los profesores Varda Shalev, Gabriel Chodick y Jacob Kuint en el Centro de Investigaci\u00f3n e Innovaci\u00f3n Maccabi KSM dirigido por el Dr. Tal Patalon. Centr\u00e1ndose en dos infecciones bacterianas muy comunes, infecciones del tracto urinario e infecciones de heridas, el documento describe c\u00f3mo se puede usar el historial de infecciones pasadas de cada paciente para elegir el mejor antibi\u00f3tico para prescribirlo y reducir las posibilidades de que surja una resistencia a los antibi\u00f3ticos.<\/p>\n<p>El tratamiento cl\u00ednico de las infecciones se centra en hacer coincidir correctamente un antibi\u00f3tico con el perfil de resistencia del pat\u00f3geno, pero incluso estos tratamientos pueden fallar, ya que la resistencia puede surgir durante el tratamiento mismo. \u00abQuer\u00edamos comprender c\u00f3mo surge la resistencia a los antibi\u00f3ticos durante el tratamiento y encontrar formas de adaptar mejor el tratamiento con antibi\u00f3ticos para cada paciente para no solo coincidir correctamente con la susceptibilidad actual a la infecci\u00f3n del paciente, sino tambi\u00e9n para minimizar el riesgo de recurrencia de la infecci\u00f3n y ganar resistencia al tratamiento\u00bb. dijo el profesor Kishony. <\/p>\n<p>La clave del \u00e9xito del enfoque fue comprender que la aparici\u00f3n de resistencia a los antibi\u00f3ticos pod\u00eda predecirse en infecciones de pacientes individuales. Las bacterias pueden evolucionar mediante la adquisici\u00f3n aleatoria de mutaciones que las hacen resistentes, pero la aleatoriedad del proceso hace que sea dif\u00edcil de predecir y evitar. Sin embargo, los investigadores descubrieron que en la mayor\u00eda de las infecciones de los pacientes, la resistencia no se adquir\u00eda por mutaciones aleatorias. En cambio, surgi\u00f3 resistencia debido a la reinfecci\u00f3n por bacterias resistentes existentes del propio microbioma del paciente. Los investigadores convirtieron estos hallazgos en una ventaja: propusieron hacer coincidir un antibi\u00f3tico no solo con la susceptibilidad de la bacteria que causa la infecci\u00f3n actual del paciente, sino tambi\u00e9n con la bacteria en su microbioma que podr\u00eda reemplazarla.<\/p>\n<p>\u00abNosotros encontr\u00f3 que la susceptibilidad a los antibi\u00f3ticos de las infecciones pasadas del paciente podr\u00eda usarse para predecir su riesgo de regresar con una infecci\u00f3n resistente despu\u00e9s del tratamiento con antibi\u00f3ticos\u00bb, explic\u00f3 el Dr. Mathew Stracy, primer autor del art\u00edculo. \u00abEl uso de estos datos, junto con los datos demogr\u00e1ficos del paciente, como la edad y el sexo, nos permiti\u00f3 desarrollar el algoritmo\u00bb. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> La IA mejora la precisi\u00f3n de la selecci\u00f3n de antibi\u00f3ticos para el tratamiento de las infecciones urinarias <strong>M\u00e1s informaci\u00f3n:<\/strong> Mathew Stracy et al, Minimizaci\u00f3n de la aparici\u00f3n de resistencia a los antibi\u00f3ticos inducida por el tratamiento en infecciones bacterianas, Science (2022). DOI: 10.1126\/science.abg9868 <strong>Informaci\u00f3n de la revista:<\/strong> Science <\/p>\n<p> Proporcionado por American Technion Society <strong>Cita<\/strong>: El algoritmo de prescripci\u00f3n de antibi\u00f3ticos reduce a la mitad el riesgo de resistencia a los antibi\u00f3ticos (2022 , 25 de febrero) recuperado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-02-antibiotic-prescribing-algorithm-antibiotic-resistance.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Unsplash\/CC0 Public Domain Los antibi\u00f3ticos son un arma de doble filo: por un lado, los antibi\u00f3ticos son esenciales para curar infecciones bacterianas. Por otro, su uso favorece la aparici\u00f3n y proliferaci\u00f3n de bacterias resistentes a los antibi\u00f3ticos. Utilizando t\u00e9cnicas de secuenciaci\u00f3n gen\u00f3mica y an\u00e1lisis de aprendizaje autom\u00e1tico de registros de pacientes, los investigadores han &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/algoritmo-de-prescripcion-de-antibioticos-reduce-a-la-mitad-el-riesgo-de-resistencia-a-los-antibioticos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abAlgoritmo de prescripci\u00f3n de antibi\u00f3ticos reduce a la mitad el riesgo de resistencia a los antibi\u00f3ticos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7672","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7672"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7672\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}