{"id":7679,"date":"2022-08-30T02:29:19","date_gmt":"2022-08-30T07:29:19","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/como-las-neuronas-encuentran-su-lugar\/"},"modified":"2022-08-30T02:29:19","modified_gmt":"2022-08-30T07:29:19","slug":"como-las-neuronas-encuentran-su-lugar","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/como-las-neuronas-encuentran-su-lugar\/","title":{"rendered":"C\u00f3mo las neuronas encuentran su lugar"},"content":{"rendered":"<p>La neurita \u00fanica AIB se coloca a lo largo de dos vecindades distintas en el anillo nervioso. (A) Esquema de un C. elegans adulto\/larva que muestra una neurona AIB (cian) y sus vecindarios posterior (naranja) y anterior (magenta) en la cabeza. La neurita AIB tiene un segmento de neurita proximal (flecha naranja), un desplazamiento posterior-anterior en la l\u00ednea media dorsal (l\u00ednea discontinua) y un segmento de neurita distal (flecha magenta; en el otro lado del gusano, detr\u00e1s de la faringe, que est\u00e1 en gris). El contorno de color ne\u00f3n representa el neuropilo del anillo nervioso. Los t\u00e9rminos segmentos de neuritas proximales o distales se refieren a la relaci\u00f3n del segmento de neuritas con el cuerpo celular AIB. Los vecindarios en los que se colocan los segmentos de neurita proximal y distal se denominan vecindarios posterior o anterior, respectivamente, debido a su posici\u00f3n a lo largo del eje anteroposterior del gusano. Tenga en cuenta que este esquema solo muestra una neurona del par AIB. El cuerpo celular est\u00e1 marcado con un asterisco. (B) Esquema ampliado de AIB y sus vecindarios en (A, C) Imagen confocal representativa que muestra la vista lateral de una neurona AIB marcada con mCherry citoplasm\u00e1tico (cian). (D) Imagen confocal representativa que muestra una neurona AIB marcada con mCherry citoplasm\u00e1tico (cian); y neurona motora RIM del vecindario anterior marcada con GFP citoplasm\u00e1tico (magenta) en vista lateral. Obs\u00e9rvese la colocalizaci\u00f3n de la neurita distal AIB (pero no la neurita proximal) con el marcador de vecindad anterior RIM (comparar con E). (E) Como (D), pero con neuronas sensoriales AIB (cian) y AWC y ASE del vecindario posterior (naranja). Tenga en cuenta la colocalizaci\u00f3n de la neurita proximal AIB (pero no la neurita distal) con los marcadores de vecindad posteriores AWC y ASE (comp\u00e1rese con D). (FJ) Igual que AE pero en vista axial indicada por la flecha en (F). La cabeza del gusano est\u00e1 inclinada en esta vista para hacer visibles los dos segmentos de neurita en las dos vecindades. Tenga en cuenta el cambio en H (flechas), correspondiente a los vecindarios cambiantes de neuritas AIB (compare I y J). (K, L) Reconstrucci\u00f3n volum\u00e9trica del conjunto de datos de conectoma de microscop\u00eda electr\u00f3nica JSH (White et al., 1986) de AIBL (K) y AIBL superpuestos en estratos de anillos nerviosos (L), en vista lateral, con estratos S2 y S3 (llamados como en Moyle et al., 2021), que contiene vecindarios anterior y posterior, respectivamente. (M) Reconstrucci\u00f3n volum\u00e9trica de AIBL y AIBR en vista axial (del conjunto de datos JSH White et al., 1986). Tenga en cuenta el cambio en los vecindarios por AIBL y AIBR, en la l\u00ednea media dorsal (l\u00ednea discontinua), forma un quiasma (ver tambi\u00e9n Figura 1, figura suplemento 1). (N) Esquema de M que resalta los vecindarios AIB para el contexto y la l\u00ednea media dorsal con una l\u00ednea discontinua (los vecindarios AIB, la polaridad sin\u00e1ptica y las propiedades de red resultantes tambi\u00e9n se muestran en la Figura 1, figura, suplemento 2). Barra de escala = 10 m para AJ y 3 m para KN. Cr\u00e9dito: DOI: 10.7554\/eLife.71171 <\/p>\n<p>Las neuronas en el sistema nervioso central y el cerebro en desarrollo se congregan en capas o vecindarios, encajando en una alineaci\u00f3n que dictar\u00e1 su funci\u00f3n. Pero, \u00bfc\u00f3mo encuentran su lugar adecuado? <\/p>\n<p>En un nuevo estudio, los investigadores de Yale utilizaron una t\u00e9cnica de microscop\u00eda avanzada que les permiti\u00f3 seguir una sola neurona en el embri\u00f3n de un gusano mientras encontraba su hogar neurol\u00f3gico.<\/p>\n<p>El equipo de investigaci\u00f3n, dirigido por Titas Sengupta, trabajando en el laboratorio de Daniel Coln-Ramos, profesor de Neurociencia y Biolog\u00eda Celular Dorys McConnell Duberg, descubri\u00f3 que las mol\u00e9culas de adhesi\u00f3n se adhieren a las neuronas que luego son esencialmente atra\u00eddas hacia una capa o vecindario espec\u00edfico y se \u00abcierran\u00bb en su lugar. Los hallazgos se publicaron en la revista eLife.<\/p>\n<p>En un video, Coln-Ramos describe lo que revel\u00f3 la tecnolog\u00eda.<\/p>\n<p>\u00abLo que podemos hacer con este microscopio es rastrear esos eventos tal como realmente est\u00e1n ocurriendo y atribuir funciones gen\u00e9ticas espec\u00edficas a estas mol\u00e9culas que estamos identificando en esa secuencia de eventos\u00bb, dijo.<\/p>\n<p>Estos conocimientos, dijo, ayudar\u00e1n a los cient\u00edficos a determinar las ra\u00edces moleculares de muchas enfermedades tempranas del desarrollo.<\/p>\n<p> Cr\u00e9dito: Universidad de Yale <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> C\u00f3mo sabe el cerebro cu\u00e1ndo sacar la basura <strong>M\u00e1s informaci\u00f3n:<\/strong> Titas Sengupta et al, Adhesi\u00f3n diferencial regula la colocaci\u00f3n de neuritas a trav\u00e9s de un mecanismo de cierre retr\u00f3grado, eLife (2021). DOI: 10.7554\/eLife.71171 <strong>Informaci\u00f3n del diario:<\/strong> eLife <\/p>\n<p> Proporcionado por la Universidad de Yale <strong>Cita<\/strong>: C\u00f3mo las neuronas encuentran su lugar (25 de febrero de 2022) consultado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-02-neurons.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La neurita \u00fanica AIB se coloca a lo largo de dos vecindades distintas en el anillo nervioso. (A) Esquema de un C. elegans adulto\/larva que muestra una neurona AIB (cian) y sus vecindarios posterior (naranja) y anterior (magenta) en la cabeza. La neurita AIB tiene un segmento de neurita proximal (flecha naranja), un desplazamiento posterior-anterior &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/como-las-neuronas-encuentran-su-lugar\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abC\u00f3mo las neuronas encuentran su lugar\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7679","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7679"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7679\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}