{"id":7686,"date":"2022-08-30T02:29:30","date_gmt":"2022-08-30T07:29:30","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/nuevo-metodo-alivia-la-fatiga-de-la-entrevista-posterior-al-desastre-al-recopilar-las-experiencias-de-los-sobrevivientes\/"},"modified":"2022-08-30T02:29:30","modified_gmt":"2022-08-30T07:29:30","slug":"nuevo-metodo-alivia-la-fatiga-de-la-entrevista-posterior-al-desastre-al-recopilar-las-experiencias-de-los-sobrevivientes","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/nuevo-metodo-alivia-la-fatiga-de-la-entrevista-posterior-al-desastre-al-recopilar-las-experiencias-de-los-sobrevivientes\/","title":{"rendered":"Nuevo m\u00e9todo alivia la fatiga de la entrevista posterior al desastre al recopilar las experiencias de los sobrevivientes"},"content":{"rendered":"<p>Cr\u00e9dito: Unsplash\/CC0 Dominio p\u00fablico <\/p>\n<p>Un nuevo enfoque para entrevistar a personas despu\u00e9s de un desastre tiene como objetivo evitar los s\u00edntomas de fatiga de la entrevista, seg\u00fan una nueva investigaci\u00f3n en el Revista de investigaci\u00f3n de dise\u00f1o. Carlota Cubelos y Motoharu Onuki de la Universidad de Tokio y Miguel Esteban de la Universidad de Waseda, en Tokio, Jap\u00f3n, explican c\u00f3mo la gamificaci\u00f3n del proceso de entrevista puede ser \u00fatil para recopilar experiencias de sobrevivientes. <\/p>\n<p>La fatiga de la entrevista surge com\u00fanmente cuando los investigadores se acercan repetidamente a los sobrevivientes de un desastre o crisis para conocer sus pensamientos, ideas y experiencias. Los sentimientos de cansancio o el aburrimiento de las experiencias a trav\u00e9s de la narraci\u00f3n repetida pueden llevar a te\u00f1ir los mismos recuerdos y percepciones que los entrevistadores esperan obtener de sus entrevistados. Los investigadores se\u00f1alan que antes de comenzar cualquier nuevo estudio, se debe considerar el estado emocional de los posibles entrevistados y adaptar las t\u00e9cnicas en consecuencia para que los participantes del estudio se sientan c\u00f3modos y capaces de reflexionar constructivamente. La gamificaci\u00f3n del proceso de la entrevista bien podr\u00eda ser una estrategia \u00fatil en este contexto y una forma positiva de evitar la fatiga de la entrevista.<\/p>\n<p>El equipo us\u00f3 el enfoque para establecer qu\u00e9 necesitaban las personas mayores despu\u00e9s del terremoto de Tohoku de 2011 y tsunami en Jap\u00f3n. Su trabajo demostr\u00f3 que el juego creaba un entorno en el que las personas se sent\u00edan c\u00f3modas compartiendo sus experiencias y pensamientos, adem\u00e1s de poder discutir sus necesidades y fortalezas. Los hallazgos podr\u00edan ser \u00fatiles en el desarrollo de soluciones para mejorar la resiliencia frente a futuros desastres, sugiere el equipo.<\/p>\n<p>El equipo escribe que en investigaciones futuras, el marco de gamificaci\u00f3n se desarrollar\u00e1 m\u00e1s y continuar\u00e1n desarroll\u00e1ndose. soluciones para las personas vulnerables a los peligros naturales. \u00abEstablecer y fortalecer una sociedad inclusiva para garantizar que las personas m\u00e1s vulnerables est\u00e9n seguras incluso en situaciones extremas deber\u00eda convertirse en una prioridad para los investigadores, profesionales y usuarios finales del dise\u00f1o\u00bb, concluyen. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Los sobrevivientes de desastres se sienten m\u00e1s preparados para el pr\u00f3ximo, pero a menudo se quedan fuera de la planificaci\u00f3n. <strong>M\u00e1s informaci\u00f3n:<\/strong> Carlota Cubelos et al, Dise\u00f1o para la sostenibilidad en la recuperaci\u00f3n post-desastre inclusiva: T\u00e9cnicas de gamificaci\u00f3n para recolectar experiencias de sobrevivientes, J. of Design Research (2022). DOI: 10.1504\/JDR.2021.121066 Proporcionado por Inderscience <strong>Cita<\/strong>: El nuevo m\u00e9todo alivia la fatiga de la entrevista posterior al desastre al recopilar las experiencias de los sobrevivientes (2022, 25 de febrero) recuperado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/ news\/2022-02-method-alliviates-post-disaster-fatigue-survivor.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Unsplash\/CC0 Dominio p\u00fablico Un nuevo enfoque para entrevistar a personas despu\u00e9s de un desastre tiene como objetivo evitar los s\u00edntomas de fatiga de la entrevista, seg\u00fan una nueva investigaci\u00f3n en el Revista de investigaci\u00f3n de dise\u00f1o. Carlota Cubelos y Motoharu Onuki de la Universidad de Tokio y Miguel Esteban de la Universidad de Waseda, &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/nuevo-metodo-alivia-la-fatiga-de-la-entrevista-posterior-al-desastre-al-recopilar-las-experiencias-de-los-sobrevivientes\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abNuevo m\u00e9todo alivia la fatiga de la entrevista posterior al desastre al recopilar las experiencias de los sobrevivientes\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7686","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7686"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7686\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}