{"id":7689,"date":"2022-08-30T02:29:35","date_gmt":"2022-08-30T07:29:35","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/si-estoy-vacunado-y-tengo-covid-19-cuales-son-mis-posibilidades-de-morir-la-respuesta-es-sorprendentemente-dificil-de-encontrar\/"},"modified":"2022-08-30T02:29:35","modified_gmt":"2022-08-30T07:29:35","slug":"si-estoy-vacunado-y-tengo-covid-19-cuales-son-mis-posibilidades-de-morir-la-respuesta-es-sorprendentemente-dificil-de-encontrar","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/si-estoy-vacunado-y-tengo-covid-19-cuales-son-mis-posibilidades-de-morir-la-respuesta-es-sorprendentemente-dificil-de-encontrar\/","title":{"rendered":"Si estoy vacunado y tengo COVID-19, \u00bfcu\u00e1les son mis posibilidades de morir? La respuesta es sorprendentemente dif\u00edcil de encontrar"},"content":{"rendered":"<p>Cr\u00e9dito: Pixabay\/CC0 Dominio p\u00fablico <\/p>\n<p>Afortunadamente, la mayor\u00eda de las personas que contraen COVID19 no se enferman gravemente, especialmente aquellas que est\u00e1n vacunadas. Pero una peque\u00f1a fracci\u00f3n es hospitalizada y una fracci\u00f3n m\u00e1s peque\u00f1a muere. Si est\u00e1 vacunado y contrae el coronavirus, \u00bfcu\u00e1les son sus posibilidades de ser hospitalizado o morir? <\/p>\n<p>Como epidemi\u00f3logo, se me ha pedido que responda a esta pregunta de una forma u otra durante la pandemia. Esta es una pregunta muy razonable para hacer, pero dif\u00edcil de responder. <\/p>\n<p>Para calcular el riesgo de hospitalizaci\u00f3n o muerte tras infectarse con el SARS-CoV-2 es necesario conocer el n\u00famero total de contagios. El problema es que nadie sabe exactamente cu\u00e1ntas personas han sido contagiadas por el coronavirus. Entonces, si bien es muy dif\u00edcil estimar el riesgo real de morir si est\u00e1 vacunado y contrae COVID-19, hay algunas formas de comprender mejor los riesgos.<\/p>\n<p>Contar infecciones<\/p>\n<p>Lo primero que se debe tener en cuenta al pensar en el riesgo es que los datos deben estar actualizados. Cada nueva variante tiene sus propias caracter\u00edsticas que cambian el riesgo que representa para aquellos a quienes infecta. Omicron apareci\u00f3 r\u00e1pidamente y parece que se est\u00e1 yendo r\u00e1pidamente, por lo que ha habido poco tiempo para que los investigadores o los funcionarios de salud recopilen y publiquen datos que puedan usarse para estimar el riesgo de hospitalizaci\u00f3n o muerte. <\/p>\n<p>Si tiene suficientes datos buenos, ser\u00eda posible calcular el riesgo de hospitalizaci\u00f3n o muerte. Deber\u00eda contar la cantidad de personas que fueron hospitalizadas o fallecieron y dividir esa cantidad por la cantidad total de infecciones. Tambi\u00e9n es importante tener en cuenta los retrasos de tiempo entre la infecci\u00f3n, la hospitalizaci\u00f3n y la muerte. Hacer este c\u00e1lculo le dar\u00eda la verdadera tasa de hospitalizaci\u00f3n o mortalidad por infecci\u00f3n. El problema es que los funcionarios de salud no saben con certeza cu\u00e1ntas personas se han infectado.<\/p>\n<p>La variante omicron es incre\u00edblemente infecciosa, pero el riesgo de que cause una enfermedad significativa es mucho menor en comparaci\u00f3n con las cepas anteriores. Es fant\u00e1stico que omicron sea menos grave, pero eso puede llevar a que menos personas busquen pruebas si est\u00e1n infectadas.<\/p>\n<p>Lo que complica a\u00fan m\u00e1s las cosas es la disponibilidad generalizada de kits de prueba en el hogar. Datos recientes de la ciudad de Nueva York sugieren que el 55% de la poblaci\u00f3n los hab\u00eda pedido y que aproximadamente una cuarta parte de las personas que dieron positivo durante el aumento de omicron usaron una prueba casera. Muchas personas que usan pruebas caseras informan sus resultados, pero muchas no lo hacen. <\/p>\n<p>Por \u00faltimo, es posible que algunas personas que s\u00ed presentan s\u00edntomas simplemente no se hagan la prueba porque no pueden acceder f\u00e1cilmente a los recursos de prueba o no ven ning\u00fan beneficio en hacerlo. <\/p>\n<p>Cuando se combinan todos estos factores, el resultado es que el recuento oficial informado de casos de coronavirus en los EE. UU. es mucho m\u00e1s bajo que el n\u00famero real.<\/p>\n<p>Casos estimados<\/p>\n<p>Desde el comienzo de la pandemia, los epidemi\u00f3logos han estado trabajando en formas de estimar el n\u00famero real de infecciones. Hay algunas maneras de hacer esto.<\/p>\n<p>Los investigadores han usado previamente resultados de pruebas de anticuerpos de grandes poblaciones para estimar la prevalencia del virus. Lleva tiempo organizar este tipo de prueba y, a fines de febrero de 2022, no parece que nadie haya hecho esto para omicron.<\/p>\n<p>Otra forma de estimar los casos es confiar en modelos matem\u00e1ticos. Los investigadores han utilizado estos modelos para hacer estimaciones del n\u00famero total de casos y tambi\u00e9n de las tasas de mortalidad por infecci\u00f3n. Pero los modelos no distinguen entre infecciones estimadas de individuos vacunados y no vacunados. <\/p>\n<p>La investigaci\u00f3n ha demostrado una y otra vez que la vacunaci\u00f3n reduce en gran medida el riesgo de enfermedad grave o muerte. Esto significa que calcular el riesgo de muerte solo es realmente \u00fatil si se puede distinguir por el estado de vacunaci\u00f3n, y los modelos existentes no lo permiten.<\/p>\n<p>\u00bfQu\u00e9 se sabe y qu\u00e9 hacer?<\/p>\n<p> Sin una buena estimaci\u00f3n del total de casos por estado de vacunaci\u00f3n, los mejores datos disponibles son los casos conocidos, las hospitalizaciones y las muertes. Si bien esta informaci\u00f3n limitada no permite a los investigadores calcular el riesgo absoluto que enfrenta un individuo, es posible comparar el riesgo entre personas vacunadas y no vacunadas.<\/p>\n<p>Los datos m\u00e1s recientes de los Centros para el Control y la Prevenci\u00f3n de Enfermedades muestra que las tasas de hospitalizaci\u00f3n son 16 veces m\u00e1s altas en adultos no vacunados en comparaci\u00f3n con los que est\u00e1n completamente vacunados, y las tasas de muerte son 14 veces m\u00e1s altas.<\/p>\n<p>\u00bfQu\u00e9 se puede sacar de todo esto? Lo que es m\u00e1s importante, la vacunaci\u00f3n reduce en gran medida el riesgo de hospitalizaci\u00f3n y muerte muchas veces.<\/p>\n<p>Pero quiz\u00e1s una segunda lecci\u00f3n es que los riesgos de hospitalizaci\u00f3n o muerte son mucho m\u00e1s complicados de entender y estudiar de lo que podr\u00eda haber pensado y el Lo mismo se aplica para decidir c\u00f3mo reaccionar ante esos riesgos.<\/p>\n<p>Observo los n\u00fameros y conf\u00edo en la capacidad de mi vacuna y refuerzo contra el COVID-19 para protegerme de una enfermedad grave. Tambi\u00e9n elijo usar una m\u00e1scara de alta calidad cuando estoy adentro con muchas personas para disminuir a\u00fan m\u00e1s mi propio riesgo y proteger a aquellos que no puedan vacunarse. <\/p>\n<p>Ha habido muchas lecciones aprendidas de esta pandemia, y hay muchas cosas que los investigadores y el p\u00fablico a\u00fan deben mejorar. Resulta que estudiar y hablar de riesgo es uno de ellos. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Los casos disminuyen, pero los expertos dicen que la pandemia de COVID-19 no ha terminado Proporcionado por The Conversation <\/p>\n<p> Este art\u00edculo se vuelve a publicar de The Conversation bajo una licencia Creative Commons. Lea el art\u00edculo original. <\/p>\n<p> <strong>Cita<\/strong>: Si estoy vacunado y tengo COVID-19, \u00bfcu\u00e1les son mis posibilidades de morir? La respuesta es sorprendentemente dif\u00edcil de encontrar (2022, 25 de febrero) recuperado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-02-vaccinated-covid-chances-dying-surprisingly.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Pixabay\/CC0 Dominio p\u00fablico Afortunadamente, la mayor\u00eda de las personas que contraen COVID19 no se enferman gravemente, especialmente aquellas que est\u00e1n vacunadas. Pero una peque\u00f1a fracci\u00f3n es hospitalizada y una fracci\u00f3n m\u00e1s peque\u00f1a muere. Si est\u00e1 vacunado y contrae el coronavirus, \u00bfcu\u00e1les son sus posibilidades de ser hospitalizado o morir? Como epidemi\u00f3logo, se me ha &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/si-estoy-vacunado-y-tengo-covid-19-cuales-son-mis-posibilidades-de-morir-la-respuesta-es-sorprendentemente-dificil-de-encontrar\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abSi estoy vacunado y tengo COVID-19, \u00bfcu\u00e1les son mis posibilidades de morir? La respuesta es sorprendentemente dif\u00edcil de encontrar\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7689","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7689"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7689\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}