{"id":7696,"date":"2022-08-30T02:29:47","date_gmt":"2022-08-30T07:29:47","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/investigacion-del-efecto-de-la-suplementacion-con-hierro-sobre-la-atrofia-del-musculo-esqueletico-en-pacientes-con-cancer\/"},"modified":"2022-08-30T02:29:47","modified_gmt":"2022-08-30T07:29:47","slug":"investigacion-del-efecto-de-la-suplementacion-con-hierro-sobre-la-atrofia-del-musculo-esqueletico-en-pacientes-con-cancer","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/investigacion-del-efecto-de-la-suplementacion-con-hierro-sobre-la-atrofia-del-musculo-esqueletico-en-pacientes-con-cancer\/","title":{"rendered":"Investigaci\u00f3n del efecto de la suplementaci\u00f3n con hierro sobre la atrofia del m\u00fasculo esquel\u00e9tico en pacientes con c\u00e1ncer"},"content":{"rendered":"<p>Resumen gr\u00e1fico. Cr\u00e9dito: DOI: 10.15252\/embr.202153746 <\/p>\n<p>Un equipo de cient\u00edficos italianos y belgas ha investigado el efecto de los suplementos de hierro sobre la atrofia del m\u00fasculo esquel\u00e9tico en pacientes con c\u00e1ncer y otras enfermedades debilitantes que estudiaron las causas de estas afecciones en humanos y modelos de ratones Los hallazgos, publicados hoy en EMBO Reports, arrojan luz sobre los mecanismos de desgaste en pacientes con c\u00e1ncer en etapa avanzada, para quienes la prevalencia de la devastadora atrofia del m\u00fasculo esquel\u00e9tico conocida generalmente como caquexia alcanza el 80%. <\/p>\n<p>Adem\u00e1s, dado que se estima que al menos el 20 % de todas las muertes relacionadas con el c\u00e1ncer son causadas directamente por la caquexia, revertir la p\u00e9rdida de masa y funci\u00f3n muscular podr\u00eda al menos prolongar la calidad de vida de dichos pacientes. Los pacientes de c\u00e1ncer con caquexia suelen sufrir una disminuci\u00f3n incontrolable de la calidad de vida, resistencia a la insulina, disfunci\u00f3n hep\u00e1tica, inflamaci\u00f3n cr\u00f3nica, microbiota intestinal alterada y absorci\u00f3n de nutrientes.<\/p>\n<p>Los investigadores primero se propusieron investigar si la deficiencia de hierro, ya conocida ser altamente prevalente entre los pacientes con c\u00e1ncer y asociado con un mal pron\u00f3stico, est\u00e1 relacionado causalmente con la caquexia. Para ello, se indujo en ratones una anemia grave por deficiencia de hierro t\u00edpica de los pacientes con c\u00e1ncer mediante una combinaci\u00f3n de dieta libre de hierro y flebotom\u00eda, que reduce el volumen de sangre circulante. Esto result\u00f3 en atrofia muscular entre esos ratones, lo que respalda la hip\u00f3tesis de que la alteraci\u00f3n del metabolismo del hierro est\u00e1 asociada con la aparici\u00f3n de desgaste muscular asociado con el c\u00e1ncer.<\/p>\n<p>Luego se descubri\u00f3 que la funci\u00f3n muscular, la masa e incluso una supervivencia m\u00e1s prolongada en los modelos de ratones con c\u00e1ncer de colon podr\u00edan sustentarse con suplementos de hierro, previniendo o revirtiendo la caquexia. Un hallazgo fue que las inyecciones intravenosas de hierro dieron como resultado ratones m\u00e1s sanos y f\u00edsicamente m\u00e1s activos que sobrevivieron mucho m\u00e1s all\u00e1 de las dos semanas habituales, as\u00ed como una fuerza de agarre notablemente mejorada en 24 horas, todo sostenido hasta el final del experimento.<\/p>\n<p>Se observ\u00f3 una mejora moderada en la fuerza en un peque\u00f1o grupo de pacientes humanos con c\u00e1ncer unos d\u00edas despu\u00e9s de la inyecci\u00f3n de carboximaltosa f\u00e9rrica, una preparaci\u00f3n de hierro com\u00fanmente utilizada como suplemento. Sin embargo, tambi\u00e9n es necesario realizar m\u00e1s estudios en humanos para validar los resultados, ya que no hubo un grupo de placebo que actuara como control en el estudio que se analiza aqu\u00ed.<\/p>\n<p>Se necesitan m\u00e1s estudios para identificar completamente los mecanismos subyacentes involucrados. , pero los experimentos con ratones indican que el hierro no es deficiente en general, sino que se limita al citosol, el fluido primario de las c\u00e9lulas, y carece de mitocondrias para la producci\u00f3n de trifosfato de adenosina (ATP), la fuente de energ\u00eda de las c\u00e9lulas y procesos como la contracci\u00f3n muscular. Parece que la suplementaci\u00f3n con hierro remedia este d\u00e9ficit al hacer que el hierro est\u00e9 disponible para las mitocondrias en las c\u00e9lulas musculares.<\/p>\n<p>Adem\u00e1s del c\u00e1ncer, la atrofia del m\u00fasculo esquel\u00e9tico es un sello distintivo de varias enfermedades cr\u00f3nicas como la insuficiencia card\u00edaca y la EPOC (Enfermedad Pulmonar Obstructiva Cr\u00f3nica). ). Por lo tanto, existe la esperanza de que la suplementaci\u00f3n con hierro pueda al menos aliviar los s\u00edntomas de estas afecciones cuando se trata de atrofia muscular.<\/p>\n<p>Sin embargo, al mismo tiempo, los efectos beneficiosos de la suplementaci\u00f3n con hierro a\u00fan deben validarse en otros modelos de c\u00e1ncer. No se puede suponer que los resultados sean transferibles a otros tipos de c\u00e1ncer porque algunos tipos dependen m\u00e1s del hierro que otros y, por lo tanto, los suplementos de hierro pueden tener diferentes niveles de \u00e9xito. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> El ejercicio f\u00edsico modula el hierro en la enfermedad de Alzheimer <strong>M\u00e1s informaci\u00f3n:<\/strong> Elisabeth Wyart et al, La suplementaci\u00f3n con hierro es suficiente para rescatar la masa muscular esquel\u00e9tica y la funci\u00f3n en la caquexia por c\u00e1ncer, EMBO Reports (2022) ). DOI: 10.15252\/embr.202153746 <strong>Informaci\u00f3n de la revista:<\/strong> EMBO Reports <\/p>\n<p> Proporcionado por la Organizaci\u00f3n Europea de Biolog\u00eda Molecular <strong>Cita<\/strong>: Investigaci\u00f3n del efecto de la suplementaci\u00f3n con hierro sobre la atrofia del m\u00fasculo esquel\u00e9tico en el c\u00e1ncer pacientes (2022, 25 de febrero) recuperado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-02-effect-iron-supplementation-skeletal-muscle.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumen gr\u00e1fico. Cr\u00e9dito: DOI: 10.15252\/embr.202153746 Un equipo de cient\u00edficos italianos y belgas ha investigado el efecto de los suplementos de hierro sobre la atrofia del m\u00fasculo esquel\u00e9tico en pacientes con c\u00e1ncer y otras enfermedades debilitantes que estudiaron las causas de estas afecciones en humanos y modelos de ratones Los hallazgos, publicados hoy en EMBO Reports, &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/investigacion-del-efecto-de-la-suplementacion-con-hierro-sobre-la-atrofia-del-musculo-esqueletico-en-pacientes-con-cancer\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abInvestigaci\u00f3n del efecto de la suplementaci\u00f3n con hierro sobre la atrofia del m\u00fasculo esquel\u00e9tico en pacientes con c\u00e1ncer\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7696","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7696"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7696\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}