{"id":7702,"date":"2022-08-30T02:29:58","date_gmt":"2022-08-30T07:29:58","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/epidemiologia-de-sifilis-gonorrea-y-clamidia-en-el-centro-y-este-de-la-region-europea-de-la-oms\/"},"modified":"2022-08-30T02:29:58","modified_gmt":"2022-08-30T07:29:58","slug":"epidemiologia-de-sifilis-gonorrea-y-clamidia-en-el-centro-y-este-de-la-region-europea-de-la-oms","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/epidemiologia-de-sifilis-gonorrea-y-clamidia-en-el-centro-y-este-de-la-region-europea-de-la-oms\/","title":{"rendered":"Epidemiolog\u00eda de s\u00edfilis, gonorrea y clamidia en el Centro y Este de la Regi\u00f3n Europea de la OMS"},"content":{"rendered":"<p>Epidemiolog\u00eda de s\u00edfilis, gonorrea y clamidia en el Centro y Este de la Regi\u00f3n Europea de la OMS (2015-2019): mientras que la mayor\u00eda de los pa\u00edses informaron m\u00e1s casos de s\u00edfilis y gonorrea en hombres que en mujeres, los casos de clamidia en mujeres superaron en n\u00famero a los de hombres en la mayor\u00eda de los pa\u00edses. Cr\u00e9dito: Eurosurveillance\/OMS <\/p>\n<p>En su art\u00edculo publicado en Eurosurveillance, Bozicevic et al. analiz\u00f3 datos sobre casos notificados de s\u00edfilis, gonorrea y clamidia durante el per\u00edodo 2015 a 2019 de 18 pa\u00edses no pertenecientes a la UE\/EEE de la Regi\u00f3n Europea de la Organizaci\u00f3n Mundial de la Salud. Durante este tiempo, el n\u00famero de casos notificados por 100.000 habitantes fue de 0,426,5 para s\u00edfilis, 018,5 para gonorrea y 043,3 para clamidia. <\/p>\n<p>A diferencia de los pa\u00edses de la Uni\u00f3n Europea y el Espacio Econ\u00f3mico Europeo (UE\/EEE), en la mayor\u00eda de los pa\u00edses de la Regi\u00f3n que no pertenecen a la UE\/EEE con tres o m\u00e1s puntos de datos en el per\u00edodo de 2015 a 2019 parece haber habr\u00e1 tendencias decrecientes en los casos notificados de s\u00edfilis, gonorrea y clamidia.<\/p>\n<p>Entre los pa\u00edses informantes, Georgia observ\u00f3 la tasa de casos de s\u00edfilis m\u00e1s alta en el \u00faltimo a\u00f1o incluido (2018 o 2019 seg\u00fan la disponibilidad de datos) con 26,5 casos por a\u00f1o. 100.000 habitantes, seguida de Kazajst\u00e1n (18,8\/100.000) y la Federaci\u00f3n de Rusia (16,6\/100.000). En comparaci\u00f3n, los pa\u00edses de la UE\/EEE tuvieron una tasa bruta de notificaci\u00f3n de s\u00edfilis de 7,0 por 100 000 habitantes en 2018. Las tasas m\u00e1s altas se registraron en Malta (17,9\/100 000), Luxemburgo (17,1\/100 000) y el Reino Unido (12,6\/100 000) .<\/p>\n<p>Mayor proporci\u00f3n de hombres con s\u00edfilis y gonorrea<\/p>\n<p>Georgia tambi\u00e9n tuvo la tasa m\u00e1s alta de casos de clamidia y gonorrea informados en el \u00faltimo a\u00f1o incluido (2018 o 2019) con 52,0 por 100\u00a0000 de clamidia casos y 18,5 por 100.000 respectivamente. Bielorrusia tuvo una tasa de notificaci\u00f3n de clamidia de 43,3 por 100 000 y Ucrania de 31,6 por 100 000. Las tasas de gonorrea estaban por encima de 10 por 100 000 habitantes en Kazajst\u00e1n y Uzbekist\u00e1n con un patr\u00f3n de disminuci\u00f3n en las tasas notificadas m\u00e1s recientemente en los pa\u00edses que ten\u00edan datos disponibles durante al menos 3 a\u00f1os, con la excepci\u00f3n de Azerbaiy\u00e1n.<\/p>\n<p>Mientras la mayor\u00eda de los pa\u00edses reportaron m\u00e1s casos de s\u00edfilis y gonorrea en hombres que en mujeres, los casos de clamidia en mujeres superaron a los de hombres en la mayor\u00eda de los pa\u00edses. <\/p>\n<p>En el per\u00edodo de 2015 a 2018, solo cuatro pa\u00edses no pertenecientes a la UE\/EEE informaron datos de pruebas de resistencia y susceptibilidad a los antimicrobianos de al menos un f\u00e1rmaco al Programa de Vigilancia Antimicrobiana Gonoc\u00f3cica, a saber, Bielorrusia, Kirguist\u00e1n, la Federaci\u00f3n Rusa y Ucrania.<\/p>\n<p>Los autores notan una disponibilidad bastante limitada de datos sobre infecciones de transmisi\u00f3n sexual (ITS) en el Centro y el Este de la Regi\u00f3n Europea de la OMS, incluidos los datos sobre RAM en gonococos. Esto influye en la comparabilidad con los datos de STI disponibles de la UE\/EEE. Abogan por una mejor disponibilidad y calidad de los datos de vigilancia de las ITS \u00abpara estimar mejor la carga de las ITS, medir el progreso hacia los objetivos de control de las ITS establecidos por la OMS y guiar la implementaci\u00f3n de los programas nacionales de control de las ITS\u00bb. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> CDC: Tasas de ITS de 2016 a 2018 entre mujeres que dan a luz <strong>M\u00e1s informaci\u00f3n:<\/strong> Jelena Barbaric et al, Surveillance and epidemiology of syphilis, gonorrhea and chlamydia in the non -Pa\u00edses de la Uni\u00f3n Europea de la Regi\u00f3n Europea de la Organizaci\u00f3n Mundial de la Salud, 2015 a 2020, Eurosurveillance (2022). DOI: 10.2807\/1560-7917.ES.2022.27.8.2100197 Proporcionado por el Centro Europeo para la Prevenci\u00f3n y el Control de Enfermedades (ECDC) <strong>Cita<\/strong>: Epidemiolog\u00eda de s\u00edfilis, gonorrea y clamidia en el Centro y Este de la OMS Regi\u00f3n europea (2022, 25 de febrero) recuperado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-02-epidemiology-syphilis-gonorrhea-chlamydia-centre.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Epidemiolog\u00eda de s\u00edfilis, gonorrea y clamidia en el Centro y Este de la Regi\u00f3n Europea de la OMS (2015-2019): mientras que la mayor\u00eda de los pa\u00edses informaron m\u00e1s casos de s\u00edfilis y gonorrea en hombres que en mujeres, los casos de clamidia en mujeres superaron en n\u00famero a los de hombres en la mayor\u00eda de &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/epidemiologia-de-sifilis-gonorrea-y-clamidia-en-el-centro-y-este-de-la-region-europea-de-la-oms\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEpidemiolog\u00eda de s\u00edfilis, gonorrea y clamidia en el Centro y Este de la Regi\u00f3n Europea de la OMS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7702","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7702"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7702\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}