{"id":7733,"date":"2022-08-30T02:30:53","date_gmt":"2022-08-30T07:30:53","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/las-dietas-bajas-en-carne-y-sin-carne-se-asocian-con-un-menor-riesgo-general-de-cancer\/"},"modified":"2022-08-30T02:30:53","modified_gmt":"2022-08-30T07:30:53","slug":"las-dietas-bajas-en-carne-y-sin-carne-se-asocian-con-un-menor-riesgo-general-de-cancer","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/las-dietas-bajas-en-carne-y-sin-carne-se-asocian-con-un-menor-riesgo-general-de-cancer\/","title":{"rendered":"Las dietas bajas en carne y sin carne se asocian con un menor riesgo general de c\u00e1ncer"},"content":{"rendered":"<p>Cr\u00e9dito: Unsplash\/CC0 Public Domain <\/p>\n<p>Comer carne cinco veces o menos por semana se asocia con un menor riesgo general de c\u00e1ncer, seg\u00fan un estudio publicado en la revista de acceso abierto BMC Medicine. <\/p>\n<p>Cody Watling y sus colegas de la Universidad de Oxford, Reino Unido, investigaron la relaci\u00f3n entre la dieta y el riesgo de c\u00e1ncer mediante el an\u00e1lisis de datos recopilados de 472\u00a0377 adultos brit\u00e1nicos que fueron reclutados en el Biobanco del Reino Unido entre 2006 y 2010. Los participantes, que ten\u00edan entre 40 y 70 a\u00f1os, informaron con qu\u00e9 frecuencia com\u00edan carne y pescado y los investigadores calcularon la incidencia de nuevos c\u00e1nceres que se desarrollaron durante un per\u00edodo promedio de 11 a\u00f1os utilizando registros de salud. Tomaron en cuenta el estado de la diabetes y los factores sociodemogr\u00e1ficos, socioecon\u00f3micos y de estilo de vida en sus an\u00e1lisis. 247 571 (52 %) de los participantes comieron carne m\u00e1s de cinco veces por semana, 205 382 (44 %) de los participantes comieron carne cinco o menos veces por semana, 10 696 (2 %) comieron pescado pero no carne y 8 685 (2 %) vegetariano o vegano. 54\u00a0961 participantes (12 %) desarrollaron c\u00e1ncer durante el per\u00edodo de estudio.<\/p>\n<p>Los investigadores encontraron que el riesgo general de c\u00e1ncer era un 2 % menor entre quienes com\u00edan carne cinco veces o menos por semana, un 10 % menor entre quienes com\u00edan pescado pero no carne, y un 14 % m\u00e1s bajo entre los vegetarianos y veganos, en comparaci\u00f3n con los que com\u00edan carne m\u00e1s de cinco veces por semana. Al comparar la incidencia de c\u00e1nceres espec\u00edficos con la dieta de los participantes, los autores encontraron que aquellos que com\u00edan carne cinco veces o menos por semana ten\u00edan un 9 % menos de riesgo de c\u00e1ncer colorrectal, en comparaci\u00f3n con aquellos que com\u00edan carne m\u00e1s de cinco veces por semana. Tambi\u00e9n encontraron que el riesgo de c\u00e1ncer de pr\u00f3stata era un 20 % m\u00e1s bajo entre los hombres que com\u00edan pescado pero no carne y un 31 % m\u00e1s bajo entre los hombres que segu\u00edan una dieta vegetariana, en comparaci\u00f3n con los que com\u00edan carne m\u00e1s de cinco veces por semana. Las mujeres posmenop\u00e1usicas que segu\u00edan una dieta vegetariana ten\u00edan un 18 % menos de riesgo de c\u00e1ncer de mama que las que com\u00edan carne m\u00e1s de cinco veces por semana. Sin embargo, los hallazgos sugieren que esto se debi\u00f3 a que las mujeres vegetarianas tend\u00edan a tener un \u00edndice de masa corporal (IMC) m\u00e1s bajo que las mujeres que com\u00edan carne.<\/p>\n<p>Los investigadores advierten que la naturaleza observacional de su estudio no permite conclusiones sobre una relaci\u00f3n causal entre la dieta y el riesgo de c\u00e1ncer. Adem\u00e1s, dado que los datos diet\u00e9ticos del UK Biobank se recopilaron en un solo momento, en lugar de durante un per\u00edodo de tiempo continuo, es posible que no sean representativos de las dietas de por vida de los participantes.<\/p>\n<p>Los autores sugieren que la investigaci\u00f3n futura podr\u00eda investigar las asociaciones entre las dietas que contienen poca o ninguna carne y el riesgo de c\u00e1nceres individuales en poblaciones m\u00e1s grandes con per\u00edodos de seguimiento m\u00e1s prolongados. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Volverse vegetariano para reducir el riesgo de c\u00e1ncer de colon <strong>M\u00e1s informaci\u00f3n:<\/strong> Cody Watling, Riesgo de c\u00e1ncer en los consumidores regulares y bajos de carne, comedores de pescado y vegetarianos: un an\u00e1lisis prospectivo de participantes del Biobanco del Reino Unido, BMC Medicine (2022). DOI: 10.1186\/s12916-022-02256-w. www.biomedcentral.com\/articles &hellip; 6\/s12916-022-02256-w <strong>Informaci\u00f3n de la revista:<\/strong> BMC Medicine <\/p>\n<p> Proporcionado por BioMed Central <strong>Cita<\/strong>: Las dietas bajas en carne y sin carne se asocian con una disminuci\u00f3n general riesgo de c\u00e1ncer (2022, 24 de febrero) recuperado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-02-health-low-meat-meat-free-diets-cancer.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Unsplash\/CC0 Public Domain Comer carne cinco veces o menos por semana se asocia con un menor riesgo general de c\u00e1ncer, seg\u00fan un estudio publicado en la revista de acceso abierto BMC Medicine. Cody Watling y sus colegas de la Universidad de Oxford, Reino Unido, investigaron la relaci\u00f3n entre la dieta y el riesgo de &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/las-dietas-bajas-en-carne-y-sin-carne-se-asocian-con-un-menor-riesgo-general-de-cancer\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLas dietas bajas en carne y sin carne se asocian con un menor riesgo general de c\u00e1ncer\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7733","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7733"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7733\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}