{"id":8710,"date":"2022-08-30T03:01:04","date_gmt":"2022-08-30T08:01:04","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/nuestros-atletas-olimpicos-estan-teniendo-una-crisis-de-salud-mental-que-estamos-haciendo-al-respecto-ademas-de-mirar\/"},"modified":"2022-08-30T03:01:04","modified_gmt":"2022-08-30T08:01:04","slug":"nuestros-atletas-olimpicos-estan-teniendo-una-crisis-de-salud-mental-que-estamos-haciendo-al-respecto-ademas-de-mirar","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/nuestros-atletas-olimpicos-estan-teniendo-una-crisis-de-salud-mental-que-estamos-haciendo-al-respecto-ademas-de-mirar\/","title":{"rendered":"Nuestros atletas ol\u00edmpicos est\u00e1n teniendo una crisis de salud mental. \u00bfQu\u00e9 estamos haciendo al respecto adem\u00e1s de mirar?"},"content":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain <\/p>\n<p>Se supone que los Juegos Ol\u00edmpicos son un espect\u00e1culo divertido y familiar. Pero dos a\u00f1os despu\u00e9s de la pandemia y en medio de una crisis de salud mental en todo el pa\u00eds, los Juegos Ol\u00edmpicos de Invierno de 2022, en ocasiones, han sido dolorosos de ver. <\/p>\n<p>El equipo de EE. UU. ya ha visto la grandeza; mire al patinador art\u00edstico favorito de los fan\u00e1ticos de 22 a\u00f1os, Nathan Chen, o la redenci\u00f3n de Lindsey Jacobellis, quien captur\u00f3 la primera medalla de oro del equipo de EE. UU. en snowboardcross. Pero es dif\u00edcil celebrar estas victorias cuando se yuxtaponen con las luchas de otros atletas.<\/p>\n<p>Zhu Yi, la patinadora art\u00edstica de 19 a\u00f1os nacida en EE. UU. que compite por China, sali\u00f3 de la pista llorando despu\u00e9s de caer dos veces. .<\/p>\n<p>Mikaela Shiffrin llor\u00f3 en la ladera de la colina despu\u00e9s de perder el control y grabar su segundo \u00abDid Not Finish\u00bb d\u00edas despu\u00e9s de que NBC transmitiera un emotivo segmento grabado sobre c\u00f3mo est\u00e1 luchando con el dolor despu\u00e9s de la muerte de su padre. muerte inesperada. El martes, su reacci\u00f3n llorosa se transmiti\u00f3 en horario de m\u00e1xima audiencia durante casi cinco minutos. Los espectadores expresaron l\u00e1stima y confusi\u00f3n sobre por qu\u00e9 el dolor de Shiffrin estuvo plasmado en sus televisores durante tanto tiempo.<\/p>\n<p>Tambi\u00e9n expresaron su consternaci\u00f3n cuando varios atletas de \u00e9lite, a menudo j\u00f3venes, luchan p\u00fablicamente en los Juegos. Pero, \u00bfpor qu\u00e9 sigue siendo una sorpresa?<\/p>\n<p>En los \u00faltimos a\u00f1os, superestrellas como Simone Biles, Naomi Osaka y Michael Phelps han expresado abiertamente la necesidad de un cambio. Nos han dicho que la presi\u00f3n es demasiada, las expectativas demasiado altas. Y los expertos dicen que los Juegos Ol\u00edmpicos en la era de COVID-19 con reglas estrictas sobre qui\u00e9n puede asistir, y sobre las pruebas y la cuarentena son un desaf\u00edo a\u00fan mayor, lo que exacerba el estr\u00e9s y la ansiedad de los atletas.<\/p>\n<p>\u00abYa hay tanto mucha presi\u00f3n por los Juegos Ol\u00edmpicos porque todos los ojos est\u00e1n puestos en ti&#8230; pero no fueron solo los Juegos Ol\u00edmpicos normales de este a\u00f1o. Hubo mucha incertidumbre sobre si se llevar\u00edan a cabo y c\u00f3mo\u00bb, dice Sian Beilock, presidente de Barnard College en Universidad de Columbia y un cient\u00edfico cognitivo que se especializa en psicolog\u00eda del deporte. \u00abSabemos que tener \u00e9xito a la vista del p\u00fablico es grandioso, pero fallar puede ser extremadamente dif\u00edcil\u00bb.<\/p>\n<p>&#8216;Es una verdadera olla a presi\u00f3n&#8217;<\/p>\n<p>Keith Kaufman, psic\u00f3logo cl\u00ednico deportivo, dice que Olympic los atletas ya enfrentan tantas presiones: La presi\u00f3n de ser perfectos; la presi\u00f3n de representar a su pa\u00eds. Incluso cuando son los mejores, se espera que sean mejores.<\/p>\n<p>\u00abMuchas de estas personas se han entrenado durante varios a\u00f1os, si no toda la vida, para prepararse para una actuaci\u00f3n corta\u00bb, dice Kaufman. \u00abEs una verdadera olla a presi\u00f3n. Hay algo \u00fanico en el desaf\u00edo de lo espor\u00e1dicas que son las Olimpiadas y lo larga e intensa que es la preparaci\u00f3n\u00bb.<\/p>\n<p>Pero las estrictas restricciones de COVID-19 en Beijing han agregado un capa de angustia emocional este a\u00f1o: los fan\u00e1ticos est\u00e1n nuevamente ausentes y los amigos y familiares de los atletas se ven obligados a quedarse en casa.<\/p>\n<p>La investigaci\u00f3n ha demostrado que el apoyo social es crucial para reducir los niveles de estr\u00e9s de los atletas.<\/p>\n<p> p&gt; <\/p>\n<p>\u00abTenemos que recordar que junto con todos los factores estresantes existentes, no tener una red de apoyo tan accesible es un gran problema\u00bb, dice Kaufman.<\/p>\n<p>La fijaci\u00f3n con los fracasos de los atletas, la miseria es peligrosa<\/p>\n<p>Beilock dice que tenemos una visi\u00f3n \u00abunidimensional\u00bb de los atletas. Se supone que su valor gira en torno a sus habilidades atl\u00e9ticas, y es miope pretender que no son humanos vulnerables capaces de equivocarse.<\/p>\n<p>\u00abLos atletas no son inmunes a los problemas de salud mental. Se enfrentan a presiones como t\u00fa y yo, y han estado lidiando con la pandemia durante los \u00faltimos dos a\u00f1os al igual que t\u00fa y yo\u00bb, dice Beilock.<\/p>\n<p>Para Shiffrin, los Juegos de Invierno de 2022 marcan sus primeros Juegos Ol\u00edmpicos sin su padre. <\/p>\n<p>\u00abEn este momento, realmente me gustar\u00eda llamarlo, para que eso no lo haga m\u00e1s f\u00e1cil\u00bb, dijo Shiffrin el lunes por la noche, rompiendo a llorar mientras hablaba de su padre, quien muri\u00f3 en 2020.<\/p>\n<p> p&gt; <\/p>\n<p>Kaufman dice que no sorprende que \u00ablos medios tiendan a querer enfocarse en el drama, lo que puede parecer bueno para la televisi\u00f3n, pero agrega otra capa a la angustia que experimenta un atleta\u00bb.<\/p>\n<p>\u00abTenemos un sesgo hacia lo negativo y, a veces, cuando vemos a alguien a quien consideramos un h\u00e9roe y lo vemos luchando, nos consuela un poco. Eso Tambi\u00e9n son humanos\u00bb.<\/p>\n<p>Los expertos dicen que las personas tienden a olvidar los logros de los atletas. Por ejemplo, Shiffrin gan\u00f3 una medalla de oro ol\u00edmpica no una, sino dos veces.<\/p>\n<p>\u00abMi esqu\u00ed ha sido realmente s\u00f3lido\u00bb, dijo Shiffrin sobre su desempe\u00f1o. \u00abCuando hay presi\u00f3n y hay algunos nervios y la sensaci\u00f3n de que quiero hacerlo bien, siempre vuelvo a la idea fundamental de que el buen esqu\u00ed estar\u00e1 all\u00ed para m\u00ed\u00bb.<\/p>\n<p>Aunque m\u00e1s atletas lo han hecho recientemente sido abiertos sobre su vulnerabilidad, la cultura deportiva enfatiza la disciplina, y Kaufman dice que debemos cambiar nuestra mentalidad para enfocarnos m\u00e1s ampliamente en sus logros.<\/p>\n<p>En lugar de obsesionarnos con las medallas, dice Kaufman, debemos apreciar el trabajo duro y la resistencia que se incluye en el entrenamiento.<\/p>\n<p>\u00abTodav\u00eda hay un sesgo hacia los atletas que son invencibles, se esfuerzan y se esfuerzan\u00bb, dice.<\/p>\n<p>\u00abDeber\u00edamos tomar un proceso m\u00e1s enfoque orientado y valore las complejidades del deporte, en lugar de reducir algo tan complejo a algo tan simple como, &#8216;\u00bfGanaron una medalla de oro o no?'\u00bb.<\/p>\n<p>Y aunque los espectadores pueden cambiar sus actitudes, los medios tambi\u00e9n desempe\u00f1an un papel en la amplificaci\u00f3n de la presi\u00f3n sobre los competidores. El a\u00f1o pasado, Osaka fue multada por negarse a hablar con la prensa despu\u00e9s de su salida del Abierto de Francia, diciendo que el cuestionamiento de los atletas por parte de los medios despu\u00e9s de una derrota es como \u00abpatear a una persona mientras est\u00e1 en el suelo\u00bb.<\/p>\n<p>\u00abNosotros debemos pensar en alterar el circo medi\u00e1tico en torno a algunos de estos atletas, y eso puede incluir no mostrarlos llorando durante 10 minutos en la pantalla\u00bb, dice Beilock. \u00abPuede incluir c\u00f3mo tratamos las entrevistas posteriores a la carrera o c\u00f3mo damos a los atletas algo de espacio despu\u00e9s de la derrota. O hablar de los atletas como personas completas, en lugar de simplemente ejecutar su deporte\u00bb.<\/p>\n<p>\u00abUna de las cosas m\u00e1s importantes que debe De esto surge una discusi\u00f3n sobre la salud mental: que es algo en lo que todos tenemos que trabajar. Pero espero que podamos usar estas conversaciones sobre salud mental para bien, en lugar de explotar su tristeza\u00bb. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Estadios vac\u00edos, temores de COVID: \u00bfC\u00f3mo afectar\u00e1 a los atletas ol\u00edmpicos? <\/p>\n<p> 2022 USA Today. Distribuido por Tribune Content Agency, LLC. <\/p>\n<p> <strong>Cita<\/strong>: Nuestros atletas ol\u00edmpicos est\u00e1n teniendo una crisis de salud mental. \u00bfQu\u00e9 estamos haciendo al respecto adem\u00e1s de mirar? (2022, 10 de febrero) recuperado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-02-olympic-athletes-mental-health-crisis.html Este documento est\u00e1 sujeto a derechos de autor. Adem\u00e1s de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede ser reproducido sin el permiso por escrito El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain Se supone que los Juegos Ol\u00edmpicos son un espect\u00e1culo divertido y familiar. Pero dos a\u00f1os despu\u00e9s de la pandemia y en medio de una crisis de salud mental en todo el pa\u00eds, los Juegos Ol\u00edmpicos de Invierno de 2022, en ocasiones, han sido dolorosos de ver. El equipo de EE. UU. &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/nuestros-atletas-olimpicos-estan-teniendo-una-crisis-de-salud-mental-que-estamos-haciendo-al-respecto-ademas-de-mirar\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abNuestros atletas ol\u00edmpicos est\u00e1n teniendo una crisis de salud mental. \u00bfQu\u00e9 estamos haciendo al respecto adem\u00e1s de mirar?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8710","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/8710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=8710"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/8710\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=8710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=8710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=8710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}