{"id":8717,"date":"2022-08-30T03:01:18","date_gmt":"2022-08-30T08:01:18","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/agregar-tirzepatida-a-la-insulina-glargina-aumenta-el-control-glucemico-en-la-dm2\/"},"modified":"2022-08-30T03:01:18","modified_gmt":"2022-08-30T08:01:18","slug":"agregar-tirzepatida-a-la-insulina-glargina-aumenta-el-control-glucemico-en-la-dm2","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/agregar-tirzepatida-a-la-insulina-glargina-aumenta-el-control-glucemico-en-la-dm2\/","title":{"rendered":"Agregar tirzepatida a la insulina glargina aumenta el control gluc\u00e9mico en la DM2"},"content":{"rendered":"<p>(HealthDay)La adici\u00f3n de tirzepatida subcut\u00e1nea versus placebo a la insulina glargina titulada da como resultado mejoras significativas en el control gluc\u00e9mico entre pacientes con diabetes tipo 2 y control gluc\u00e9mico inadecuado, seg\u00fan un estudio publicado en la edici\u00f3n del 8 de febrero de la revista Journal of the American Medical Association. <\/p>\n<p>Dominik Dahl, MD, de Gemeinschaftspraxis fr Innere Medizin und Diabetologie en Hamburgo, Alemania, y sus colegas asignaron al azar a adultos con diabetes tipo 2 que recib\u00edan insulina glargina, que ten\u00edan un control gluc\u00e9mico inadecuado, para recibir inyecciones subcut\u00e1neas una vez por semana de 5 mg , 10 mg o 15 mg de tirzepatida (116, 119 y 120, respectivamente) o placebo de volumen equivalente (120 adultos) durante 40 semanas.<\/p>\n<p>Los investigadores encontraron que el tratamiento se interrumpi\u00f3 prematuramente a las 10 , 12, 18 y 3 % de los participantes en los grupos de 5 mg, 10 mg y 15 mg de tirzepatida y en el grupo de placebo, respectivamente. Desde el inicio hasta la semana 40, el cambio medio de hemoglobina A1c (HbA1c) fue de 2,11, 2,40 y 2,34 % con 5 mg, 10 mg y 15 mg de tirzepatida, respectivamente, frente a 0,86 % con placebo. Desde el inicio, el cambio medio en el peso corporal fue de 5,4, 7,5, 8,8 y 1,6 kg con 5 mg, 10 mg y 15 mg de tirzepatida y placebo, respectivamente. En comparaci\u00f3n con los tratados con placebo, los porcentajes m\u00e1s altos de pacientes tratados con tirzepatida ten\u00edan HbA1c inferior al 7 % (85 a 90 % frente a 34 %).<\/p>\n<p>\u00abLos resultados del estudio actual proporcionan informaci\u00f3n cl\u00ednicamente relevante en relaci\u00f3n con el uso de tirzepatida en combinaci\u00f3n con una insulina basal que deber\u00eda ayudar a los m\u00e9dicos cuando se considera esta opci\u00f3n de tratamiento\u00bb, escriben los autores.<\/p>\n<p>Varios autores revelaron v\u00ednculos financieros con compa\u00f1\u00edas farmac\u00e9uticas, incluida Eli Lilly, que fabrica tirzepatida y financi\u00f3 el estudio. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Tirzepatida no inferior, superior a semaglutida para T2DM <strong>M\u00e1s informaci\u00f3n:<\/strong> Dominik Dahl et al, Efecto de la tirzepatida subcut\u00e1nea frente al placebo a\u00f1adido a la insulina glargina titulada sobre el control gluc\u00e9mico en pacientes con tipo 2 Diabetes, JAMA (2022). DOI: 10.1001\/jama.2022.0078 <strong>Informaci\u00f3n de la revista:<\/strong> Revista de la Asociaci\u00f3n M\u00e9dica Estadounidense <\/p>\n<p> Copyright 2021 HealthDay. Reservados todos los derechos. <\/p>\n<p> <strong>Cita<\/strong>: Adding tirzepatide to insulin glargine ups glucemic control in T2DM (2022, 10 de febrero) consultado el 29 de agosto de 2022 en https:\/\/medicalxpress.com\/news\/2022-02-adding- tirzepatide-insulina-glargine-ups.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(HealthDay)La adici\u00f3n de tirzepatida subcut\u00e1nea versus placebo a la insulina glargina titulada da como resultado mejoras significativas en el control gluc\u00e9mico entre pacientes con diabetes tipo 2 y control gluc\u00e9mico inadecuado, seg\u00fan un estudio publicado en la edici\u00f3n del 8 de febrero de la revista Journal of the American Medical Association. Dominik Dahl, MD, de &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/agregar-tirzepatida-a-la-insulina-glargina-aumenta-el-control-glucemico-en-la-dm2\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abAgregar tirzepatida a la insulina glargina aumenta el control gluc\u00e9mico en la DM2\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8717","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/8717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=8717"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/8717\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=8717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=8717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=8717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}