{"id":8720,"date":"2022-08-30T03:01:24","date_gmt":"2022-08-30T08:01:24","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/estudio-ofrece-nuevos-conocimientos-sobre-como-la-exposicion-a-metales-puede-afectar-el-crecimiento-fetal\/"},"modified":"2022-08-30T03:01:24","modified_gmt":"2022-08-30T08:01:24","slug":"estudio-ofrece-nuevos-conocimientos-sobre-como-la-exposicion-a-metales-puede-afectar-el-crecimiento-fetal","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/estudio-ofrece-nuevos-conocimientos-sobre-como-la-exposicion-a-metales-puede-afectar-el-crecimiento-fetal\/","title":{"rendered":"Estudio ofrece nuevos conocimientos sobre c\u00f3mo la exposici\u00f3n a metales puede afectar el crecimiento fetal"},"content":{"rendered":"<p>Cr\u00e9dito: Pixabay\/CC0 Dominio p\u00fablico <\/p>\n<p>Un nuevo estudio dirigido por Dartmouth, publicado en la revista Environmental International, revela c\u00f3mo la exposici\u00f3n prenatal a mezclas de metales que se encuentran com\u00fanmente puede afectar adversamente el crecimiento fetal. <\/p>\n<p>El crecimiento fetal est\u00e1 relacionado con la salud futura: los beb\u00e9s que nacen peque\u00f1os para su edad gestacional experimentan mayores tasas de mortalidad neonatal y tienen un mayor riesgo de desarrollar deterioro neurocognitivo en la ni\u00f1ez y enfermedad cardiometab\u00f3lica m\u00e1s adelante en la vida. <\/p>\n<p>Un n\u00famero creciente de estudios ha establecido que los metales t\u00f3xicos, provenientes de fuentes como alimentos y agua potable contaminados y aire y polvo contaminados, prevalecen en el medio ambiente, y muchos de estos metales pueden atravesar la placenta o alterar la funci\u00f3n placentaria, contribuyendo a la reducci\u00f3n del crecimiento fetal. <\/p>\n<p>Pero las investigaciones anteriores que analizan los impactos de los metales en el crecimiento fetal generalmente han analizado un metal a la vez y dentro de una poblaci\u00f3n individual. <\/p>\n<p>\u00abLa limitaci\u00f3n de eso es que, por lo general, estamos expuestos a una mezcla compleja de m\u00faltiples metales simult\u00e1neamente que pueden interactuar entre s\u00ed, y los rangos de exposici\u00f3n pueden ser estrechos en una sola poblaci\u00f3n para un metal determinado\u00bb, explica la autora principal Caitlin Howe, Ph.D., profesora asistente de epidemiolog\u00eda en la Escuela de Medicina Geisel de Dartmouth, cuya investigaci\u00f3n se centra en la exposici\u00f3n a metales t\u00f3xicos y sus impactos en la salud materna e infantil. <\/p>\n<p>\u00abEntonces, nuestro objetivo era analizar m\u00faltiples poblaciones diversas con diferentes tipos de exposiciones, para que pudi\u00e9ramos tener una mejor idea de la relaci\u00f3n dosis-respuesta completa para algunos de estos qu\u00edmicos en el contexto de la mezcla m\u00e1s grande ,\u00bb ella dice. <\/p>\n<p>Para lograr esto, los investigadores realizaron un an\u00e1lisis de mezcla ambiental de los impactos de los metales en el crecimiento fetal, reuniendo datos de tres grupos geogr\u00e1fica y demogr\u00e1ficamente diversos en los EE. UU. Los grupos, ubicados en New Hampshire, Los \u00c1ngeles y Puerto Rico, participe en el programa de investigaci\u00f3n nacional Environmental Influences on Child Health Outcomes (ECHO) apoyado por los NIH que estudia los efectos de una amplia gama de influencias ambientales tempranas en la salud y el desarrollo infantil.<\/p>\n<p>Usando una novela enfoque estad\u00edstico que puede dar cuenta de mezclas complejas de contaminantes, los investigadores examinaron asociaciones entre siete metales que se encuentran com\u00fanmente (antimonio, cadmio, cobalto, mercurio, molibdeno, n\u00edquel y esta\u00f1o) medidos en 1,002 muestras de orina materna que se recolectaron durante el embarazo y peso al nacer para la edad gestacional. Tambi\u00e9n investigaron las posibles diferencias entre los grupos y el sexo de los beb\u00e9s.<\/p>\n<p>\u00abNuestro hallazgo m\u00e1s consistente fue que el antimonio, un metal poco estudiado, se asoci\u00f3 con un menor peso al nacer para la edad gestacional en los tres grupos y en tanto en hombres como en mujeres, lo que sugiere que puede tener un impacto adverso en el crecimiento fetal\u00bb, dice Howe. \u00abEntonces, ese es un elemento en el que nos gustar\u00eda identificar cu\u00e1les son las principales fuentes de exposici\u00f3n para que podamos ayudar a reducir esa exposici\u00f3n para prevenir efectos nocivos sobre el crecimiento fetal en estas diferentes poblaciones\u00bb.<\/p>\n<p>Por ejemplo, las concentraciones m\u00e1s altas de antimonio observadas en los grupos de Los \u00c1ngeles y Puerto Rico pueden deberse a sus ubicaciones urbanas, ya que se sabe que la contaminaci\u00f3n del aire relacionada con el tr\u00e1fico por el desgaste de los frenos es una fuente importante de exposici\u00f3n al antimonio, al igual que la fundici\u00f3n y la quema de carb\u00f3n. plantas e incineradores de residuos. Por el contrario, el agua embotellada puede ser una fuente relevante de exposici\u00f3n al antimonio para los tres grupos.<\/p>\n<p>Aunque los investigadores identificaron algunas asociaciones dependientes del grupo y\/o del sexo para muchos de los otros metales estudiados, dice Howe , carec\u00edan de la consistencia que se observ\u00f3 para los resultados de antimonio y, por lo tanto, merecen una mayor investigaci\u00f3n. <\/p>\n<p>\u00abNuestra esperanza es que podamos hacer un estudio m\u00e1s grande en el futuro que incluya m\u00e1s cohortes, para que podamos analizar m\u00e1s a fondo qu\u00e9 est\u00e1 impulsando esas inconsistencias y comprender mejor las posibles diferencias debido a la geograf\u00eda u otras caracter\u00edsticas de la poblaci\u00f3n. \u00ab, dice Howe. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Los metales y los metaloides pueden alterar las concentraciones de hormonas prenatales durante el embarazo: estudio <strong>M\u00e1s informaci\u00f3n:<\/strong> Caitlin G. Howe et al, Prenatal metal(loid) mixes and birth peso for gestational age : Un an\u00e1lisis combinado de tres cohortes que participan en el programa ECHO, Environment International (2022). DOI: 10.1016\/j.envint.2022.107102 <strong>Informaci\u00f3n de la revista:<\/strong> Environment International <\/p>\n<p> Proporcionado por Dartmouth College <strong>Cita<\/strong>: El estudio ofrece nuevos conocimientos sobre c\u00f3mo la exposici\u00f3n a metales puede afectar el crecimiento fetal (2022, 10 de febrero) recuperado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-02-insights-metal-exposures-impact-fetal.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Pixabay\/CC0 Dominio p\u00fablico Un nuevo estudio dirigido por Dartmouth, publicado en la revista Environmental International, revela c\u00f3mo la exposici\u00f3n prenatal a mezclas de metales que se encuentran com\u00fanmente puede afectar adversamente el crecimiento fetal. El crecimiento fetal est\u00e1 relacionado con la salud futura: los beb\u00e9s que nacen peque\u00f1os para su edad gestacional experimentan mayores &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/estudio-ofrece-nuevos-conocimientos-sobre-como-la-exposicion-a-metales-puede-afectar-el-crecimiento-fetal\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio ofrece nuevos conocimientos sobre c\u00f3mo la exposici\u00f3n a metales puede afectar el crecimiento fetal\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8720","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/8720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=8720"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/8720\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=8720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=8720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=8720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}