{"id":12950,"date":"2022-07-26T13:55:17","date_gmt":"2022-07-26T18:55:17","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/como-leer-la-biblia-bien\/"},"modified":"2022-07-26T13:55:17","modified_gmt":"2022-07-26T18:55:17","slug":"como-leer-la-biblia-bien","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/como-leer-la-biblia-bien\/","title":{"rendered":"C\u00f3mo leer la Biblia&nbsp;Bien"},"content":{"rendered":"<div class='resource__body'>\n<p>Leer la Biblia como cristiano le da m\u00e1s informaci\u00f3n sobre el misterio del universo que Mois\u00e9s, el rey David o Salom\u00f3n. <em>Leer<\/em> te proporciona una comprensi\u00f3n inimaginable. <\/p>\n<p>No entendemos \u201cel misterio de Cristo\u201d (Efesios 3:3) a trav\u00e9s de encantamientos m\u00edsticos, o meditaciones mentales, o incluso a trav\u00e9s de la simple oraci\u00f3n. M\u00e1s bien, Pablo dice que es al leer lo que escribi\u00f3 que podemos entender lo que no se dio a conocer en todo su significado \u201ca los hijos de los hombres en otras generaciones\u201d (Efesios 3:5).<\/p>\n<p>De esto, debemos inferir que Dios quiere que prestemos atenci\u00f3n a las palabras de la Escritura y sepamos c\u00f3mo se usan. Entonces, cuando lleguemos a nuestras Biblias, dejemos de lado los errores gemelos de la pereza y la desesperanza. No podemos darnos el lujo de desviarnos perezosamente de las palabras de Dios; debemos esforzarnos por comprender lo que Dios pretend\u00eda que entendi\u00e9ramos a trav\u00e9s de los autores b\u00edblicos. Pero incluso cuando sea dif\u00edcil de entender, lea con esperanza, sabiendo que Dios, a trav\u00e9s de la lectura de su palabra, desea que comprendamos las verdades m\u00e1s grandes del universo, y \u00c9l nos ayudar\u00e1 a hacerlo.<\/p>\n<\/p>\n<p><em>Mira el libro<\/em> es el esfuerzo m\u00e1s reciente de John Piper para ayudar a ense\u00f1ar a las personas a leer la Biblia por s\u00ed mismas. Es una serie continua de videos de 8 a 12 minutos en los que la c\u00e1mara est\u00e1 en el texto, no en el maestro. <\/p>\n<p>Como parte de esta iniciativa, Deseando a Dios est\u00e1 organizando eventos regionales enfocados en ciertos pasajes de las Escrituras. Esta es la Parte 2 de una serie sobre Efesios llamada \u00abVer y saborear el esplendor de la gracia soberana de Dios\u00bb.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Leer la Biblia como cristiano le da m\u00e1s informaci\u00f3n sobre el misterio del universo que Mois\u00e9s, el rey David o Salom\u00f3n. Leer te proporciona una comprensi\u00f3n inimaginable. No entendemos \u201cel misterio de Cristo\u201d (Efesios 3:3) a trav\u00e9s de encantamientos m\u00edsticos, o meditaciones mentales, o incluso a trav\u00e9s de la simple oraci\u00f3n. M\u00e1s bien, Pablo dice &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/como-leer-la-biblia-bien\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abC\u00f3mo leer la Biblia&nbsp;Bien\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12950","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/12950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=12950"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/12950\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=12950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=12950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=12950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}