{"id":12951,"date":"2022-07-26T13:55:19","date_gmt":"2022-07-26T18:55:19","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/quien-podria-ser-feliz-en-un-mundo-como-el-nuestro\/"},"modified":"2022-07-26T13:55:19","modified_gmt":"2022-07-26T18:55:19","slug":"quien-podria-ser-feliz-en-un-mundo-como-el-nuestro","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/quien-podria-ser-feliz-en-un-mundo-como-el-nuestro\/","title":{"rendered":"\u00bfQui\u00e9n podr\u00eda ser feliz en un mundo como el nuestro?"},"content":{"rendered":"<div class='resource__body'>\n<p>Dios es un Dios que hace felices. Lo reclama como su nombre, un s\u00edmbolo eterno de qui\u00e9n <em>es<\/em>: \u201cSaldr\u00e9is con alegr\u00eda y ser\u00e9is conducidos en paz. . . . Y har\u00e1 un nombre para el Se\u00f1or\u201d (Isa\u00edas 55:12\u201313). El plan eterno de Dios es hacer feliz a su pueblo.<\/p>\n<p>Y, sin embargo, muy a menudo, la felicidad parece estar fuera de nuestro alcance: aborto institucionalizado, tiroteos masivos, recurrencia del c\u00e1ncer, colapso moral, amigos infieles. , pecados personales que parecen tan incrustados en nuestros huesos que simplemente no morir\u00e1n. \u00bfQui\u00e9n podr\u00eda ser feliz en un mundo como el nuestro?<\/p>\n<p>Dios no se lo pierde. No se sienta con los brazos cruzados, prometiendo en vano alegr\u00eda a los creyentes aplastados por la tristeza. Entr\u00f3 en nuestro mundo corporalmente y soport\u00f3 el mayor de todos los dolores, incluso una muerte de maldici\u00f3n en una cruz (Filipenses 2:8), para que <em>en<\/em> nuestros dolores, <em>en<\/em> el dolor de vivir en un mundo ca\u00eddo, podemos \u201cgozarnos, aunque ahora por un poco de tiempo . . . hab\u00e9is sido afligidos por diversas pruebas\u201d (1 Pedro 1:6). Esto es lo que significa estar \u201ctristes, pero siempre gozosos\u201d en el Dios que hace felices (2 Corintios 6:10).<\/p>\n<\/p>\n<p><em>Mira el Libro<\/em> es el \u00faltimo esfuerzo de John Piper para ayudar a ense\u00f1ar a las personas a leer la Biblia por s\u00ed mismas. Es una serie continua de videos de 8 a 12 minutos en los que la c\u00e1mara est\u00e1 en el texto, no en el maestro. <\/p>\n<p>Como parte de esta iniciativa, Deseando a Dios est\u00e1 organizando eventos regionales enfocados en ciertos pasajes de las Escrituras. Esta es la Parte 1 de una serie sobre Efesios llamada \u00abVer y saborear el esplendor de la gracia soberana de Dios\u00bb.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dios es un Dios que hace felices. Lo reclama como su nombre, un s\u00edmbolo eterno de qui\u00e9n es: \u201cSaldr\u00e9is con alegr\u00eda y ser\u00e9is conducidos en paz. . . . Y har\u00e1 un nombre para el Se\u00f1or\u201d (Isa\u00edas 55:12\u201313). El plan eterno de Dios es hacer feliz a su pueblo. Y, sin embargo, muy a menudo, &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/quien-podria-ser-feliz-en-un-mundo-como-el-nuestro\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfQui\u00e9n podr\u00eda ser feliz en un mundo como el nuestro?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12951","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/12951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=12951"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/12951\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=12951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=12951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=12951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}