{"id":12954,"date":"2022-07-26T13:55:25","date_gmt":"2022-07-26T18:55:25","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/como-vivir-en-los-ultimos-dias-de-la-historia\/"},"modified":"2022-07-26T13:55:25","modified_gmt":"2022-07-26T18:55:25","slug":"como-vivir-en-los-ultimos-dias-de-la-historia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/como-vivir-en-los-ultimos-dias-de-la-historia\/","title":{"rendered":"C\u00f3mo vivir en los \u00faltimos&nbsp;d\u00edas de la historia"},"content":{"rendered":"<div class='resource__body'>\n<p>\u201cEl fin est\u00e1 cerca\u201d.<\/p>\n<p>Esta frase casi se ha desgastado por las im\u00e1genes de los profetas del tablero s\u00e1ndwich y los salvajes predicadores callejeros de ojos cerrados. Pero tambi\u00e9n es lo que dijo el ap\u00f3stol Pedro hace dos mil a\u00f1os: \u201cEl fin de todas las cosas se acerca\u201d (1 Pedro 4:7). Este tiempo entre la primera y la segunda venida de Cristo son los \u201c\u00faltimos d\u00edas\u201d (1 Pedro 1:20; Hebreos 1:2; 9:26), y por lo tanto, los cristianos deben estar especialmente atentos a su comportamiento para hacer \u201cel mejor uso del tiempo\u201d (Efesios 5:16). <\/p>\n<p>El tiempo se est\u00e1 acabando, entonces, \u00bfc\u00f3mo debemos vivir?<\/p>\n<p>Tomar el final de todas las cosas con sobriedad y seriedad significa que nuestra confianza en la oraci\u00f3n aumenta. En lugar de trabajar fren\u00e9ticamente para \u201chacer, hacer, hacer\u201d antes de que se acabe el tiempo, debemos venir m\u00e1s y m\u00e1s a descansar en la soberan\u00eda de Dios y buscar su ayuda (1 Pedro 4:7). Esta oraci\u00f3n no nos lleva al aislamiento, sino a un amor cada vez mayor por el pr\u00f3jimo, desde el coraz\u00f3n y en el hogar (1 Pedro 4:8\u20139).<\/p>\n<\/p>\n<p><em>Look at the Book<\/em> es el esfuerzo m\u00e1s reciente de John Piper para ayudar a ense\u00f1ar a las personas a leer la Biblia por s\u00ed mismas. Es una serie continua de videos de 8 a 12 minutos en los que la c\u00e1mara est\u00e1 en el texto, no en el maestro. <\/p>\n<p>Como parte de esta iniciativa, Deseando a Dios est\u00e1 organizando eventos regionales enfocados en ciertos pasajes de las Escrituras. Esta es la Parte 11 de una serie sobre 1 Pedro llamada \u201cEsperando, Cantando y Amando en el Fuego Purificador\u201d. Se lanzar\u00e1n m\u00e1s partes en las pr\u00f3ximas semanas.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEl fin est\u00e1 cerca\u201d. Esta frase casi se ha desgastado por las im\u00e1genes de los profetas del tablero s\u00e1ndwich y los salvajes predicadores callejeros de ojos cerrados. Pero tambi\u00e9n es lo que dijo el ap\u00f3stol Pedro hace dos mil a\u00f1os: \u201cEl fin de todas las cosas se acerca\u201d (1 Pedro 4:7). Este tiempo entre la &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/como-vivir-en-los-ultimos-dias-de-la-historia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abC\u00f3mo vivir en los \u00faltimos&nbsp;d\u00edas de la historia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12954","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/12954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=12954"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/12954\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=12954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=12954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=12954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}