{"id":23577,"date":"2022-07-29T17:47:00","date_gmt":"2022-07-29T22:47:00","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/pueden-sobrevivir-nuestros-huesos-secos-despues-de-que-el-pecado-nos-ha-separado-de-dios\/"},"modified":"2022-07-29T17:47:00","modified_gmt":"2022-07-29T22:47:00","slug":"pueden-sobrevivir-nuestros-huesos-secos-despues-de-que-el-pecado-nos-ha-separado-de-dios","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/pueden-sobrevivir-nuestros-huesos-secos-despues-de-que-el-pecado-nos-ha-separado-de-dios\/","title":{"rendered":"\u00bfPueden sobrevivir nuestros \u201chuesos secos\u201d despu\u00e9s de que el pecado nos ha separado de Dios?"},"content":{"rendered":"<p>Mi amiga jud\u00eda Miriam Feinberg Vamosh y yo ten\u00edamos un itinerario. En 2007, mientras viajaba por la Tierra de la Biblia con Miriam para hacer investigaci\u00f3n para nuestro libro <em>Reflejos de la Tierra Santa de Dios, un viaje personal a trav\u00e9s de Israel&nbsp;<\/em> (Thomas Nelson, 2008), logramos ce\u00f1irnos a ese itinerario. A menos que decidi\u00e9ramos desviarnos.<\/p>\n<p>As\u00ed fue el d\u00eda que entramos al Jard\u00edn de Getseman\u00ed, un jard\u00edn bien cuidado de olivos antiguos y nudosos con hojas diminutas que brillan con los rayos del sol y la suave susurro de una brisa. Cerca de all\u00ed, los visitantes entraban y sal\u00edan de la Iglesia de Todas las Naciones, una iglesia construida sobre un lecho de roca donde Jes\u00fas or\u00f3 la noche de su traici\u00f3n (Marcos 14:32-42).<\/p>\n<p>Tom\u00e9 fotos aqu\u00ed y all\u00ed de los \u00e1rboles y de los caminos que se cruzaban entre ellos. Entonces un hombre reconoci\u00f3 a Miriam y le pregunt\u00f3: \u201c\u00bfTe gustar\u00eda ir al jard\u00edn privado?\u201d. Miriam respondi\u00f3 con una pregunta: \u00ab\u00bfTienes la llave?\u00bb<\/p>\n<p>\u00abS\u00ed\u00bb, dijo \u00e9l.<\/p>\n<p>En un momento, nos escoltaban silenciosamente a un jard\u00edn al otro lado la calle. Sin mucha fanfarria, el hombre abri\u00f3 la puerta, entramos y luego el hombre cerr\u00f3 la puerta detr\u00e1s de nosotros. Est\u00e1bamos solos en un \u00e1rea cerrada que se parec\u00eda mucho a la de enfrente. . . solo que este ten\u00eda una peque\u00f1a estructura similar a una cueva y, dentro de esa estructura. . . huesos.<\/p>\n<h2>Un valle de huesos secos<\/h2>\n<p>Montones y montones de huesos humanos. . . blanqueada por el tiempo. Seco. Fr\u00e1gil. Llevaban aqu\u00ed un tiempo. Le pregunt\u00e9 a Miriam sobre ellos y me ofreci\u00f3 una posibilidad, aunque realmente nunca confirmamos su suposici\u00f3n. <\/p>\n<p>Pero estos huesos me recordaron los vers\u00edculos del libro de Ezequiel, que contiene cuarenta y ocho cap\u00edtulos de algunos de los pasajes de juicio y esperanza m\u00e1s descriptivos y amplios que se encuentran en el texto de la Biblia. Tejidas como un tapiz hay visiones de la ira de Dios y Su gloria, de Su condenaci\u00f3n y Su salvaci\u00f3n. \u00bfY por qu\u00e9? Porque el pueblo escogido de Dios le hab\u00eda dado la espalda a \u00c9l ya Sus caminos. Hab\u00edan ca\u00eddo en la corrupci\u00f3n, incluso dentro del Templo. Su adoraci\u00f3n estaba contaminada, sus vidas coloreadas por los matices de la desobediencia y el paganismo. Dios anunci\u00f3 Su decisi\u00f3n: para limpiar el lugar, permitir\u00eda que Jerusal\u00e9n y el Templo fueran destruidos. Entran los babilonios.<\/p>\n<p>El pueblo, ahora en cautiverio del rey Nabucodonosor, cre\u00eda que todo estaba perdido. \u00bfQu\u00e9 pod\u00edan hacer ahora sino tratar de encajar? Estaban, a sus propios ojos, <em>muertos<\/em> como pueblo. Le hab\u00edan dado la espalda a Dios, \u00c9l les hab\u00eda dado la espalda a ellos (en realidad, les hab\u00eda dado la espalda a su pecado, pero nunca a ellos), y no pod\u00eda haber vuelta atr\u00e1s. O eso pensaban.<\/p>\n<p>Como la visi\u00f3n de Ezequiel de condenaci\u00f3n y salvaci\u00f3n comenz\u00f3 en el r\u00edo Kebar en Babilonia y luego continu\u00f3, Dios se lo llev\u00f3 por el Esp\u00edritu. En el cap\u00edtulo 37 de Ezequiel, al joven profeta se le muestra un valle, un punto bajo, <em>lleno de huesos<\/em> (37:1). Hab\u00eda tantos huesos, que <em>cubr\u00edan el fondo del valle,&nbsp;<\/em>y estaban <em>dispersos&nbsp;<\/em>y <em>se secaron por completo&nbsp;<\/em>(37:2) . Esta escena, que se parece mucho a una novela de Stephen King, mostraba a los antiguos ciudadanos de Jud\u00e1 que hab\u00edan sido llevados cautivos por Babilonia, con los huesos marchitos por la desesperanza. No yac\u00edan all\u00ed como esqueletos completos. En cambio, fueron arrojados por todo el lugar. \u00bfQu\u00e9 bien podr\u00eda salir de una escena as\u00ed? \u00bfQu\u00e9 esperanza pod\u00eda haber para el pueblo que hab\u00eda pagado tal precio, uno que sinti\u00f3 de una vez por todas, por su desobediencia?&nbsp;<\/p>\n<\/p>\n<p><em><\/p>\n<p>De el exterior mirando hacia adentro, al igual que yo hab\u00eda mirado dentro de la cueva escondida en el jard\u00edn privado en el Monte de los Olivos, la respuesta deber\u00eda haber sido un rotundo \u00abno\u00bb. No habr\u00eda esperado que los huesos se movieran repentinamente y vibraran hasta que los huesos de la rodilla estuvieran conectados con los huesos del muslo y as\u00ed sucesivamente. No hubiera esperado que los cr\u00e1neos formaran rostros y que los esqueletos, una vez reunidos, formaran m\u00fasculos, \u00f3rganos y piel. No esperaba que esos huesos, apilados unos sobre otros, se pusieran de pie y formaran un ej\u00e9rcito.&nbsp;<\/p>\n<p>Pero Ezequiel era consciente de que Dios pod\u00eda hacer lo que Dios quisiera. Y esto es lo que Dios le dijo al profeta. Primero los huesos se juntaron y la carne se form\u00f3, pero no hab\u00eda vida. Pero la vida vendr\u00eda de nuevo. Se producir\u00eda la restauraci\u00f3n. . . <em>despu\u00e9s<\/em> del aliento<em>&nbsp;<\/em>entr\u00f3 en ellos.&nbsp;<\/p>\n<p><em>Entonces me dijo: \u201cProfetiza al aliento; profetiza, hijo de hombre, y dile: &#8216;As\u00ed dice el Soberano&nbsp;<\/em><em>Se\u00f1or<\/em><em>&nbsp;: Ven, respira, de los cuatro vientos y sopla en estos muertos , para que vivan.&#8217;\u201d<\/em><em>&nbsp;Profetic\u00e9, pues, como me hab\u00eda mandado, y entr\u00f3 esp\u00edritu en ellos; cobraron vida y se pusieron de pie: un gran ej\u00e9rcito&nbsp;<\/em>(Ezequiel 37:9, 10).<\/p>\n<p>En el Antiguo Testamento hebreo, la palabra aliento es <em>r\u00fbah <\/em>, que significa <em>aliento&nbsp;<\/em>. . . y <em>viento&nbsp;<\/em>. . . y <em>Esp\u00edritu<\/em>. Muchos a\u00f1os despu\u00e9s de esta escena de carnicer\u00eda y vida y huesos rechinando y esqueletos vivientes, cuando Jes\u00fas explic\u00f3 el camino de la salvaci\u00f3n a Nicodemo, us\u00f3 este juego de palabras, un giro (por as\u00ed decirlo) que pens\u00f3 que Nicodemo entender\u00eda. p&gt;<\/p>\n<p><em>De cierto os digo, que nadie puede entrar en el reino de Dios si no nace de agua y del Esp\u00edritu.<\/em><em>&nbsp;La carne da a luz a la carne, pero el Esp\u00edritu&amp;nbsp ;da a luz al esp\u00edritu. No deber\u00edas sorprenderte de que te diga: &#8216;Tienes que nacer de nuevo&#8217;. El&nbsp;<\/em>viento<em>&nbsp;sopla donde quiere. Oyes su sonido, pero no sabes de d\u00f3nde viene ni ad\u00f3nde va. As\u00ed es con todo aquel que es nacido del Esp\u00edritu<em>\u201d&nbsp;<\/em>(Juan 3:5-8, \u00e9nfasis m\u00edo).&nbsp;<\/p>\n<p>Entonces la esperanza est\u00e1 dentro el esp\u00edritu. Estos huesos secos m\u00edos no pueden hacer nada por s\u00ed mismos m\u00e1s de lo que los huesos secos en el jard\u00edn privado podr\u00edan ponerse de pie y bailar entre los olivos. Pero por el poder del Esp\u00edritu, todas las cosas se vuelven posibles.<\/p>\n<h2>\u00bfQu\u00e9 se necesitar\u00eda para traernos de regreso hoy?<\/h2>\n<p>Recientemente pas\u00e9 una gran cantidad de tiempo (un <em> cantidad de tiempo inusual<\/em> para m\u00ed) acostado en el sof\u00e1 viendo televisi\u00f3n y durmiendo la siesta (gracias a COVID). D\u00e9jame ser sincero; despu\u00e9s de unas pocas horas, ca\u00ed en la desesperaci\u00f3n. Los comerciales que anuncian el pecado y la impiedad parecen ser la norma ahora (recuerdo cuando los comerciales eran mujeres de mediana edad que anunciaban l\u00edquido para lavar platos y cosas por el estilo). Promovemos las cosas que deben mantenerse en privado y mantenemos en privado las cosas que deben promocionarse. Incluso los comerciales que anuncian pr\u00f3ximos espect\u00e1culos y pel\u00edculas nos inundan con cosas de naturaleza imp\u00eda.&nbsp;<\/p>\n<p>Me sent\u00ed como Ezequiel parado (o acostado) en un valle, rodeado de huesos secos. Y me preguntaba qu\u00e9 se necesitar\u00eda para traernos de vuelta de Babilonia. O, me preguntaba, \u00bfhemos decidido simplemente tratar de encajar? \u00bfNo ser\u00eda m\u00e1s f\u00e1cil yacer all\u00ed, coci\u00e9ndose al sol, que levantarse como un ej\u00e9rcito listo para marchar a la batalla?<\/p>\n<p>La respuesta para m\u00ed y para ti, hoy es la misma que antes. por los exiliados de Jerusal\u00e9n: necesitamos que el Esp\u00edritu Santo de Dios sople sobre nosotros. Necesitamos que \u00c9l sople a trav\u00e9s del valle hasta que todos los huesos se unan nuevamente y luego sople nuevamente hasta que los m\u00fasculos, los \u00f3rganos y la carne se formen y sople una vez m\u00e1s hasta que estemos firmes como un ej\u00e9rcito, fuertes y listos para la guerra que Satan\u00e1s est\u00e1 librando contra la humanidad. <\/p>\n<p>Entonces, si hago esta pregunta: <em>\u00bfPueden vivir los huesos secos y dispersos de mi vida despu\u00e9s de que el pecado me ha separado de Dios<\/em>?, determino que la respuesta es un rotundo <em>\u00a1s\u00ed!&nbsp;<\/em><\/p>\n<p>\u201cAs\u00ed que\u201d, escribi\u00f3 Pablo en su carta a la iglesia de Corinto, \u201csi alguno est\u00e1 en Cristo, nueva criatura es; lo viejo se ha ido, lo nuevo ha llegado!\u201d (2 Corintios 5:17).<\/p>\n<p>Es el Esp\u00edritu de Cristo quien sopla a trav\u00e9s de nosotros y dentro de nosotros para traernos de regreso a donde debemos estar, ya sea que seamos nuevos en la fe o Llevo muchos a\u00f1os recorriendo los caminos entre los olivos. todos vamos a pecar. Todos nos quedaremos cortos. Pero Dios nunca nos falla. As\u00ed como restaur\u00f3 a Israel, nos restaura a nosotros. \u00c9l nos devuelve a la vida para que formemos un ej\u00e9rcito poderoso.&nbsp;<\/p>\n<p>Y quiz\u00e1s cuando la complacencia haya dado paso a la convicci\u00f3n, dejemos de vivir en Babilonia y volvamos a adorar y a vivir en el manera que Dios quiso desde el principio. en santidad. Pureza. Confianza en la Verdad.&nbsp;<\/p>\n<p>\u00bfDe qu\u00e9 manera se han secado y esparcido tus huesos? \u00bfDe qu\u00e9 manera te has conformado al mundo que parece habernos tomado cautivos? \u00bfEs m\u00e1s f\u00e1cil para ti yacer dentro del valle o est\u00e1s listo para verlos reunirse de nuevo? Luego ore: \u201cRespira, Esp\u00edritu, respira\u201d. Am\u00e9n.<\/p>\n<p><em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mi amiga jud\u00eda Miriam Feinberg Vamosh y yo ten\u00edamos un itinerario. En 2007, mientras viajaba por la Tierra de la Biblia con Miriam para hacer investigaci\u00f3n para nuestro libro Reflejos de la Tierra Santa de Dios, un viaje personal a trav\u00e9s de Israel&nbsp; (Thomas Nelson, 2008), logramos ce\u00f1irnos a ese itinerario. A menos que decidi\u00e9ramos &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/pueden-sobrevivir-nuestros-huesos-secos-despues-de-que-el-pecado-nos-ha-separado-de-dios\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfPueden sobrevivir nuestros \u201chuesos secos\u201d despu\u00e9s de que el pecado nos ha separado de Dios?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-23577","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/23577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=23577"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/23577\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=23577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=23577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=23577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}