{"id":24032,"date":"2022-07-29T18:02:12","date_gmt":"2022-07-29T23:02:12","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/que-quiso-decir-jesus-con-una-casa-dividida-no-puede-sostenerse\/"},"modified":"2022-07-29T18:02:12","modified_gmt":"2022-07-29T23:02:12","slug":"que-quiso-decir-jesus-con-una-casa-dividida-no-puede-sostenerse","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/que-quiso-decir-jesus-con-una-casa-dividida-no-puede-sostenerse\/","title":{"rendered":"\u00bfQu\u00e9 quiso decir Jes\u00fas con \u201cUna casa dividida no puede sostenerse\u201d?"},"content":{"rendered":"<blockquote>\n<p>\u00abJes\u00fas conoc\u00eda los pensamientos de ellos y les dijo: &#8216;Todo reino dividido contra s\u00ed mismo ser\u00e1 destruido, y toda ciudad o casa dividida contra s\u00ed misma no permanecer\u00e1.'\u00bb &#8211; Mateo 12:25<\/p>\n<p>\u00abSi una casa est\u00e1 dividida contra s\u00ed misma, esa casa no podr\u00e1 permanecer\u00bb. &#8211; Marcos 3:25<\/p>\n<\/blockquote>\n<p>\u00abUna casa dividida no puede subsistir\u00bb recuerda a Abraham Lincoln y su famoso discurso de 1858. Pero, \u00bfentendemos qui\u00e9n lo dijo primero, por qu\u00e9 lo dijo y \u00bfCon qu\u00e9 prop\u00f3sito? Encontramos la frase \u00abuna casa dividida no puede subsistir\u00bb en Mateo 12:25 y Marcos 3:25. Jes\u00fas lo us\u00f3 en defensa de su autoridad contra las acusaciones hechas por los fariseos.<\/p>\n<h2>\u00bfQu\u00e9 significa \u00abuna casa dividida\u00bb en la Biblia?<\/h2>\n<p>Jes\u00fas pretend\u00eda que sus ense\u00f1anzas probaran que \u00e9l era el Mes\u00edas y el Hijo de Dios. Tambi\u00e9n quer\u00eda preparar a sus oyentes para aceptar el reino de Dios, que \u00e9l establecer\u00eda. Por \u00faltimo, se propuso persuadir a los jud\u00edos de que Dios aceptar\u00eda a los gentiles en su reino. A medida que los oyentes de Jes\u00fas prestaban m\u00e1s atenci\u00f3n a sus ense\u00f1anzas, resist\u00edan su mensaje.<\/p>\n<p>Debido a esta resistencia, Jes\u00fas se retiraba a lugares privados para ense\u00f1ar y ministrar. Muchas personas lo segu\u00edan a esos lugares y le tra\u00edan a los enfermos para que los curara. Debido a su compasi\u00f3n por los heridos, Jes\u00fas los san\u00f3 y repar\u00f3 sus vidas rotas. Uno de esos hombres, que estaba pose\u00eddo por un demonio, era ciego y mudo. Jes\u00fas lo san\u00f3 para que pudiera hablar y ver. Esto asombr\u00f3 a la gente, y se preguntaron entre ellos si este podr\u00eda ser el Mes\u00edas.<\/p>\n<p>En la construcci\u00f3n original de la oraci\u00f3n griega, asombrados significa \u00abfuera de s\u00ed mismos\u00bb. Tambi\u00e9n indica un movimiento progresivo ya que no pod\u00edan dejar de hablar de ello. Me pregunto si la gente trat\u00f3 de llevar la situaci\u00f3n m\u00e1s imposible a Jes\u00fas. Entonces Jes\u00fas hizo lo \u00abimposible\u00bb y liber\u00f3 a este hombre, y su asombro se extendi\u00f3 como la p\u00f3lvora. El asombro comenz\u00f3 como un susurro. Luego rod\u00f3 por el mercado como el zumbido de un motor diesel. \u00ab\u00bfEscuchaste? Jes\u00fas san\u00f3 al hombre pose\u00eddo por un demonio. \u00a1\u00c9l puede hablar y ver! \u00bfPodr\u00eda ser este el Mes\u00edas?\u00bb La historia y la pregunta pasaron de persona a persona como la versi\u00f3n antigua de una publicaci\u00f3n viral en las redes sociales. Y luego lleg\u00f3 a o\u00eddos de los fariseos.<\/p>\n<p>Anteriormente en Mateo 12, Jes\u00fas revel\u00f3 su autoridad al sanar la mano seca de un hombre en s\u00e1bado. Este acto de compasi\u00f3n en s\u00e1bado incit\u00f3 a los fariseos a tramar maneras de matar a Jes\u00fas. Ahora descubrieron que Jes\u00fas liber\u00f3 a alguien de su posesi\u00f3n demon\u00edaca, y la gente pregunta si \u00e9l es el Mes\u00edas. Al enterarse de este nuevo milagro, acusaron a Jes\u00fas de estar aliado con Satan\u00e1s.<\/p>\n<h2>\u00bfA qu\u00e9 respondi\u00f3 esto Jes\u00fas?<\/h2>\n<p>Los fariseos estaban en medio de un plan para matar Jes\u00fas. Esta \u00faltima curaci\u00f3n plante\u00f3 el momento ideal para lanzar una acusaci\u00f3n en su contra. Si pudieran cuestionar su identidad y afirmar que estaba trabajando con Satan\u00e1s, podr\u00edan acusarlo de un delito. El delito que esperaban imputarle era la hechicer\u00eda, que se castigaba con la muerte. Dijeron que Jes\u00fas estaba pose\u00eddo por un demonio y que su poder proven\u00eda de una alianza con Satan\u00e1s. Los fariseos deseaban desacreditar la identidad de Jes\u00fas y atribuir su poder a Satan\u00e1s. Jes\u00fas llam\u00f3 a sus acusadores y respondi\u00f3 a sus il\u00f3gicas acusaciones con tres argumentos. Uno, que Satan\u00e1s estar\u00eda obrando contra s\u00ed mismo. Dos, que sus propios exorcistas jud\u00edos afirmaron usar el poder de Dios. Tres, que Jes\u00fas pudo entrar en el reino de Satan\u00e1s y marcharse con el bot\u00edn de la victoria.<\/p>\n<p>Primero, Jes\u00fas revela su conocimiento de dos reinos en guerra: el reino de las tinieblas y el reino de Dios. Si Jes\u00fas de hecho estaba pose\u00eddo por Satan\u00e1s, pero liber\u00f3 a este hombre, entonces Satan\u00e1s frustra su propio prop\u00f3sito. Un reino que trabaja contra s\u00ed mismo fracasa. Esto fue cuando Jes\u00fas dijo, \u00abuna casa dividida contra s\u00ed misma no puede permanecer\u00bb.<\/p>\n<p>En segundo lugar, los fariseos afirmaban que sus propios exorcistas echaban fuera demonios por el Esp\u00edritu de Dios. Al cuestionar la autoridad de Jes\u00fas, negaron el reino de Dios obrando en sus vidas. Jes\u00fas no lo dice, pero nuevamente implica que \u00abuna casa dividida contra s\u00ed misma no puede permanecer en pie\u00bb. <\/p>\n<p>Tercero, Jes\u00fas cuenta la historia del hombre fuerte. Esta par\u00e1bola muestra la capacidad de Jes\u00fas para entrar en la casa del hombre fuerte y marcharse con el bot\u00edn de la victoria. Jes\u00fas ata al hombre fuerte y lo roba liberando a sus v\u00edctimas esclavizadas. Una vez m\u00e1s, Jes\u00fas muestra que \u00abuna casa dividida no puede permanecer en pie\u00bb.<\/p>\n<p>Liberar a alguien de la posesi\u00f3n demon\u00edaca socava el reino de Satan\u00e1s. Su reino forma un frente unido para esclavizar a la gente al pecado, la enfermedad, la posesi\u00f3n y la muerte. M\u00e1s bien, Jes\u00fas invadi\u00f3 el reino del diablo y lo incapacit\u00f3. Jes\u00fas se llev\u00f3 a uno de los cautivos de Satan\u00e1s al liberarlo.<\/p>\n<h2>\u00bfQu\u00e9 lecci\u00f3n estaba tratando de ense\u00f1ar Jes\u00fas?<\/h2>\n<p>El poder de Jes\u00fas era innegable cuando liber\u00f3 al hombre pose\u00eddo por el demonio. A trav\u00e9s de este milagro, Jes\u00fas tambi\u00e9n revel\u00f3 el conflicto entre los dos reinos. El reino de Dios ocupa una posici\u00f3n importante en la ense\u00f1anza y la misi\u00f3n de Jes\u00fas. Casi veinte de sus par\u00e1bolas se relacionan con este concepto. \u00c9l trae el reino de Dios a la gente, une sus corazones al suyo y edifica su iglesia sobre \u00e9l, el fundamento firme.<\/p>\n<p>Las caracter\u00edsticas asociadas con el reino de Dios son internas y espirituales. Pero el pueblo quer\u00eda un reino basado en la identidad nacional y el poder pol\u00edtico. Los milagros de Jes\u00fas, incluida la expulsi\u00f3n de demonios, transmitieron la realidad y la autenticidad del reino de Dios. Era innegable.<\/p>\n<p>Jes\u00fas ense\u00f1\u00f3 que el reino de Dios es tanto presente como futuro. Est\u00e1 presente en la persona de Jesucristo y en lo que hizo a trav\u00e9s de su muerte y resurrecci\u00f3n. Est\u00e1 dentro de nosotros cuando experimentamos crecimiento espiritual en medio de un mundo ca\u00eddo. Es en el futuro que Cristo vendr\u00e1 nuevamente en su poder y gloria para finalizar la destrucci\u00f3n del diablo. Jes\u00fas estaba tratando de ense\u00f1ar la importancia de la unidad en \u00e9l. Estar con \u00e9l, reunirse con \u00e9l y contarles a otros acerca de \u00e9l. No dispersarnos ni oponernos a \u00e9l. El reino de Dios ya es y a\u00fan no, y la iglesia puede ayudar o entorpecer la obra del reino de los cielos.<\/p>\n<h2>C\u00f3mo la unidad construye una casa<\/h2>\n<p>Cuando Jes\u00fas dijo, \u00abun casa dividida no puede sostenerse\u00bb, quiso decir que una casa que se opone a s\u00ed misma no tiene poder. Dado que el pecado, la enfermedad y la esclavitud a\u00fan prevalecen en nuestro mundo, sabemos que el poder de Satan\u00e1s no ha terminado. Jes\u00fas se opone al reino de la muerte y la oscuridad al traer la libertad a los cautivos. \u00c9l tiene la m\u00e1xima autoridad, y cuando regrese, vencer\u00e1 a Satan\u00e1s para siempre.<\/p>\n<p>Para alcanzar la unidad en el cuerpo de Cristo, debemos edificar nuestra vida espiritual sobre la persona de Jesucristo. Tenemos la tarea de crecer hacia la madurez con Cristo como nuestro l\u00edder y Se\u00f1or. Nos mantenemos leales a sus ense\u00f1anzas y seguimos su ejemplo en la vida. Elegimos la constancia y la fidelidad, el gozo y la esperanza.<\/p>\n<p>Jes\u00fas vino a la tierra para abrirnos un camino para conocer el coraz\u00f3n del Padre. El prop\u00f3sito completo de Jes\u00fas significa que un d\u00eda volver\u00e1 en poder y gloria. \u00c9l separar\u00e1 a los malvados de los justos. \u00c9l cumplir\u00e1 la promesa del banquete de bodas de Mateo 22:1-2 y Lucas 22:29-30. Jes\u00fas resucitar\u00e1 a los muertos, instituir\u00e1 el juicio final y traer\u00e1 la era venidera. Este evento entre Jes\u00fas y los fariseos da como resultado que Jes\u00fas haga un llamado a la acci\u00f3n. Una casa dividida contra s\u00ed misma no permanecer\u00e1, y el que no est\u00e1 con Jes\u00fas est\u00e1 contra \u00e9l. El que con \u00e9l no recoge, desparrama. Jes\u00fas, lleno y empoderado con el Esp\u00edritu Santo, libera a la humanidad para vivir por \u00e9l, amarlo y estar en unidad con \u00e9l.<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abJes\u00fas conoc\u00eda los pensamientos de ellos y les dijo: &#8216;Todo reino dividido contra s\u00ed mismo ser\u00e1 destruido, y toda ciudad o casa dividida contra s\u00ed misma no permanecer\u00e1.&#8217;\u00bb &#8211; Mateo 12:25 \u00abSi una casa est\u00e1 dividida contra s\u00ed misma, esa casa no podr\u00e1 permanecer\u00bb. &#8211; Marcos 3:25 \u00abUna casa dividida no puede subsistir\u00bb recuerda a &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/que-quiso-decir-jesus-con-una-casa-dividida-no-puede-sostenerse\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfQu\u00e9 quiso decir Jes\u00fas con \u201cUna casa dividida no puede sostenerse\u201d?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24032","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/24032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=24032"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/24032\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=24032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=24032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=24032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}