{"id":24105,"date":"2022-07-29T18:04:37","date_gmt":"2022-07-29T23:04:37","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/por-que-debemos-recordar-que-todos-han-pecado-y-estan-destituidos-de-la-gloria-de-dios\/"},"modified":"2022-07-29T18:04:37","modified_gmt":"2022-07-29T23:04:37","slug":"por-que-debemos-recordar-que-todos-han-pecado-y-estan-destituidos-de-la-gloria-de-dios","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/por-que-debemos-recordar-que-todos-han-pecado-y-estan-destituidos-de-la-gloria-de-dios\/","title":{"rendered":"Por qu\u00e9 debemos recordar que todos han pecado y est\u00e1n destituidos de la gloria de Dios"},"content":{"rendered":"<h2 style=\"text-align: center\">\u201cPor cuanto todos pecaron y est\u00e1n destituidos de la gloria de Dios\u201d. (Romanos 3:23)<\/h2>\n<p>Este vers\u00edculo frecuentemente citado es cortes\u00eda del ap\u00f3stol Pablo en sus cartas a la iglesia romana. La declaraci\u00f3n hace una gran declaraci\u00f3n sobre toda la humanidad, una declaraci\u00f3n que ha sido cierta desde Ad\u00e1n y Eva en el jard\u00edn de Ed\u00e9n. Cada persona en cada civilizaci\u00f3n en la Tierra ha pecado. Y con el pecado ha venido varias consecuencias: separaci\u00f3n de Dios y una capacidad restringida para glorificar Su nombre.<\/p>\n<p>Hoy, cuando se evoca este vers\u00edculo dentro de los sermones, el mensaje tiene la intenci\u00f3n de comunicar a los creyentes que nadie de nosotros es perfecto. Todos tienen pecados que enfrentan, han enfrentado y otros con los que lidiar\u00e1n en el futuro. Esto significa que las personas son pecadoras desde la ni\u00f1ez hasta el punto de la muerte. Ad\u00e1n y Eva se quedaron cortos en su capacidad para glorificar a Dios. Los creyentes de hoy tienen sus propias luchas, que a veces les impiden glorificar a Dios. Las palabras de Pablo luego hacen eco de una verdad que es tan precisa como eterna.<\/p>\n<p>Aunque sea precisa, \u00bfpor qu\u00e9 Pablo sinti\u00f3 la necesidad de mencionar esto a la iglesia, y por qu\u00e9 se les sigue diciendo esto a los creyentes hoy en d\u00eda? Seguramente los cristianos somos conscientes del pecado, por eso rezamos pidiendo perd\u00f3n. Para comprender la importancia continua de este vers\u00edculo, primero debemos examinar el contexto en el que aparecen estas palabras por primera vez.<\/p>\n<h2><strong>Comprender el contexto de Romanos 3:23 y Por cuanto todos pecaron y caen Lejos de la gloria de Dios<\/strong><\/h2>\n<p>Las dos ideas clave m\u00e1s notables en Romanos 3:23 son los conceptos del pecado y la gloria de Dios. Antes de que Pablo escriba esa l\u00ednea espec\u00edfica, comienza el tercer cap\u00edtulo del Libro de Romanos destacando una cierta verdad acerca de Dios. Pablo nota que Dios es \u201cjusto\u201d, mientras que la humanidad tiene una tendencia a ser \u201cinjusta\u201d (Romanos 3:3). A pesar de la diferencia, Dios sigue siendo quien es y esa cualidad justa nunca cambia, sin importar c\u00f3mo nos comportemos. El ap\u00f3stol contin\u00faa afirmando que incluso cuando Dios est\u00e1 tratando con el juicio, lo hace con justicia (Romanos 3:5-6).<\/p>\n<p>Pablo luego indica que tanto los jud\u00edos como los griegos han pecado. \u00c9l llega a esta conclusi\u00f3n porque todos est\u00e1n conscientes &#8211; esa es la decisi\u00f3n correcta a tomar &#8211; a trav\u00e9s de la ley. Sin embargo, todos de alguna manera y en alg\u00fan momento han fallado en seguir la ley, someti\u00e9ndose al juicio de Dios (Romanos 3:19-20). La condenaci\u00f3n que la gente pudo haber enfrentado bajo la ley anterior es anulada debido a que la justicia de Dios ahora se revela a trav\u00e9s de Jesucristo. Pablo afirma que incluso con el sacrificio redentor de Jes\u00fas, la gente seguir\u00eda siendo injusta sin la gracia de Dios.<\/p>\n<blockquote>\n<p>\u201cPor cuanto todos pecaron y est\u00e1n destituidos de la gloria de Dios; son justificados gratuitamente por su gracia mediante la redenci\u00f3n que es en Cristo Jes\u00fas.\u201d (Romanos 3:23-24)<\/p>\n<\/blockquote>\n<p>Podemos entender la palabra gracia como un favor inmerecido. Durante el resto del pasaje, Pablo argumenta que las acciones de una persona no le otorgan el favor de Dios. La redenci\u00f3n de Jes\u00fas y la fe de una persona (dada en gracia) en esa redenci\u00f3n logran eso. Adem\u00e1s, Pablo parece estar enfatizando el punto de que ning\u00fan creyente est\u00e1 por encima de otro. Una vez m\u00e1s, la amonestaci\u00f3n de Pablo aqu\u00ed tiene sentido debido a los conceptos de pecado y de glorificar a Dios. Podemos verificar las afirmaciones de Pablo sobre el pecado con las palabras pronunciadas por Santiago.<\/p>\n<blockquote>\n<p>\u201cAs\u00ed que es pecado conocer el bien y no hacerlo\u201d. (Santiago 4:17)<\/p>\n<\/blockquote>\n<p>Esto es cierto para todo creyente. Todo el mundo ha sabido en un momento u otro cu\u00e1l era la elecci\u00f3n correcta, pero eligi\u00f3 lo contrario. Cuando pensamos en la gloria de Dios, podemos considerar Su justicia. La palabra gloria significa \u201cmuy grande alabanza, honor o distinci\u00f3n otorgada de com\u00fan acuerdo\u201d.<\/p>\n<p>Con el pecado, las personas estropean su capacidad de reflejar la imagen de Dios dentro de s\u00ed mismas. As\u00ed es como nos quedamos cortos de la gloria de Dios. La raz\u00f3n por la que Pablo entendi\u00f3 los efectos del pecado, y por qu\u00e9 nosotros tambi\u00e9n podemos, es c\u00f3mo el pecado nos gu\u00eda en nuestra relaci\u00f3n con Dios. Al igual que Ad\u00e1n y Eva, el pecado lleva a una separaci\u00f3n de Dios (G\u00e9nesis 3:23-24). Sin embargo, Dios no nos abandona por Su justicia. Tampoco hizo eso con Ad\u00e1n y Eva, pero la consecuencia es sentirse f\u00edsica, emocional y espiritualmente distante de \u00c9l, al menos por un tiempo.<\/p>\n<p>Cuanto m\u00e1s conscientes somos del pecado en nosotros mismos, m\u00e1s podemos trabajar para cambiar nuestros caminos y trabajar para glorificar a Dios volvi\u00e9ndonos a Dios en fe y oraci\u00f3n. Nuestra fe en Cristo nos justifica ante Dios.&nbsp;<\/p>\n<h2><strong>\u00bfPor qu\u00e9 necesitamos que se nos recuerde que &#8216;por cuanto todos pecaron y est\u00e1n destituidos de la gloria de Dios&#8217;?<\/strong><\/h2>\n<p>Pablo eligi\u00f3 recordar a los cristianos en Roma esta verdad b\u00edblica. \u00bfPor qu\u00e9? La respuesta se encuentra en la misma raz\u00f3n por la cual los cristianos de hoy necesitan que se les recuerde. Todos han pecado, por lo tanto, ning\u00fan creyente es mejor que otro. Importante en nuestra comprensi\u00f3n de este vers\u00edculo de Pablo, tenemos que entender las prioridades para un cristiano. Recibimos los dos grandes mandamientos de Jes\u00fas en el Libro de Mateo (Mateo 22:36-40). Si amar a los dem\u00e1s como nos amamos a nosotros mismos es el segundo gran mandamiento, entonces no podemos cumplirlo poni\u00e9ndonos por encima de los dem\u00e1s. Tenemos que contarlos como iguales a nosotros.<\/p>\n<p>Reconocer que todos son pecadores significa que todos tienen sus propias luchas \u00fanicas, y nadie est\u00e1 libre de culpa. Tal idea promueve la humildad e incluso la unidad entre los cristianos. Si todos tienen dificultades, entonces las personas pueden unirse como comunidad para apoyarse mutuamente. Adem\u00e1s, si todos luchamos, entonces cada uno de nosotros tiene una necesidad de Dios. Las palabras de Pablo tambi\u00e9n indican otra verdad. Hab\u00eda una persona que era perfecta, pero esa persona era m\u00e1s grande que el mero hombre, \u00c9l era Jes\u00fas el Cristo, completamente hombre y completamente Dios. Si pensamos que hemos vivido una vida sin pecado, eso nos pondr\u00eda al mismo nivel de Jes\u00fas, lo cual contradir\u00eda las Escrituras. Reconocer que pecamos nos da espacio para buscar a Jes\u00fas y esforzarnos por ser m\u00e1s como \u00c9l.<\/p>\n<p>Las palabras de Pablo son un recordatorio siempre importante de la gracia, un favor inmerecido, de Dios, que nos informa que nuestras acciones no est\u00e1n destinados a ser transaccionales. No podemos hacer cosas y luego esperar que Dios nos d\u00e9 lo que queremos. Tal idea nos hace parecer merecedores de la bendici\u00f3n de Dios, pero Su favor es inmerecido. Nuestra relaci\u00f3n con Dios no es igual en el sentido de que Dios nos da tanto como nosotros le damos. Seg\u00fan Pablo, eso es una bendici\u00f3n de nuestra parte porque nuestra injusticia nunca impide que Dios sea justo. Por lo tanto, \u00c9l puede bendecirnos incluso en aquellos momentos en los que sentimos que no lo merecemos.<\/p>\n<p>Sin embargo, har\u00edamos bien en servir a Dios, cosechando los beneficios de tener fe, pero sin esperar m\u00e1s de lo que Dios decide dar.<\/p>\n<p>No hay obras que podamos hacer para ganar una transacci\u00f3n salvadora con Dios (Romanos 3:27). \u00c9l no nos necesita. Lo necesitamos. Sin que las obras nos puedan justificar ante Dios (por nuestra naturaleza pecaminosa), nuestra fe es la que nos permite tener una relaci\u00f3n y desde esa fe, podemos realizar obras en amor y obediencia. Ad\u00e1n y Eva tuvieron una relaci\u00f3n con Dios que dur\u00f3 no por sus acciones, sino por la acci\u00f3n de Dios y Su don de fe. Sus acciones llevaron a la separaci\u00f3n de \u00c9l, pero la fe mantuvo viva su conexi\u00f3n con Dios. Nuestra relaci\u00f3n con Dios es diferente porque tenemos a Jes\u00fas, pero esto es lo que significa ser justificados por la gracia. La fe nos mantiene en una relaci\u00f3n con Dios.<\/p>\n<h2><strong>\u00bfC\u00f3mo debemos vivir sabiendo que la justicia de Cristo nos ha sido dada?<\/strong><\/h2>\n<p>Saber que la justicia de Cristo nos ha sido dada que se nos ha dado, hay tres cosas en las que podemos trabajar diariamente para fortalecer a\u00fan m\u00e1s nuestra fe.<\/p>\n<p><strong>Leer las Escrituras<\/strong><\/p>\n<blockquote>\n<p>\u201cTodas las Escrituras es inspirado por Dios y \u00fatil para ense\u00f1ar, para reprender, para corregir, para instruir en justicia.\u201d (2 Timoteo 3:16)<\/p>\n<\/blockquote>\n<p>Leer la Biblia diariamente nos ayudar\u00e1 a edificar nuestra fe fortaleciendo nuestra conciencia de la ense\u00f1anza de Dios. Leer la Biblia nos hace conscientes de vers\u00edculos como Romanos 3:23. Cuanto m\u00e1s comprendamos las expectativas de Dios para Sus seguidores, m\u00e1s podremos trabajar para vivir la vida que \u00c9l desea.<\/p>\n<p><strong>Estar en comunidad<\/strong><\/p>\n<blockquote>\n<p>\u201c El hierro afila al hierro, y una persona afila a otra\u201d. (Proverbios 27:17)<\/p>\n<\/blockquote>\n<p>Donde fallamos en seguir las Escrituras y posiblemente caemos en pecado, otros pueden servir amonestando nuestro comportamiento. A veces tomamos malas decisiones basadas en lo que no sabemos. Otras veces nos falta la motivaci\u00f3n para hacer lo correcto. Tener otros creyentes que entiendan la palabra de Dios ayudar\u00e1 a garantizar que tomemos mejores decisiones con m\u00e1s frecuencia.<\/p>\n<p><strong>Buscar a Dios continuamente<\/strong><\/p>\n<blockquote>\n<p>\u201cSiempre dejo que el Se\u00f1or gu\u00edame. Porque \u00e9l est\u00e1 a mi diestra, no ser\u00e9 conmovido\u201d. (Salmo 16:8)<\/p>\n<\/blockquote>\n<p>Buscar a Dios no promete una vida libre de problemas. La promesa es, en cambio, la capacidad de superar ese problema, ya sea en esta vida o en la siguiente. Dios cuida de sus hijos. Sin embargo, para que podamos buscar verdaderamente a Dios, tenemos que buscar una relaci\u00f3n con \u00c9l a\u00fan m\u00e1s intencionalmente de lo que lo hacemos con aquellos en nuestra vida diaria.<\/p>\n<p>Si el efecto natural del pecado es alguna forma de separaci\u00f3n de Dios, entonces hacemos todo lo posible para acercarnos eliminando el comportamiento pecaminoso de nuestras vidas con la ayuda de Dios. Con una comprensi\u00f3n del mensaje de Pablo a la iglesia en Roma, podemos humillarnos ante Dios y ante los dem\u00e1s mientras cada uno de nosotros trabaja para llegar a ser m\u00e1s como Cristo. Cuanto m\u00e1s podamos progresar en cada uno de estos tres pasos, m\u00e1s nos acercaremos a Dios y nos alejaremos del pecado.<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cPor cuanto todos pecaron y est\u00e1n destituidos de la gloria de Dios\u201d. (Romanos 3:23) Este vers\u00edculo frecuentemente citado es cortes\u00eda del ap\u00f3stol Pablo en sus cartas a la iglesia romana. La declaraci\u00f3n hace una gran declaraci\u00f3n sobre toda la humanidad, una declaraci\u00f3n que ha sido cierta desde Ad\u00e1n y Eva en el jard\u00edn de Ed\u00e9n. &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/por-que-debemos-recordar-que-todos-han-pecado-y-estan-destituidos-de-la-gloria-de-dios\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abPor qu\u00e9 debemos recordar que todos han pecado y est\u00e1n destituidos de la gloria de Dios\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24105","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/24105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=24105"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/24105\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=24105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=24105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=24105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}