{"id":24115,"date":"2022-07-29T18:04:56","date_gmt":"2022-07-29T23:04:56","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/siete-pasajes-biblicos-de-los-ultimos-dias-que-rara-vez-escuchara-predicar-a-los-pastores\/"},"modified":"2022-07-29T18:04:56","modified_gmt":"2022-07-29T23:04:56","slug":"siete-pasajes-biblicos-de-los-ultimos-dias-que-rara-vez-escuchara-predicar-a-los-pastores","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/siete-pasajes-biblicos-de-los-ultimos-dias-que-rara-vez-escuchara-predicar-a-los-pastores\/","title":{"rendered":"Siete pasajes b\u00edblicos de los &#8216;\u00faltimos d\u00edas&#8217; que rara vez escuchar\u00e1 predicar a los pastores"},"content":{"rendered":"<p>\u00bfCu\u00e1ndo fue la \u00faltima vez que escuch\u00f3 un serm\u00f3n de los \u00ab\u00faltimos d\u00edas\u00bb del Antiguo Testamento?<\/p>\n<p>Cuando la mayor\u00eda de los pastores predican un serm\u00f3n sobre el fin de los tiempos suelen comenzar con el Discurso de los Olivos (Mateo 24, Marcos 13 y Lucas 21) o el Libro del Apocalipsis. Durante a\u00f1os, el enfoque en las discusiones sobre los \u00faltimos tiempos ha permanecido en el Nuevo Testamento. Desafortunadamente, eso da como resultado que nuestros maestros solo nos den el final de la historia. Al leer una historia, tiene sentido comenzar por el principio, en lugar de por el final, y tratar de descifrar la historia a partir de ah\u00ed. Sin embargo, el estudio de los \u00ab\u00faltimos d\u00edas\u00bb en la mayor\u00eda de las iglesias de hoy nos tiene haciendo esto mismo. Yo tambi\u00e9n hice eso durante a\u00f1os, hasta que finalmente decid\u00ed comenzar desde el principio del libro.<\/p>\n<p>Aqu\u00ed hay siete pasajes del Antiguo Testamento que he encontrado en mis estudios que son cruciales para entender el \u00ab\u00faltimos d\u00edas\u00bb sobre los que rara vez escuchar\u00e1 a los pastores predicar en las iglesias de hoy:<\/p>\n<h2>1. La predicci\u00f3n de Jacob de los \u00faltimos d\u00edas<\/h2>\n<p>\u00bfCreer\u00edas que la primera menci\u00f3n de los \u00ab\u00faltimos d\u00edas\u00bb est\u00e1 en<strong>&nbsp;<\/strong>G\u00e9nesis 49? &nbsp;\u00abY Jacob llam\u00f3 a sus hijos y les dijo: \u00abRe\u00fananse, y les contar\u00e9 lo que les suceder\u00e1 en los <em>\u00faltimos d\u00edas<\/em> (NKJV)\u00bb. &nbsp;Ir\u00f3nicamente, el primer &nbsp;pasaje de la Biblia que habla de <em>los \u00faltimos d\u00edas<\/em>&nbsp; est\u00e1 en el <em>primer&nbsp;<\/em> libro de la Biblia y no en el \u00faltimo. Este pasaje habla de los \u00faltimos d\u00edas de las doce tribus de Israel.<\/p>\n<h2>2. Advertencia de Mois\u00e9s a los israelitas<\/h2>\n<p>En Deuteronomio 31:29, Mois\u00e9s les dice a los israelitas: \u00abPorque yo s\u00e9 que despu\u00e9s de mi muerte os corromper\u00e9is y os apartar\u00e9is del camino que os he mandado, y el mal os acontecer\u00e1 en los <em>postreros d\u00edas<\/em>, porque har\u00e9is lo malo ante los ojos de Jehov\u00e1, provoc\u00e1ndole a ira con la obra de vuestras manos\u201d (NASB). Este vers\u00edculo est\u00e1 en el contexto de Deuteronomio 28-32 y Lev\u00edtico 26. Dios est\u00e1 estableciendo el Pacto con Su pueblo. Dios promete a Su pueblo bendiciones venideras por la obediencia y maldiciones por la desobediencia. Estudie sus referencias cruzadas y encontrar\u00e1 muchas conexiones fascinantes con el Nuevo Testamento, particularmente &nbsp;Romanos 9-11 y &nbsp;el libro de Apocalipsis. A partir de este pasaje, comenzar\u00e1 a ver que los \u00faltimos d\u00edas de los que se habla en Deuteronomio 31:29 est\u00e1n hablando de &nbsp;los \u00faltimos d\u00edas del Antiguo Pacto, no los \u00faltimos d\u00edas de la tierra.<\/p>\n<h2><strong>3. La predicci\u00f3n de Jerem\u00edas de los \u00faltimos d\u00edas<\/strong><\/h2>\n<p>Jerem\u00edas 30:24<strong>&nbsp;<\/strong>dice: El furor de la ira de Jehov\u00e1 no se apartar\u00e1, hasta que haya cumplido y hasta que haya cumplido el prop\u00f3sito de su coraz\u00f3n; <em>en los postreros d\u00edas<\/em> entender\u00e9is esto (NASB).\u00bb Jerem\u00edas 30:24 habla del juicio que vendr\u00e1 sobre Su pueblo, y &nbsp;es tambi\u00e9n el contexto de Jerem\u00edas 31. Jerem\u00edas 31 contiene varias profec\u00edas cumplidas en &nbsp;la primera venida de Cristo. Por ejemplo, Jerem\u00edas 31:15 es una profec\u00eda cumplida en Mateo 2:16-18. Jes\u00fas nace bajo la ley (G\u00e1latas 4:4), al final del Antiguo Pacto. El Antiguo El pacto est\u00e1 terminando con el nacimiento de Cristo, y el Nuevo Pacto est\u00e1 cerca con el comienzo de Su ministerio. Escribiendo a los jud\u00edos, el autor de &nbsp;Hebreos dice en el cap\u00edtulo 1:1-2: &nbsp; hace a los padres en los profetas en muchas partes y de muchas maneras <em>en estos postreros d\u00edas<\/em> nos ha hablado por el Hijo, a quien constituy\u00f3 heredero de todo, y por quien asimismo hizo el mundo\u00bb. Las cosas \u00abhabladas en otro tiempo a los padres y profetas\u201d son los pasajes que estamos delineando aqu\u00ed. Si estudias estos vers\u00edculos cuidadosamente, en contra del pensamiento actual, los \u00faltimos d los d\u00edas de los jud\u00edos y su pacto estaban sobre ellos. Estas referencias comienzan a alinearse con los \u00faltimos d\u00edas del Antiguo Pacto, no con los \u00faltimos d\u00edas del mundo.<\/p>\n<h2>4. Predicci\u00f3n del Nuevo Pacto que Vendr\u00eda<strong>&nbsp;<\/strong><\/h2>\n<p>Otro pasaje en el contexto de Jerem\u00edas 30:24 es Jerem\u00edas 31:31-34 &#8212; una profec\u00eda que predice que el Nuevo Pacto vendr\u00eda al final del Antiguo Pacto. &nbsp;El escritor del libro de Hebreos &nbsp;verifica esto en Hebreos cap\u00edtulo 8. El Nuevo Pacto para Su pueblo profetizado en Jerem\u00edas 31 se cumple en el Siglo I, y el Antiguo Pacto se vuelve obsoleto en Hebreos 8:13. Una vez m\u00e1s, vemos que los \u00faltimos d\u00edas del Antiguo Pacto estaban sobre ellos en el primer siglo. Todo el contexto de Hebreos 8 se establece nuevamente en el contexto de Hebreos 1:1-2.&nbsp;<\/p>\n<h2>5. Jes\u00fas naci\u00f3 en los &#8216;\u00faltimos d\u00edas&#8217;<\/h2>\n<p>Miqueas 4 muestra que Jes\u00fas naci\u00f3 en los \u00faltimos d\u00edas del Antiguo Pacto: \u00abY suceder\u00e1 <em>en los \u00faltimos d\u00edas<\/em>, &nbsp;que el monte de la casa de Jehov\u00e1 ser\u00e1 establecido como cabeza de los montes, y se alzar\u00e1 sobre los collados, y los pueblos afluir\u00e1n a \u00e9l. En el mismo contexto, Miqueas 5:2 dice: \u201cPero t\u00fa, Bel\u00e9n Efrata, peque\u00f1a para estar entre las familias de Jud\u00e1, de ti me saldr\u00e1 el que ser\u00e1 Se\u00f1or en Israel. desde los d\u00edas de la eternidad.\u201d<\/p>\n<p>Esta profec\u00eda se cumple en los \u00faltimos d\u00edas de la Antigua Alianza seg\u00fan Mateo 2:1-6: \u201cDespu\u00e9s que naci\u00f3 Jes\u00fas en Bel\u00e9n de Judea en los d\u00edas del rey Herodes, llegaron del oriente a Jerusal\u00e9n unos magos, diciendo: &nbsp;\u00bfD\u00f3nde est\u00e1 el Rey de los jud\u00edos que ha nacido? Porque su estrella hemos visto en el oriente, y venimos a adorarle. Cuando el rey Herodes oy\u00f3 esto, se turb\u00f3, y toda Jerusal\u00e9n con \u00e9l. Y habiendo reunido a todos los principales sacerdotes y escribas del pueblo, les pregunt\u00f3 d\u00f3nde hab\u00eda de nacer el Cristo. Entonces le dijeron: En Bel\u00e9n de Judea, porque as\u00ed est\u00e1 escrito por el profeta: &#8216;Pero t\u00fa, Bel\u00e9n, en la tierra de Jud\u00e1, no eres la m\u00e1s peque\u00f1a entre los pr\u00edncipes de Jud\u00e1; porque de ti saldr\u00e1 un Gobernante que pastorear\u00e1 a mi pueblo Israel.&#8217; \u00ab<\/p>\n<p><em><strong>(Referencias cruzadas:&nbsp;<\/strong><\/em>Deuteronomio 31:29<em>:&nbsp;<\/em>Jueces 2:19<em>) <\/em><\/p>\n<h2><strong>6.&nbsp;<\/strong><strong>La predicci\u00f3n de juicio de Isa\u00edas sobre el Israel del Antiguo Pacto en los \u00faltimos d\u00edas<\/strong><\/h2>\n<p>Vemos esto en Jerem\u00edas 30:24: Jerem\u00edas 4:8, Jerem\u00edas 30:24 y Jerem\u00edas 23:20. En Isa\u00edas 2:1-2, vemos casi palabra por palabra las palabras de Miqueas 4:1, sobre los \u00faltimos d\u00edas del pacto: \u00abLa palabra que vio Isa\u00edas hijo de Amoz acerca de Jud\u00e1 y de Jerusal\u00e9n. Acontecer\u00e1 ahora que <em>En los postreros d\u00edas &nbsp;<\/em>El monte de la casa de Jehov\u00e1 ser\u00e1 establecido como jefe de los montes, y ser\u00e1 elevado sobre los collados, y todas las naciones correr\u00e1n hacia \u00e9l\u201d&lt;\/p <\/p>\n<p>Este segmento de las Escrituras est\u00e1 lleno de descripciones de los \u00faltimos d\u00edas que se pueden rastrear a trav\u00e9s del Nuevo Testamento hasta el libro de Apocalipsis. En el mismo contexto de Isa\u00edas 2 est\u00e1 la par\u00e1bola de la vi\u00f1a (Isa\u00edas 5:1-7) \u2013 \u00a1la Vi\u00f1a es la casa de Israel! (vs. 7). \u00a1Es una vi\u00f1a que Dios dijo que produc\u00eda uvas sin valor! Esta misma par\u00e1bola cita Jes\u00fas en Mateo 21:33-46. &nbsp;Vers\u00edculos 40-45 Jes\u00fas describe lo que vendr\u00e1 sobre los jud\u00edos en sus \u00faltimos d\u00edas. &nbsp;Los fariseos, estando familiarizados con las palabras del profeta Isa\u00edas, &nbsp;sab\u00edan exactamente lo que Jes\u00fas dec\u00eda, y que Jes\u00fas dec\u00eda la par\u00e1bola acerca de ellos. El fin del sistema del Antiguo Pacto termin\u00f3 en la Cruz, pero la destrucci\u00f3n final del sistema de templos lleg\u00f3 en el a\u00f1o 70 dC<\/p>\n<h2>7. La predicci\u00f3n de Joel de que el Esp\u00edritu Santo ser\u00eda derramado en los \u00faltimos d\u00edas<\/h2>\n<p>Joel 2:28-32 es citado por el ap\u00f3stol Pedro en su serm\u00f3n sobre Pentecost\u00e9s en Hechos 2:14-21: \u00abPero Pedro, poni\u00e9ndose de parte de los once, alz\u00f3 la voz y les dijo: Varones jud\u00edos y todos los que habit\u00e1is en Jerusal\u00e9n, esto os sea notorio y o\u00edd mis palabras, porque estos hombres no est\u00e1n borrachos como supon\u00e9is, porque es <em>solamente<\/em> la hora tercera del d\u00eda; &nbsp;pero <em>esto<\/em> es lo dicho por medio del profeta Joel: \u201c&#8217;En los postreros d\u00edas, Dios dice: Derramar\u00e9 mi Esp\u00edritu sobre todos los pueblos. Vuestros hijos y vuestras hijas profetizar\u00e1n, vuestros j\u00f3venes ver\u00e1n visiones, vuestros ancianos so\u00f1ar\u00e1n sue\u00f1os. &nbsp;A\u00fan sobre mis siervos, tanto hombres como mujeres, derramar\u00e9 mi Esp\u00edritu Santo en aquellos d\u00edas, y profetizar\u00e1n\u00bb.<\/p>\n<p>Seg\u00fan el profeta Joel, el Esp\u00edritu Santo ser\u00eda derramado en \u00ablos \u00faltimos d\u00edas\u00bb. Esta profec\u00eda se estaba cumpliendo en Hechos 2 seg\u00fan el Ap\u00f3stol Pedro. Su audiencia en Hechos 2 son jud\u00edos de \u00abtodas las naciones debajo del cielo\u00bb.<\/p>\n<p>\u00bfPodr\u00edan todos estos pasajes del Antiguo Testamento que fueron cumplidos y se\u00f1alados por escritores inspirados en el Nuevo Testamento ser sobre los \u00faltimos d\u00edas del Antiguo Testamento? \u00bfPacto y no los \u00faltimos d\u00edas del mundo? Vale la pena su tiempo y estudio para investigar las Escrituras.<\/p>\n<p>Todos los profetas que hemos mencionado anteriormente estaban escribiendo a los jud\u00edos sobre el juicio venidero sobre ellos por romper el pacto. de Deuteronomio 28-32. Los eventos de los \u00faltimos d\u00edas mencionados en el Antiguo Testamento incluyeron el nacimiento del Mes\u00edas, la venida del Nuevo Pacto, el derramamiento del Esp\u00edritu Santo y el juicio pendiente sobre el sistema del Antiguo Pacto. Jes\u00fas dice claramente que este juicio es viniendo sobre la generaci\u00f3n a la que vino en el primer siglo (Mateo 23:36, Mateo 24:34, Marcos 13:30, Lucas 21:32).<\/p>\n<p>Entonces, \u00bfqu\u00e9 significa todo esto? Las referencias brindan el contexto para los pasajes del Nuevo Testamento relacionados con los \u00ab\u00faltimos d\u00edas\u00bb. Hoy en d\u00eda, casi nunca se escucha desde el p\u00falpito, en una cultura que est\u00e1 m\u00e1s fascinada con las se\u00f1ales de los eventos mundiales que con las Escrituras.<\/p>\n<p>En bienes ra\u00edces, la regla de oro es \u00abubicaci\u00f3n, ubicaci\u00f3n, ubicaci\u00f3n\u00bb. En escatolog\u00eda, es \u00bb se\u00f1ales, se\u00f1ales, se\u00f1ales\u00bb. \u00bfQu\u00e9 tal si volvemos a \u00abEscritura, Escritura, Escritura\u00bb?<\/p>\n<p>Desaf\u00edo a nuestros pastores y maestros en la iglesia de hoy a comenzar a abordar estos pasajes sobre los \u00daltimos D\u00edas desde el Viejo Testamento. Proporcionan el contexto para los pasajes del Nuevo Testamento sobre los \u00daltimos D\u00edas y generar\u00e1n debates saludables dentro de nuestras iglesias hoy.<\/p>\n<p><em><strong>Paul Lopez<\/strong> es un estudiante de la Palabra desde hace mucho tiempo y un maestro de la Biblia y l\u00edder de un grupo peque\u00f1o en Murrieta Valley Church en Murrieta, California.<\/em><\/p>\n<p><strong><em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfCu\u00e1ndo fue la \u00faltima vez que escuch\u00f3 un serm\u00f3n de los \u00ab\u00faltimos d\u00edas\u00bb del Antiguo Testamento? Cuando la mayor\u00eda de los pastores predican un serm\u00f3n sobre el fin de los tiempos suelen comenzar con el Discurso de los Olivos (Mateo 24, Marcos 13 y Lucas 21) o el Libro del Apocalipsis. Durante a\u00f1os, el enfoque &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/siete-pasajes-biblicos-de-los-ultimos-dias-que-rara-vez-escuchara-predicar-a-los-pastores\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abSiete pasajes b\u00edblicos de los &#8216;\u00faltimos d\u00edas&#8217; que rara vez escuchar\u00e1 predicar a los pastores\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24115","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/24115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=24115"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/24115\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=24115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=24115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=24115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}