{"id":24974,"date":"2022-07-29T18:35:46","date_gmt":"2022-07-29T23:35:46","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/cual-es-el-significado-de-bc-y-ad-que-tiene-que-ver-jesus-con-esto\/"},"modified":"2022-07-29T18:35:46","modified_gmt":"2022-07-29T23:35:46","slug":"cual-es-el-significado-de-bc-y-ad-que-tiene-que-ver-jesus-con-esto","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/cual-es-el-significado-de-bc-y-ad-que-tiene-que-ver-jesus-con-esto\/","title":{"rendered":"\u00bfCu\u00e1l es el significado de BC y AD? \u00bfQu\u00e9 tiene que ver Jes\u00fas con esto?"},"content":{"rendered":"<h2> \t\u00bfQu\u00e9 significan BC y AD?<\/h2>\n<p> Si bien la mayor\u00eda cree que AD significa despu\u00e9s de la muerte, en realidad proviene de la frase latina \u201c<em>anno domini<\/em>\u201d que significa \u201ca\u00f1o de nuestro Se\u00f1or\u201d. Dionisio cre\u00eda, quiz\u00e1s con raz\u00f3n, que la historia deber\u00eda dividirse por el mayor acontecimiento de la historia humana; a saber, el nacimiento de Jesucristo. Por lo tanto, todo el tiempo posterior al nacimiento de Cristo se conoci\u00f3 como AD y toda la historia antes del nacimiento de Cristo se denomin\u00f3 BC para \u00abantes de Cristo\u00bb (una adici\u00f3n que hizo Beda en los a\u00f1os 700).<\/p>\n<p> Un monje llamado Dionisio pens\u00f3 que era prudente cambiar el sistema de dataci\u00f3n utilizado anteriormente, m\u00e1s com\u00fanmente lo que fue el comienzo del Imperio Romano, que marca el tiempo con el comienzo del Imperio Romano. Corr\u00eda el a\u00f1o 247 de Diocleciano cuando Dionisio decidi\u00f3 actualizar el calendario para reflejar el nacimiento de Jes\u00fas. As\u00ed que un a\u00f1o fue Diocleciano 247 y al a\u00f1o siguiente se convirti\u00f3 en 532 dC.<\/p>\n<p> El sistema de dataci\u00f3n de Dionisio no se adopt\u00f3 por completo hasta la Edad Media, cuando Carlomagno lo us\u00f3 en todo su Imperio. Pero a\u00fan as\u00ed, durante los per\u00edodos de la Reforma y el Renacimiento, muchos usaron \u00abAD\u00bb, \u00abera cristiana\u00bb y \u00abera com\u00fan\u00bb indistintamente. Pero finalmente, la forma AD\/BC de marcar la historia gan\u00f3 el d\u00eda y permaneci\u00f3 pr\u00e1cticamente indiscutible en Occidente hasta finales del siglo XXI. En los \u00faltimos d\u00edas se ha convertido en una pr\u00e1ctica com\u00fan utilizar las abreviaturas CE (era com\u00fan) y BCE (antes de la era com\u00fan) para marcar la historia. Las fechas siguen siendo las mismas pero se eliminan las connotaciones religiosas. En 2011, la BBC adopt\u00f3 por completo el uso de BCE para marcar la historia; su explicaci\u00f3n da una buena representaci\u00f3n de las razones del cambio:<\/p>\n<blockquote>\n<p> \t\t<em>Dado que la BBC est\u00e1 comprometida con la imparcialidad, es apropiado que usemos t\u00e9rminos que no ofendan ni alejen a los no cristianos. . De acuerdo con la pr\u00e1ctica moderna, BCD\/CE (Before Common Era\/Common Era) se utilizan como una alternativa religiosamente neutral a BC\/AD<\/em>. (Fuente)<\/p>\n<\/blockquote>\n<p> En 2000, los bautistas del sur hicieron una resoluci\u00f3n instando a la continuaci\u00f3n del calendario tradicional. El razonamiento dentro de la resoluci\u00f3n fue que \u201c<em>la pr\u00e1ctica es el resultado de la secularizaci\u00f3n, el anti-sobrenaturalismo, el pluralismo religioso y la correcci\u00f3n pol\u00edtica generalizada en nuestra sociedad<\/em>\u201d. Eso ciertamente parece cuadrar con la decisi\u00f3n de la BBC de adoptar CE\/BCE, aunque no estoy seguro de que podamos decir que esta es <em>siempre<\/em> la motivaci\u00f3n.<\/p>\n<p> Entonces, \u00bfc\u00f3mo deber\u00eda el \u00bfCristiano responde? \u00bfEst\u00e1 bien usar CE\/BCE para marcar la historia, o es capitular ante la cultura y deshonrar a Cristo? Aqu\u00ed hay un par de cosas a considerar al abordar un tema como este.<\/p>\n<h2> 1. \u00bfAD\/BC est\u00e1 en la Biblia y es b\u00edblicamente correcto para fechar?<\/h2>\n<p> La doctrina de la la suficiencia de las Escrituras toca este tema. Wayne Grudem define \u00fatilmente la doctrina:<\/p>\n<blockquote>\n<p> \t\t\u00ab<em>La suficiencia de las Escrituras significa que las Escrituras conten\u00edan todas las palabras de Dios que \u00c9l pretend\u00eda que su pueblo tuviera en cada etapa de la historia redentora, y que ahora contiene todas las palabras de Dios que necesitamos para la salvaci\u00f3n, para confiar perfectamente en \u00e9l y para obedecerle perfectamente<\/em>\u00ab. (Teolog\u00eda sistem\u00e1tica, 127)<\/p>\n<\/blockquote>\n<p> Una implicaci\u00f3n de esta doctrina es que no tenemos el derecho de llamar pecado a algo que no est\u00e1 prohibido por las Escrituras, ya sea expl\u00edcita o impl\u00edcitamente, y tambi\u00e9n que no estamos obligados a hacer algo a menos que las Escrituras lo requieran de nosotros. Los escritores b\u00edblicos no sab\u00edan nada del calendario dionis\u00edaco. Por lo tanto, usar AD\/BC para nuestro sistema de dataci\u00f3n no es b\u00edblicamente vinculante. Usted puede, en libertad, usar CE\/BCE para sus calendarios si es su preferencia.<\/p>\n<p> Las Escrituras <em>s\u00ed<\/em> hablan de que Cristo es aquel de quien se divide toda la historia. Apocalipsis 5 ense\u00f1a mucho. Solo \u00e9l puede abrir los rollos, lo que significa que solo \u00e9l puede moverse a lo largo de la historia. Y sabemos por lo que dijo Cristo en el camino a Ema\u00fas que toda la Escritura y toda la historia deben ser vistas a trav\u00e9s de los lentes de Su persona y obra. Entonces, incluso si no usa d. claro que no debemos involucrarnos en controversias tontas, debemos tener cuidado de no asumir que todo lo que causa controversia es tonter\u00eda. Agradezco estas sabias palabras de Douglas Wilson:<\/p>\n<blockquote>\n<p> \t\t\u00ab<em>Cada vez que lleguemos a esa escurridiza y siempre en retroceso &#8216;colina para morir&#8217;, descubriremos, al llegar all\u00ed, que solo parec\u00eda una colina para morir desde la distancia. De cerca, cuando la posible muerte tambi\u00e9n est\u00e1 de cerca, se parece a cualquier otra colina. De repente, parece una colina para mantenerse con vida, cubierta con tierra vegetal que se parece sospechosamente a un terreno com\u00fan. As\u00ed que resulta que rendir colinas no es la mejor manera de entrenar para defender las m\u00e1s importantes. La retirada crea h\u00e1bito<\/em>\u00ab.<\/p>\n<\/blockquote>\n<p> Creo que esto es a lo que apuntaba la resoluci\u00f3n anterior de los bautistas del sur cuando dec\u00edan:<\/p>\n<blockquote>\n<p> \t\t\u201c<em>POR CUANTO, el m\u00e9todo tradicional de dataci\u00f3n es un recordatorio de la preeminencia de Cristo y Su evangelio en la historia mundial; y POR CUANTO, esta retenci\u00f3n es un recordatorio para aquellos en esta era secular de la importancia de la vida y la misi\u00f3n de Cristo y enfatiza a todos que la historia es, en \u00faltima instancia, Su Historia.<\/em>\u201d<\/p>\n<\/blockquote>\n<p> Quiz\u00e1s <em>deber\u00edamos<\/em> esforzarnos por mantener un recordatorio en nuestros calendarios de que Jesucristo es el punto central de la historia. GK Chesterton una vez aconsej\u00f3 no mover una publicaci\u00f3n a menos que sepa por qu\u00e9 esa publicaci\u00f3n estaba all\u00ed. Es un gran recordatorio de que a pesar de que no nos inclinamos ante la tradici\u00f3n, es importante. No deber\u00edamos jugar con tradiciones probadas y verdaderas sin al menos saber por qu\u00e9 y qu\u00e9 estamos cambiando. Tal vez CE\/BCE sea una mejor manera de fechar nuestros calendarios para fines misionales, o tal vez no lo sea. Independientemente, debemos usar la sabidur\u00eda y el amor unos por otros cuando abordamos temas de preferencia como este.<\/p>\n<h2> 3. Jes\u00fas divide la historia<\/h2>\n<p> Aqu\u00ed es donde tenemos que admitir que esto es un \u00e1rea que requiere sabidur\u00eda y libertad personal. Este tema en particular podr\u00eda encajar mejor dentro de una conversaci\u00f3n sobre asuntos discutibles, a la Romans 14. No debemos atar la conciencia de aquellos que ven esto como un problema sin importancia ni debemos intentar desalentar a aquellos que <em>lo hacen<\/em>. vemos esto como un tema importante.<\/p>\n<p> Al final del d\u00eda, todos debemos decir que Jes\u00fas divide la historia y que la verdad debe reflejarse en nuestros corazones, incluso si no necesariamente se refleja en nuestros calendarios <\/p>\n<p> <em>Mike Leake es el pastor principal de FBC Marionville en Marionville, Missouri. Actualmente est\u00e1 cursando su M.Div. en el Seminario Teol\u00f3gico Bautista del Sur. Mike est\u00e1 casado con Nikki y tienen dos hijos, Isaiah y Hannah. <\/em><em>Puedes seguirlo en Twitter @MikeLeake.<\/em> <\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 significan BC y AD? Si bien la mayor\u00eda cree que AD significa despu\u00e9s de la muerte, en realidad proviene de la frase latina \u201canno domini\u201d que significa \u201ca\u00f1o de nuestro Se\u00f1or\u201d. Dionisio cre\u00eda, quiz\u00e1s con raz\u00f3n, que la historia deber\u00eda dividirse por el mayor acontecimiento de la historia humana; a saber, el nacimiento de &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/cual-es-el-significado-de-bc-y-ad-que-tiene-que-ver-jesus-con-esto\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfCu\u00e1l es el significado de BC y AD? \u00bfQu\u00e9 tiene que ver Jes\u00fas con esto?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24974","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/24974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=24974"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/24974\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=24974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=24974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=24974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}