{"id":24986,"date":"2022-07-29T18:36:13","date_gmt":"2022-07-29T23:36:13","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/cuando-vio-jesus-a-satanas-caer-como-un-rayo\/"},"modified":"2022-07-29T18:36:13","modified_gmt":"2022-07-29T23:36:13","slug":"cuando-vio-jesus-a-satanas-caer-como-un-rayo","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/cuando-vio-jesus-a-satanas-caer-como-un-rayo\/","title":{"rendered":"\u00bfCu\u00e1ndo vio Jes\u00fas a Satan\u00e1s \u00abcaer como un rayo\u00bb?"},"content":{"rendered":"<p>En uno de los vers\u00edculos m\u00e1s enigm\u00e1ticos del Evangelio de Lucas, Jes\u00fas dice a sus disc\u00edpulos: \u00abVi a Satan\u00e1s caer del cielo como un rayo\u00bb (Lucas 10:18). ). La pregunta no es sobre el <em>qu\u00e9<\/em> de la declaraci\u00f3n de Jes\u00fas. Est\u00e1 claro que Satan\u00e1s est\u00e1 bajo juicio. M\u00e1s bien, la confusi\u00f3n es sobre el <em>cu\u00e1ndo<\/em> de la declaraci\u00f3n. Puede sonar como una referencia a cuando Satan\u00e1s <em>se convirti\u00f3<\/em> en Satan\u00e1s, ante el jard\u00edn del Ed\u00e9n, abandonando su estatus entre las huestes celestiales de Dios, pero esa conclusi\u00f3n ser\u00eda demasiado apresurada<\/p>\n<p>B\u00e1sicamente tenemos tres opciones cuando se trata de determinar el momento de la ca\u00edda de Satan\u00e1s: antes, durante o despu\u00e9s del tiempo de Jes\u00fas. Muchas personas han ofrecido opiniones. Quiz\u00e1s la interpretaci\u00f3n m\u00e1s com\u00fan es que Jes\u00fas est\u00e1 viendo o recordando la ca\u00edda original de Satan\u00e1s. Esta opci\u00f3n tiene poco sentido en el contexto. Antes de la declaraci\u00f3n, Jes\u00fas hab\u00eda enviado a los disc\u00edpulos a sanar y predicar que el reino de Dios se hab\u00eda acercado a ellos (Lucas 10:1-9). Regresan asombrados y emocionados por el hecho de que los demonios se les sujetaron en el nombre de Jes\u00fas (Lucas 10:17). Entonces Jes\u00fas dice: \u00abVi a Satan\u00e1s caer del cielo como un rayo\u00bb.<\/p>\n<p>Hay una conexi\u00f3n entre el reino, la derrota de los demonios y Satan\u00e1s. Pero si la ca\u00edda de Satan\u00e1s en Lucas 10:18 habla de un evento en el pasado remoto, \u00bfpor qu\u00e9 no se estableci\u00f3 entonces el reino? \u00bfPor qu\u00e9 Satan\u00e1s todav\u00eda era poderoso cuando Jes\u00fas apareci\u00f3 en escena? Incluso con el reino de Israel bajo David y la presencia de Dios en el templo, el poder y la influencia de Satan\u00e1s son evidentes en casi todas las p\u00e1ginas de la historia del Antiguo Testamento.<\/p>\n<p>La opini\u00f3n de que Jes\u00fas se refer\u00eda a la ca\u00edda de Satan\u00e1s durante su propio ministerio es mejor, pero no est\u00e1 exento de problemas. No leemos en ninguna parte de la Biblia que alguien haya echado fuera demonios antes del ministerio de Jes\u00fas. Esa demostraci\u00f3n de poder, as\u00ed como los anuncios del reino y la autoridad gobernante de Dios en la tierra, son inconfundibles. Esto es consistente con lo que Lucas escribe en el pr\u00f3ximo cap\u00edtulo (Lucas 11:14-23), donde identifica a Jes\u00fas con el \u00abhombre fuerte\u00bb que ata a Satan\u00e1s. Con Jes\u00fas habiendo atado al hombre fuerte (Satan\u00e1s), \u00c9l y Sus disc\u00edpulos pueden saquear el reino de Satan\u00e1s. Esto parece estar relacionado con lo que Jes\u00fas dice despu\u00e9s de Su declaraci\u00f3n acerca de Satan\u00e1s (Lucas 10:19-20), donde les otorga a los disc\u00edpulos poder sobre las fuerzas del mal. Pero estos vers\u00edculos tambi\u00e9n producen dificultades. \u00bfPor qu\u00e9 leemos m\u00e1s adelante en el mismo evangelio y en otras partes del Nuevo Testamento que los disc\u00edpulos no eran inmunes al poder de Satan\u00e1s (Lucas 22:31-61; 2 Corintios 12:7; 1 Tesalonicenses 2:18)?&lt;\/p <\/p>\n<p>Esto nos lleva a la tercera opci\u00f3n: la afirmaci\u00f3n de Jes\u00fas se refiere a un tiempo posterior al suyo. Dado que Satan\u00e1s estaba (y est\u00e1) todav\u00eda vivo y bien, con respecto a su continua oposici\u00f3n a la Iglesia en todas partes, tiene sentido ver la ca\u00edda de Satan\u00e1s \u00abcomo un rayo del cielo\u00bb como un evento futuro. La expresi\u00f3n utilizada por Lucas (\u00abYo vi\u00bb) era bastante com\u00fan en el Antiguo Testamento para introducir visiones prof\u00e9ticas, especialmente en el libro de Daniel (Daniel 4:10; Daniel 7:2, Daniel 7:4, Daniel 7:6- 7, Daniel 7:9, Daniel 7:11, Daniel 7:13, Daniel 7:21).1<\/p>\n<p>Mi propio punto de vista es una combinaci\u00f3n del segundo y tercer punto de vista. Parece bastante claro que el gobierno de Dios comenz\u00f3 con el ministerio de Jes\u00fas, pero es un gobierno en progreso que alcanzar\u00e1 una culminaci\u00f3n final en un tiempo futuro. Como nos recuerda repetidamente el Antiguo Testamento, y como Jes\u00fas afirm\u00f3 en Lucas 10:18, <em>en ese d\u00eda<\/em> la derrota de nuestro enemigo c\u00f3smico ser\u00e1 r\u00e1pida y definitiva.<\/p>\n<p><strong> Nota final:<\/strong><\/p>\n<p>1. La misma forma del verbo griego usado en Lucas 10:18 se usa en todas estas referencias de \u00abvisi\u00f3n\u00bb en la versi\u00f3n griega de Daniel.<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>En uno de los vers\u00edculos m\u00e1s enigm\u00e1ticos del Evangelio de Lucas, Jes\u00fas dice a sus disc\u00edpulos: \u00abVi a Satan\u00e1s caer del cielo como un rayo\u00bb (Lucas 10:18). ). La pregunta no es sobre el qu\u00e9 de la declaraci\u00f3n de Jes\u00fas. Est\u00e1 claro que Satan\u00e1s est\u00e1 bajo juicio. M\u00e1s bien, la confusi\u00f3n es sobre el cu\u00e1ndo &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/cuando-vio-jesus-a-satanas-caer-como-un-rayo\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfCu\u00e1ndo vio Jes\u00fas a Satan\u00e1s \u00abcaer como un rayo\u00bb?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24986","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/24986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=24986"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/24986\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=24986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=24986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=24986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}