{"id":29842,"date":"2022-07-30T01:09:10","date_gmt":"2022-07-30T06:09:10","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/el-modelo-para-la-felicidad\/"},"modified":"2022-07-30T01:09:10","modified_gmt":"2022-07-30T06:09:10","slug":"el-modelo-para-la-felicidad","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/el-modelo-para-la-felicidad\/","title":{"rendered":"El modelo para la felicidad"},"content":{"rendered":"<p>Charles Dickens comenz\u00f3 su novela cl\u00e1sica, <em>A Tale Two Cities<\/em>, con la afirmaci\u00f3n: \u00abEra el mejor de los tiempos; era el peor de los tiempos .\u00bb Creo que tambi\u00e9n es una evaluaci\u00f3n precisa de la cultura estadounidense actual. En muchos sentidos, nunca hemos visto tiempos mejores. Pero en muchos sentidos, nunca hemos visto tiempos peores.<\/p>\n<p>\u00bfRecuerdas esa frase tan repetida de hace un par de elecciones? \u00abEs la econom\u00eda, est\u00fapido\u00bb. Bueno, no es la econom\u00eda; Es m\u00e1s que eso. Cuando nuestra econom\u00eda era fuerte, nuestra moral era baja. Ahora, cuando nuestra econom\u00eda est\u00e1 luchando, nuestra moral sigue siendo baja. <\/p>\n<p>Creo que la respuesta se puede encontrar en una declaraci\u00f3n que hizo Abraham Lincoln: <\/p>\n<blockquote><p>Nos hemos olvidado de Dios. Hemos olvidado la mano misericordiosa, que nos preserv\u00f3 en la paz y nos multiplic\u00f3, enriqueci\u00f3 y fortaleci\u00f3. En vano hemos imaginado en el enga\u00f1o de nuestro coraz\u00f3n que todas estas bendiciones que vemos en nuestro pa\u00eds fueron producidas por sabidur\u00eda superior y virtud propia. <\/p><\/blockquote>\n<p>El honesto Abe ten\u00eda raz\u00f3n. Nos hemos olvidado de Dios. Esto ha sido especialmente evidente durante la \u00faltima d\u00e9cada en las batallas judiciales por la recitaci\u00f3n del Juramento a la Bandera en las escuelas p\u00fablicas y la exhibici\u00f3n de los Diez Mandamientos en lugares p\u00fablicos. <\/p>\n<p>Sin embargo, ante nosotros en los Diez Mandamientos, encontramos el plan de Dios para una sociedad. Una de las razones originales del \u00e9xito de nuestro pa\u00eds se encuentra en sus or\u00edgenes y en su adhesi\u00f3n a estos absolutos que Dios mismo nos ha dado. <\/p>\n<p>Estos principios no solo son buenos para una naci\u00f3n, sino tambi\u00e9n para los individuos. La Biblia dice que si queremos vivir vidas satisfactorias, productivas y, de hecho, felices, entonces necesitamos conocer a Dios, caminar con \u00c9l y guardar Sus mandamientos. <\/p>\n<p>Algunas personas piensan que pueden quebrantar los mandamientos de Dios con abandono, pero sin repercusiones. Salom\u00f3n sab\u00eda un poco acerca de quebrantar los mandamientos. Era un hombre que tuvo una reca\u00edda masiva. Puedes leer su historia en Eclesiast\u00e9s 1. <\/p>\n<p>Salom\u00f3n ten\u00eda recursos ilimitados. Lo que quisiera era suyo. Pero despu\u00e9s de probar todo lo que este mundo ten\u00eda para ofrecer, dijo: \u00abEsta es mi conclusi\u00f3n final: teme a Dios y obedece sus mandamientos, porque este es el deber de toda persona\u00bb (Eclesiast\u00e9s 12:13 NTV). <\/p>\n<p>Salom\u00f3n estaba diciendo: \u00abEscucha. He pasado por la escuela de los golpes duros. S\u00e9 de lo que hablo. Teme a Dios y guarda Sus mandamientos. Perseguir todas estas otras cosas es vano. es insatisfactorio\u00bb. <\/p>\n<p>En sus propias palabras, dijo que era como \u00abaferrarse al viento\u00bb (ver Eclesiast\u00e9s 6:9). <\/p>\n<p>Dios nos ha dado un modelo para la felicidad. Creemos que proviene de la libertad de todas las limitaciones. Pero esto no es cierto. La felicidad proviene de permanecer dentro de los muros de protecci\u00f3n que Dios nos ha dado en Su Palabra. <\/p>\n<p>Ahora estamos viendo los resultados finales de ese gran experimento social que comenz\u00f3 en la d\u00e9cada de 1960. Podemos concluir claramente que fue un fracaso colosal ya que dejamos de lado absolutos como la familia, la fidelidad, la honestidad, la compasi\u00f3n y todo lo dem\u00e1s, y perseguimos lo que quer\u00edamos. Como dice la Escritura en el Salmo 1, <\/p>\n<blockquote><p>Bienaventurado [o bienaventurado] el var\u00f3n que no anduvo en consejo de malos, ni estuvo en camino de pecadores, ni en silla de el desde\u00f1oso; sino que en la ley del Se\u00f1or est\u00e1 su delicia, y en su ley medita de d\u00eda y de noche. Ser\u00e1 como \u00e1rbol plantado junto a corrientes de aguas, que da su fruto en su tiempo, y cuya hoja tampoco cae; y todo lo que hace prosperar\u00e1. (vv. 1-3 NKJV) <\/p><\/blockquote>\n<p>\u00bfQuieres ser una persona feliz? Se encuentra en hacer lo correcto. Tambi\u00e9n se encuentra en no hacer lo incorrecto. <\/p>\n<p>No vas a encontrar la felicidad en el materialismo. No lo vas a encontrar en una carrera. No lo vas a encontrar en una relaci\u00f3n. No lo vas a encontrar en el sexo. No lo vas a encontrar en las drogas. No lo vas a encontrar en nada de lo que este mundo tiene para ofrecer. <\/p>\n<p>\u00bfQuieres ser una persona feliz? Vive a la manera de Dios. \u00bfQuieres ser una persona infeliz? Vive a tu manera. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charles Dickens comenz\u00f3 su novela cl\u00e1sica, A Tale Two Cities, con la afirmaci\u00f3n: \u00abEra el mejor de los tiempos; era el peor de los tiempos .\u00bb Creo que tambi\u00e9n es una evaluaci\u00f3n precisa de la cultura estadounidense actual. En muchos sentidos, nunca hemos visto tiempos mejores. Pero en muchos sentidos, nunca hemos visto tiempos peores. &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/el-modelo-para-la-felicidad\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEl modelo para la felicidad\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29842","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/29842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=29842"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/29842\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=29842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=29842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=29842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}