{"id":29858,"date":"2022-07-30T02:01:24","date_gmt":"2022-07-30T07:01:24","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/10-mentiras-que-el-mundo-nos-dice-sobre-el-matrimonio\/"},"modified":"2022-07-30T02:01:24","modified_gmt":"2022-07-30T07:01:24","slug":"10-mentiras-que-el-mundo-nos-dice-sobre-el-matrimonio","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/10-mentiras-que-el-mundo-nos-dice-sobre-el-matrimonio\/","title":{"rendered":"10 Mentiras que el mundo nos dice sobre el matrimonio"},"content":{"rendered":"<p>El matrimonio es un maravilloso regalo de Dios. Sin embargo, a menudo, los mejores regalos no siempre se valoran como deber\u00edan. La vida se pone ocupada. Nos apresuramos y nos distraemos. Empezamos a darnos por sentado. Discutimos y dejamos que surjan los resentimientos. Comparamos nuestros propios matrimonios con los que nos rodean, anhelando felices para siempre, en lugar de quedar atrapados en el dolor y el arrepentimiento. Empezamos a distanciarnos. Y lamentablemente, muchas veces, comenzamos a buscar la \u201csalida\u201d m\u00e1s cercana.<\/p>\n<p>Una cosa es cierta, hoy hay una batalla por los matrimonios, y el enemigo no quiere nada m\u00e1s que destruirlos a todos. Pero no tenemos que dejarlo ganar. Dios ciertamente tiene una mejor manera, \u00c9l es quien cre\u00f3 el matrimonio. Sus palabras brindan gu\u00eda, sabidur\u00eda, fortaleza y esperanza en todo lo que enfrentamos, tanto ahora como en el futuro.<\/p>\n<p><strong>Aqu\u00ed hay 10 mentiras que el mundo puede contarte sobre tu matrimonio:<\/strong> <\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>El matrimonio es un maravilloso regalo de Dios. Sin embargo, a menudo, los mejores regalos no siempre se valoran como deber\u00edan. La vida se pone ocupada. Nos apresuramos y nos distraemos. Empezamos a darnos por sentado. Discutimos y dejamos que surjan los resentimientos. Comparamos nuestros propios matrimonios con los que nos rodean, anhelando felices para &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/10-mentiras-que-el-mundo-nos-dice-sobre-el-matrimonio\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab10 Mentiras que el mundo nos dice sobre el matrimonio\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29858","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/29858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=29858"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/29858\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=29858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=29858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=29858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}