{"id":3907,"date":"2022-07-26T00:01:00","date_gmt":"2022-07-26T05:01:00","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/5-razones-por-las-que-el-servicio-de-adoracion-de-las-1100-a-m-esta-desapareciendo\/"},"modified":"2022-07-26T00:01:00","modified_gmt":"2022-07-26T05:01:00","slug":"5-razones-por-las-que-el-servicio-de-adoracion-de-las-1100-a-m-esta-desapareciendo","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/5-razones-por-las-que-el-servicio-de-adoracion-de-las-1100-a-m-esta-desapareciendo\/","title":{"rendered":"5 razones por las que el servicio de adoraci\u00f3n de las 11:00 a. m. est\u00e1 desapareciendo"},"content":{"rendered":"<div class=\"entry-content\">\n<div class=\"wp-block-image is-style-default\"><\/div>\n<p><em>Por Thom S. Rainer<\/em><\/p>\n<p>Ojal\u00e1 supiera la raz\u00f3n espec\u00edfica por la que la mayor\u00eda de las iglesias ofrecieron un servicio los domingos a las 11:00 a. m. durante d\u00e9cadas.<\/p>\n<p>Las posibles teor\u00edas son muchos, pero ninguno ha sido corroborado con la investigaci\u00f3n hist\u00f3rica. La m\u00e1s plausible es la teor\u00eda agraria.<\/p>\n<p>Esa perspectiva sostiene que las iglesias acomodaron a los agricultores en la comunidad. Los granjeros ten\u00edan m\u00faltiples tareas que ten\u00edan que hacer en la ma\u00f1ana.<\/p>\n<p>Hac\u00edan las tareas y luego iban a la iglesia. A menudo segu\u00edan el servicio individual con una comida compartida en el terreno.<\/p>\n<p>Pero el servicio de las 11:00 a. m. est\u00e1 desapareciendo.<\/p>\n<div class='code-block code-block-1'> <\/div>\n<p>En lugar de perder tiempo tratando de descubrir el origen del servicio de las 11:00 a. m., decid\u00ed preguntarle a varios l\u00edderes de la iglesia por qu\u00e9 descontinuaron el servicio en sus iglesias. Surgieron cinco temas comunes.<\/p>\n<p><strong>1. Cuando una iglesia pas\u00f3 de un servicio a dos, el horario de las 11:00 a. m. ya no ten\u00eda sentido.<\/strong><\/p>\n<p>Cuando las iglesias comenzaron a programar servicios adicionales, el horario de las 11:00 a. buen horario para el tr\u00e1fico, el flujo y la duraci\u00f3n del servicio. Algunas iglesias tambi\u00e9n tuvieron que programar la escuela dominical o grupos en torno a los nuevos horarios.<\/p>\n<p>La desaparici\u00f3n del servicio de las 11:00 a. m. probablemente est\u00e9 relacionada con las iglesias que se mudaron a m\u00faltiples servicios m\u00e1s que por cualquier otra raz\u00f3n.<\/p>\n<p>2. Las iglesias con un solo servicio comenzaron a darse cuenta de las desventajas del servicio de las 11:00 a. m.<\/strong><\/p>\n<p>La mayor\u00eda de estos l\u00edderes de la iglesia no pod\u00edan ofrecer una explicaci\u00f3n convincente para un solo servicio con una hora tan tard\u00eda. La mayor\u00eda de las personas hab\u00edan estado despiertas durante horas, incluso si asist\u00edan a un grupo oa una clase antes del servicio. Y el servicio de adoraci\u00f3n inevitablemente llega hasta la hora del almuerzo.<\/p>\n<div style=\"clear:both;margin-top:0em;margin-bottom:1em\">\n<div class=\"centered-text-area\">\n<div class=\"centered-text\" style=\"float: left\">\n<div class=\"u1322b4eef7e457cdd2370219594d41b6-content\">Ver tambi\u00e9n&nbsp; El grupo que con mayor probabilidad a\u00fan faltar\u00e1 en su iglesia<\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p><strong>3. M\u00e1s personas eligen un horario de media ma\u00f1ana si tienen la opci\u00f3n.<\/strong><\/p>\n<p>He dirigido equipos para realizar una serie de encuestas congregacionales. La pluralidad de encuestados escogi\u00f3 un horario de adoraci\u00f3n que comenzara entre las 9:00 y las 10:30 horas. Rara vez la gente dice que quiere asistir a un servicio de las 11:00 am a menos que sean tradicionalistas fuertes.<\/p>\n<p><strong>4. Los millennials son particularmente reacios a los servicios de las 11:00 a. m.<\/strong><\/p>\n<p>Son la generaci\u00f3n m\u00e1s poblada en la historia de Estados Unidos. Si deciden asistir a un servicio, probablemente no ser\u00e1 a las 11:00 AM. Es dif\u00edcil precisar una raz\u00f3n espec\u00edfica de su aversi\u00f3n.<\/p>\n<p>Si les pregunta, es probable que obtenga una pregunta a su pregunta: \u00bfPor qu\u00e9 <em>deber\u00edamos<\/em> asistir a un servicio en ese momento?<\/p>\n<p><strong>5. Algunas personas perciben que una iglesia con un servicio solitario a las 11:00 a. m. es demasiado tradicional y fuera de onda.<\/strong><\/p>\n<p>Por lo tanto, los l\u00edderes cambian el servicio a una hora que no solo tiene m\u00e1s sentido , pero tambi\u00e9n se percibe como m\u00e1s relevante para los miembros y la comunidad.<\/p>\n<p>\u00bfCu\u00e1les son sus tiempos de servicio? \u00bfSu iglesia todav\u00eda tiene un servicio de 11:00 AM? \u00bfCu\u00e1l es el horario de atenci\u00f3n m\u00e1s atendido?<\/p>\n<div style=\"background-color:#f2f2f2;color:#32373c\" class=\"wp-block-genesis-blocks-gb-profile-box square gb-has- avatar gb-font-size-18 gb-block-profile gb-profile-columns\">\n<div class=\"gb-profile-column gb-profile-avatar-wrap\">\n<div class=\"gb-profile-image- wrap\"><\/div>\n<\/div>\n<div class=\"gb-perfil-columna gb-perfil-contenido-envoltura\">\n<h2 class=\"gb-perfil-nombre\" style=\"color:#32373c\"> Thom S. Rainer<\/h2>\n<p class=\"gb-profile-title\" style=\"color:#32373c\"><strong>@ThomRainer<\/strong><\/p>\n<div class=\"gb-profile- text\">\n<p>Thom es ex presidente y director ejecutivo de Lifeway Christian Resources y autor de <em>Autopsy of a Deceased Church<\/em>.<\/p>\n<\/div>\n<ul class=\"gb-social- enlaces\"><\/ul>\n<\/div>\n<\/div>\n<p class=\"has-small-font-size\"><em>Esto apareci\u00f3 originalmente en ThomRainer.com.<\/em><\/p>\n<div class='yarpp yarpp-related yarpp-related-website yarpp-template-thumbnails'>\n<h3>Publicaciones relacionadas:<\/h3>\n<div class=\"yarpp-thumbnails-horizontal\"> \u00bfQu\u00e9 creen los pastores sobre el \u00bfFin de los tiempos? \u00bfQu\u00e9 creen los pastores sobre el libro de Apocalipsis? 3 formas de llegar a personas no religiosas en su comunidad <\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Thom S. Rainer Ojal\u00e1 supiera la raz\u00f3n espec\u00edfica por la que la mayor\u00eda de las iglesias ofrecieron un servicio los domingos a las 11:00 a. m. durante d\u00e9cadas. Las posibles teor\u00edas son muchos, pero ninguno ha sido corroborado con la investigaci\u00f3n hist\u00f3rica. La m\u00e1s plausible es la teor\u00eda agraria. Esa perspectiva sostiene que las &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/5-razones-por-las-que-el-servicio-de-adoracion-de-las-1100-a-m-esta-desapareciendo\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab5 razones por las que el servicio de adoraci\u00f3n de las 11:00 a. m. est\u00e1 desapareciendo\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3907","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/3907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=3907"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/3907\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=3907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=3907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=3907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}