{"id":3909,"date":"2022-07-26T00:01:03","date_gmt":"2022-07-26T05:01:03","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/estudio-la-teologia-es-importante-para-las-iglesias-en-crecimiento\/"},"modified":"2022-07-26T00:01:03","modified_gmt":"2022-07-26T05:01:03","slug":"estudio-la-teologia-es-importante-para-las-iglesias-en-crecimiento","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/estudio-la-teologia-es-importante-para-las-iglesias-en-crecimiento\/","title":{"rendered":"Estudio: La teolog\u00eda es importante para las iglesias en crecimiento"},"content":{"rendered":"<div class=\"entry-content\">\n<div class=\"wp-block-image\"><\/div>\n<p>Por el personal<\/p>\n<p>Creciendo en la d\u00e9cada de 1970 en Canad\u00e1, David Haskell iba a menudo a la iglesia con su abuela. En ese entonces, ir a la iglesia era lo que se hac\u00eda los domingos. \u201cLa iglesia de la abuela estaba repleta de j\u00f3venes y adultos por igual\u201d, escribe en una columna para el Calgary Sun.<\/p>\n<p>Y las congregaciones evang\u00e9licas como la de su abuela no eran las \u00fanicas que atra\u00edan multitudes, argumenta Haskell. Las iglesias de todo tipo en su ciudad (luterana, anglicana, presbiteriana) estaban llenas, escribe.<\/p>\n<p>Pero los tiempos cambiaron. Muchas iglesias en Canad\u00e1, especialmente las congregaciones principales, se han tambaleado. Haskell, un periodista convertido en profesor universitario, quer\u00eda saber qu\u00e9 sali\u00f3 mal.<\/p>\n<p>As\u00ed que \u00e9l y dos colegas pasaron cinco a\u00f1os estudiando 22 iglesias en Ontario, Canad\u00e1, algunas creciendo y otras fracasando. En el camino, encuestaron a m\u00e1s de 2000 feligreses en esas congregaciones.<\/p>\n<p>Descubrieron que lo que la gente cree realmente importa. Las iglesias que se adhieren a la teolog\u00eda conservadora tienen m\u00e1s probabilidades de crecer que aquellas que no lo hacen.<\/p>\n<div class='code-block code-block-1' style='margin: 8px 0'> <\/div>\n<p>\u201cPor ejemplo, debido a su perspectiva conservadora, los miembros crecientes del clero de la iglesia en nuestro estudio tomaron el mandato de Jes\u00fas de &#8216;Ir y hacer disc\u00edpulos&#8217; literalmente\u201d, escribe Haskell en el Washington Post. .<\/p>\n<p>\u201cNuestra investigaci\u00f3n sugiere que las iglesias no tienen que abandonar o diluir sus creencias fundamentales para seguir siendo &#8216;relevantes&#8217; o atraer a la gente a sus servicios\u201d, dice el coinvestigador Kevin Flatt.<\/p>\n<p>\u201cPor el contrario, las iglesias que se adhieren a creencias bastante conservadoras que enfatizan la verdad de la Biblia, la importancia de compartir el evangelio y la acci\u00f3n continua de Dios en el mundo, en realidad tienen m\u00e1s probabilidades de crecer\u201d.<\/p>\n<p>Las iglesias en crecimiento y las iglesias en declive ten\u00edan enfoques y creencias muy diferentes, seg\u00fan el estudio.<\/p>\n<div class=\"wp-block-image\"><\/div>\n<div class='yarpp yarpp-related yarpp- sitio web relacionado yarpp-template-thumbnails'>\n<h3>Publicaciones relacionadas:<\/h3>\n<div class=\"yarpp-thumbnails-horizontal\"> 22 Estad\u00edsticas vitales para el ministerio en 2022 9 Caracter\u00edsticas de Spiri Iglesias Tualmente Saludables y en Crecimiento Num\u00e9rico Las Iglesias Peque\u00f1as Contin\u00faan Creciendo\u2014pero en N\u00famero, no en Tama\u00f1o 6 Grandes Cambios Ocurriendo en las Iglesias de los Estados Unidos <\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por el personal Creciendo en la d\u00e9cada de 1970 en Canad\u00e1, David Haskell iba a menudo a la iglesia con su abuela. En ese entonces, ir a la iglesia era lo que se hac\u00eda los domingos. \u201cLa iglesia de la abuela estaba repleta de j\u00f3venes y adultos por igual\u201d, escribe en una columna para el &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/estudio-la-teologia-es-importante-para-las-iglesias-en-crecimiento\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio: La teolog\u00eda es importante para las iglesias en crecimiento\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3909","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/3909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=3909"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/3909\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=3909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=3909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=3909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}