{"id":3926,"date":"2022-07-26T00:01:32","date_gmt":"2022-07-26T05:01:32","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/encontrar-nuestra-voz-por-que-es-importante-el-declive-del-canto-congregacional-y-como-solucionarlo\/"},"modified":"2022-07-26T00:01:32","modified_gmt":"2022-07-26T05:01:32","slug":"encontrar-nuestra-voz-por-que-es-importante-el-declive-del-canto-congregacional-y-como-solucionarlo","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/encontrar-nuestra-voz-por-que-es-importante-el-declive-del-canto-congregacional-y-como-solucionarlo\/","title":{"rendered":"Encontrar nuestra voz: por qu\u00e9 es importante el declive del canto congregacional y c\u00f3mo solucionarlo"},"content":{"rendered":"<div class=\"entry-content\">\n<div class=\"wp-block-image\"><\/div>\n<p><em>Por Bob Smietana<\/em><\/p>\n<p>Demasiadas canciones. No hay suficientes cantantes. Ese es el problema que enfrentan muchas congregaciones en estos d\u00edas, dice Tony Payne, l\u00edder de adoraci\u00f3n veterano y profesor asociado de m\u00fasica en Wheaton College.<\/p>\n<p>Ya sea que una iglesia toque himnos o las \u00faltimas canciones de adoraci\u00f3n, menos personas quieren cantar, \u00e9l dice. \u201cHay mucha gente parada all\u00ed muda durante el culto\u201d.<\/p>\n<p>El canto congregacional ha sido durante mucho tiempo un elemento b\u00e1sico de las iglesias protestantes, desde la Reforma, cuando \u201cCastillo fuerte es nuestro Dios\u201d fue el \u00faltimo \u00e9xito. canci\u00f3n de adoraci\u00f3n. Y hoy en d\u00eda, las iglesias tienen m\u00e1s canciones para elegir que nunca.<\/p>\n<p>Lifeway Worship, por ejemplo, tiene un cat\u00e1logo de 4000 canciones de adoraci\u00f3n, mientras que Christian Copyright Licensing International (CCLI) tiene 300 000, todas disponibles con un clic. de un bot\u00f3n.<\/p>\n<p>Sin embargo, Payne y otros l\u00edderes de adoraci\u00f3n veteranos temen que el canto congregacional est\u00e9 en declive.<\/p>\n<div class='code-block code-block-1' style='margin: 8px 0'> <\/div>\n<p>Esas son malas noticias, dice Rick Eubanks, pastor de adoraci\u00f3n y estudiantes de la Iglesia Bautista Oak Grove en Burleson, Texas. El canto congregacional es una parte esencial de la adoraci\u00f3n cristiana, dice. Cuando las iglesias no cantan juntas, falta algo vital.<\/p>\n<p>\u201cReunirse para adorar no se trata de ver actuar a otras personas\u201d, dice. \u201cY no se trata de la m\u00fasica; se trata de permitir que las personas se conecten con Dios\u201d.<\/p>\n<p>\u00bfC\u00f3mo llegamos aqu\u00ed?<\/p>\n<p>Mike Harland, director de Lifeway Worship, dice que varios factores han contribuido a la disminuci\u00f3n de la congregaci\u00f3n cantando. Entre ellos: el hecho de que hay menos lugares para que los miembros de la congregaci\u00f3n canten en la iglesia, en gran parte debido a la disminuci\u00f3n de los coros.<\/p>\n<p>En 1998, el 54 por ciento de las iglesias estadounidenses ten\u00edan un coro, seg\u00fan la Estudio de Congregaciones Nacionales. Para 2012, menos de la mitad ten\u00eda un coro (45 por ciento).<\/p>\n<p>Las iglesias evang\u00e9licas m\u00e1s grandes, en particular, se han alejado de los coros, en parte debido a las finanzas y en parte porque han adoptado estilos contempor\u00e1neos de m\u00fasica. M\u00e1s de dos tercios (69 por ciento) ten\u00edan coros en 1998. Para 2012, poco m\u00e1s de un tercio (36 por ciento) ten\u00edan coros.<\/p>\n<p>Eso es preocupante, dicen los autores del Estudio Nacional de Congregaciones, ya que significa menos laicos tienen un papel que desempe\u00f1ar en la adoraci\u00f3n.<\/p>\n<p>\u201cVale la pena examinar por derecho propio el declive de los coros porque cantar en el coro es una de las formas m\u00e1s comunes, junto con los estudios b\u00edblicos, para las personas. para involucrarse m\u00e1s profundamente en una congregaci\u00f3n, y es la forma m\u00e1s com\u00fan para que los laicos participen activamente en la adoraci\u00f3n reunida\u201d, seg\u00fan el autor del estudio.<\/p>\n<p>Perder un coro puede da\u00f1ar el canto congregacional, dice Eubanks.<\/p>\n<p>\u201cUn coro puede ser una organizaci\u00f3n que otorga permisos\u201d, dice. \u201cLe dan permiso a la gente para cantar\u201d.<\/p>\n<p>Otro factor podr\u00eda ser la mentalidad consumista que prevalece en muchas iglesias hoy en d\u00eda.<\/p>\n<p>\u201cNos han ense\u00f1ado en nuestras iglesias y en la comunidad cristiana comercializando la subcultura que nos rodea para tratar la m\u00fasica como otro producto para consumir, tal como tenemos el resto de nuestra fe\u201d, escribe el pastor de adoraci\u00f3n Mike Cosper en su libro Rhythms of Grace.<\/p>\n<p>\u201cSi algo no cumple nuestras preferencias, hemos aprendido a descartarlo, unirnos a otra iglesia y comprar un CD diferente. Hemos aprendido a ser espectadores los domingos\u2014escuchando, disfrutando y criticando\u2014pero la Biblia nos llama sin disculpas a ser participantes\u201d.<\/p>\n<p>Si los miembros de la iglesia no vienen a la iglesia con una actitud de adoraci\u00f3n, es probable que no participen.<\/p>\n<p>Un estudio de Lifeway Research de 2008 encontr\u00f3 que muchos feligreses se sienten desconectados durante el culto. Casi la mitad (47 por ciento) de los 2,500 feligreses protestantes en la encuesta dijeron que a menudo estaban \u00absiguiendo los movimientos\u00bb durante las porciones de canto y oraci\u00f3n de los servicios de adoraci\u00f3n.<\/p>\n<p>Harland se pregunta si las iglesias desalientan involuntariamente el canto durante los servicios.<\/p>\n<p>Alrededor de la mitad de los evang\u00e9licos blancos asisten a una iglesia que utiliza pantallas multimedia durante los servicios, seg\u00fan el Public Religion Research Institute. Bajar las luces hace que las pantallas sean m\u00e1s f\u00e1ciles de leer. Pero Harland dice que puede enviar un mensaje no deseado.<\/p>\n<p>\u201cCuando apagas las luces y tienes una iluminaci\u00f3n teatral en el escenario, le est\u00e1s sugiriendo a la congregaci\u00f3n que est\u00e1n aqu\u00ed para ver algo en lugar de participar\u201d. dice.<\/p>\n<p>Otro factor: el canto no siempre se ve como una estrategia de discipulado.<\/p>\n<p>Harland dice que los pastores y los ministros de m\u00fasica no siempre est\u00e1n en la misma p\u00e1gina. El ministerio de la m\u00fasica a veces hace lo suyo, en lugar de integrarse a la misi\u00f3n de la iglesia. Y los pastores, a su vez, no siempre valoran las contribuciones de los ministerios musicales. En cambio, la m\u00fasica a veces se ve como un calentamiento para el serm\u00f3n.<\/p>\n<p>\u201cCreo que algunos pastores dejaron de ver el ministerio de la m\u00fasica como una empresa de hacer disc\u00edpulos\u201d, dice Harland.<\/p>\n<p>Tambi\u00e9n muchas canciones, demasiado r\u00e1pido <\/p>\n<p>Luego est\u00e1 la abrumadora cantidad de canciones de adoraci\u00f3n disponibles para las iglesias.<\/p>\n<p>En el pasado, las iglesias ten\u00edan un n\u00famero limitado de canciones que pod\u00edan cantar. Un himnario puede tener alrededor de 700 canciones, y tal vez la mitad de ellas se usar\u00edan regularmente, dice Harland. Ahora los l\u00edderes de adoraci\u00f3n pueden elegir entre un n\u00famero casi ilimitado de canciones, y las canciones de adoraci\u00f3n m\u00e1s populares no duran mucho.<\/p>\n<p>\u201cA los m\u00fasicos les gusta eso porque tienden a aburrirse tocando las mismas canciones\u201d, dice Harland. . \u201cLes gusta tocar m\u00fasica nueva, y las congregaciones se pierden debido a un cambio constante de canciones\u201d.<\/p>\n<p>Entre 1995 y 1999, las canciones m\u00e1s populares de CCLI se mantuvieron bastante estables. En ese per\u00edodo, tres de las cinco canciones principales se mantuvieron entre las cinco principales, al igual que siete de las 10 principales y 20 de las 25 principales.<\/p>\n<p>Por el contrario, de 2011 a 2014 (los datos del \u00faltimo a\u00f1o est\u00e1 disponible), ninguna de las cinco canciones principales permaneci\u00f3 igual, y solo quedaron tres de las 10 canciones principales y 13 de las 25 principales.<\/p>\n<p>A Payne le preocupa el ritmo de la m\u00fasica de adoraci\u00f3n moderna. Aprender nuevas canciones requiere tiempo y repetici\u00f3n, dice. Se pregunta si los l\u00edderes de adoraci\u00f3n tratan de acelerar el proceso y terminan rindi\u00e9ndose demasiado pronto.<\/p>\n<p>\u201cEstamos constantemente aprendiendo canciones que tienen una vida \u00fatil limitada\u201d, dice Payne. \u00abEn unos meses se habr\u00e1n ido para siempre y estamos en otra cosa\u00bb.<\/p>\n<p>Nadie quiere sonar mal<\/p>\n<p>Tambi\u00e9n existe la realidad de que la mayor\u00eda de la gente no A menudo canto en p\u00fablico. La asistencia a la iglesia se ha vuelto menos frecuente, por lo que las personas tienen menos oportunidades de cantar en grupo durante un mes. Y el canto corporativo de cualquier tipo ha disminuido constantemente en la cultura estadounidense durante el \u00faltimo medio siglo.<\/p>\n<div style=\"clear:both;margin-top:0em;margin-bottom:1em\">\n<div class=\"centered -text-area\">\n<div class=\"centered-text\" style=\"float: left\">\n<div class=\"u53348b194beed547bf08a509139be202-content\">V\u00e9ase tambi\u00e9n&nbsp; \u00bfQu\u00e9 pasa si mi llamado causa dolor a mis hijos?<\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p>No es sorprendente que la gente no cante cuando Est\u00e1s en la iglesia, dice Keith Pipes, un veterano pastor de adoraci\u00f3n en Nashville. Cantar en un grupo puede resultar inc\u00f3modo en estos d\u00edas, dice.<\/p>\n<p>\u201cHay personas que nunca antes han cantado en un grupo organizado\u201d, dice. \u201cLuego se presentan en la iglesia y se les pide que canten con un par de cientos de personas. Pueden sentir que es realmente extra\u00f1o\u201d.<\/p>\n<p>Si las personas no se sienten c\u00f3modas con un himno o una canci\u00f3n de adoraci\u00f3n, es poco probable que canten, dice Rita Ruby, maestra de canto y l\u00edder de adoraci\u00f3n de Chicago. <\/p>\n<p>Cantar en p\u00fablico ya es bastante dif\u00edcil, dice ella. Cantar una canci\u00f3n que no conoces bien en p\u00fablico es peor.<\/p>\n<p>\u201cNadie quiere sonar horrible, especialmente con alguien sentado justo frente a ti\u201d, dice.<\/p>\n<p> Llevar a una audiencia no comprometida a un compromiso total no es una tarea f\u00e1cil. Puede tomar algo de tiempo, paciencia y entrenamiento intencional. No existe una f\u00f3rmula m\u00e1gica ni siquiera un estilo de adoraci\u00f3n que convenza a la gente de cantar.<\/p>\n<p>Afortunadamente, seg\u00fan Harland y otros pastores de adoraci\u00f3n, hay algunos pasos que los l\u00edderes de la iglesia pueden tomar para ayudar a las congregaciones a disfrutar del canto y participar.<\/p>\n<p>No cantes una canci\u00f3n de adoraci\u00f3n como la del CD<\/p>\n<p>Encontrar la clave correcta es esencial, dice Eubanks. La mayor\u00eda de los l\u00edderes de adoraci\u00f3n, dice, cantan en una clave que les queda bien, para que puedan dirigir con la mayor fuerza posible. Desafortunadamente, la gente no siempre puede seguirlos en esa clave. En su lugar, dice, elija una clave que tenga el mayor atractivo.<\/p>\n<p>\u201cUna canci\u00f3n estar\u00e1 en la clave de si bemol en el CD, pero la mayor\u00eda de la gente no puede cantar tan alto\u201d, dice. \u00abSi podemos reducirlo a la clave de G, estar\u00e1 bien para la mayor\u00eda de los rangos vocales\u00bb.<\/p>\n<p>T\u00f3mese m\u00e1s tiempo para ense\u00f1ar una nueva canci\u00f3n<\/p>\n<p>Pocas personas pueden escuchar una canci\u00f3n o himno una vez y est\u00e9 listo para cantar. As\u00ed que divide una canci\u00f3n en partes m\u00e1s peque\u00f1as, dice Pipes. T\u00f3mese unos minutos para cantar el coro un par de veces hasta que la gente se familiarice con \u00e9l. Luego agregue los versos.<\/p>\n<p>La repetici\u00f3n tambi\u00e9n es crucial. No tenga miedo de cantar una nueva canci\u00f3n dos o tres semanas seguidas hasta que la gente la aprenda, dice Pipes.<\/p>\n<p>D\u00edgales a los miembros de la iglesia lo que van a cantar con anticipaci\u00f3n<\/p>\n<p> Informe a los miembros de la iglesia con anticipaci\u00f3n qu\u00e9 canciones se cantar\u00e1n el domingo y proporcione enlaces a la m\u00fasica en un bolet\u00edn informativo de la iglesia, correo electr\u00f3nico o publicaci\u00f3n en el sitio web de la iglesia. Los feligreses pueden escuchar con anticipaci\u00f3n y estar listos para cantar.<\/p>\n<p>Deje que la congregaci\u00f3n gane<\/p>\n<p>Harland trata de incluir un himno o canci\u00f3n de adoraci\u00f3n favorita en cada servicio. Por lo general, es una canci\u00f3n que la congregaci\u00f3n conoce bien, una que tiene un tono c\u00f3modo y que a la congregaci\u00f3n le encanta cantar.<\/p>\n<p>Con suficientes victorias, la confianza de la congregaci\u00f3n crecer\u00e1. Adem\u00e1s, la gente aprender\u00e1 a confiar en los l\u00edderes de adoraci\u00f3n y estar\u00e1 dispuesta a seguirlos.<\/p>\n<p>Y no olvide el poder de un himno familiar, uno que est\u00e1 alojado en la memoria colectiva de una iglesia. Esas canciones pueden ayudar a una congregaci\u00f3n a cantar sin tener que preocuparse por recordar la letra o c\u00f3mo suena la melod\u00eda.<\/p>\n<p>Involucre a la congregaci\u00f3n<\/p>\n<p>\u00bfQuiere que la gente cante? Enciende las luces. Tener el sal\u00f3n ligeramente iluminado puede ayudar a la congregaci\u00f3n a participar en la adoraci\u00f3n.<\/p>\n<p>Frank Byers, director de medios de Bridge Church en Spring Hill, Tennessee, dice que los l\u00edderes de la iglesia pueden aprender de los m\u00fasicos seculares que intencionalmente toman medidas para conectarse con su audiencia.<\/p>\n<p>Una de esas formas es hacer contacto visual con los miembros de la audiencia. Por el contrario, dice, muchos l\u00edderes de adoraci\u00f3n cierran los ojos durante el servicio. Eso puede aislarlos de la congregaci\u00f3n.<\/p>\n<p>\u201cSi no los miro, \u00bfc\u00f3mo puedo recibir a la congregaci\u00f3n en el culto?\u201d dice.<\/p>\n<p>\u00c9l ve el papel del l\u00edder de adoraci\u00f3n como un facilitador, ayudando a la congregaci\u00f3n como un todo a conectarse con Dios a trav\u00e9s del canto y la adoraci\u00f3n.<\/p>\n<p>\u201cComo facilitador, mi trabajo es mantener la conversaci\u00f3n en marcha\u201d, dice. \u201cMi trabajo es facilitar esta conversaci\u00f3n entre Dios y Su pueblo\u201d.<\/p>\n<p>El lenguaje corporal tambi\u00e9n es importante cuando se dirige m\u00fasica, dice Payne. Los l\u00edderes de adoraci\u00f3n deben guiar a la congregaci\u00f3n a trav\u00e9s de una canci\u00f3n, d\u00e1ndoles pistas y alent\u00e1ndolos a cantar.<\/p>\n<p>\u201cAlgo tan simple como una sonrisa en su rostro puede darle permiso a la congregaci\u00f3n para cantar\u201d, dice.<\/p>\n<p> p&gt; <\/p>\n<p>\u201cUn buen liderazgo pastoral incluir\u00e1 decisiones sabias sobre cantos y din\u00e1micas, asegurando que los servicios creen un espacio para que la congregaci\u00f3n se escuche a s\u00ed misma, se escuche unos a otros y unan sus voces en el canto\u201d, escribe Cosper.<\/p>\n<p>Recuerda por qu\u00e9 cantas en primer lugar<\/p>\n<p>Los pastores, los l\u00edderes de adoraci\u00f3n y las congregaciones tienen que creer que el canto importa, o nunca querr\u00e1n cantar, dice Harland. Las iglesias cantan, dice, porque las Escrituras esperan que lo hagan.<\/p>\n<p>Tambi\u00e9n cantan porque es una forma poderosa de discipulado que une la verdad y la melod\u00eda e incrusta esa verdad en el alma de las personas.<\/p>\n<p>\u201c Melody ayuda a las personas a recordar\u201d, dice Harland. \u201cCantar es una herramienta poderosa para desarrollar seguidores de Cristo\u201d.<\/p>\n<p>Pipes dice que cantar tambi\u00e9n fortalece a la comunidad de creyentes.<\/p>\n<p>\u201cEn Efesios 5, Pablo escribe que debemos hablar con uno otro con salmos, himnos y c\u00e1nticos espirituales\u201d, dice Pipes.<\/p>\n<p>\u201cCuando nos reunimos en adoraci\u00f3n colectiva, no solo estamos cantando a Dios, estamos cantando acerca de Dios unos a otros. A trav\u00e9s del canto, podemos animar e instruir a nuestros hermanos y hermanas en Cristo. Nuestra adoraci\u00f3n a trav\u00e9s del canto tambi\u00e9n sirve como testimonio para los no cristianos que se sientan en nuestros bancos\u201d.<\/p>\n<p>Hay un gozo que viene de cantar en la iglesia, dice Payne. \u201cEdifica comunidad y ayuda a las iglesias a aprender verdades espirituales y vivirlas\u201d.<\/p>\n<p>Harland est\u00e1 de acuerdo: \u201cLa reuni\u00f3n del cuerpo de Cristo es un cuerpo que deber\u00eda estar cantando\u201d.<\/p>\n<div style=\"background-color:#f2f2f2;color:#32373c\" class=\"wp-block-genesis-blocks-gb-profile-box square gb-has-avatar gb-font-size-18 gb-block-profile gb -profile-columns\">\n<div class=\"gb-profile-column gb-profile-avatar-wrap\">\n<div class=\"gb-perfil-image-wrap\"><\/div>\n<\/div>\n<div class=\"columna-perfil-gb-envoltura-contenido-perfil-gb\">\n<h2 class=\"nombre-perfil-gb\" style=\"color:#32373c\">Bob Smietana<\/h2>\n<p class=\"perfil-gb -title\" style=\"color:#32373c\"><strong>@bobsmietana<\/strong><\/p>\n<div class=\"gb-profile-text\">\n<p>Bob es el ex escritor principal de Lifeway Research. En septiembre de 2018, se uni\u00f3 a Religion News Service, donde actualmente se desempe\u00f1a como escritor nacional.<\/p>\n<\/div>\n<ul class=\"gb-social-links\"><\/ul>\n<\/div>\n<\/div>\n<div class='yarpp yarpp-related yarpp-related-website yarpp-template-thumbnails'>\n<h3>Publicaciones relacionadas:<\/h3>\n<div class=\"yarpp-thumbnails-horizontal\"> \u00bfQu\u00e9 creen los pastores acerca de la \u00bfLibro de revelaci\u00f3n? <\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Bob Smietana Demasiadas canciones. No hay suficientes cantantes. Ese es el problema que enfrentan muchas congregaciones en estos d\u00edas, dice Tony Payne, l\u00edder de adoraci\u00f3n veterano y profesor asociado de m\u00fasica en Wheaton College. Ya sea que una iglesia toque himnos o las \u00faltimas canciones de adoraci\u00f3n, menos personas quieren cantar, \u00e9l dice. \u201cHay &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/encontrar-nuestra-voz-por-que-es-importante-el-declive-del-canto-congregacional-y-como-solucionarlo\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEncontrar nuestra voz: por qu\u00e9 es importante el declive del canto congregacional y c\u00f3mo solucionarlo\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3926","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/3926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=3926"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/3926\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=3926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=3926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=3926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}