{"id":3942,"date":"2022-07-26T00:01:59","date_gmt":"2022-07-26T05:01:59","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/por-que-nadie-quiere-una-fe-investigadora-no-una-heredada\/"},"modified":"2022-07-26T00:01:59","modified_gmt":"2022-07-26T05:01:59","slug":"por-que-nadie-quiere-una-fe-investigadora-no-una-heredada","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/por-que-nadie-quiere-una-fe-investigadora-no-una-heredada\/","title":{"rendered":"Por qu\u00e9 nadie quiere una fe investigadora, no una heredada"},"content":{"rendered":"<div class=\"entry-content\">\n<div class=\"wp-block-image is-style-default\"><\/div>\n<p>Por personal <\/p>\n<p>\u00bfC\u00f3mo pueden las iglesias llegar al creciente n\u00famero de personas sin religi\u00f3n, es decir, aquellas que afirman no tener afiliaci\u00f3n religiosa, en Estados Unidos? Dave y Jon Ferguson dicen que podr\u00eda ser tan simple como una oraci\u00f3n de nueve palabras.<\/p>\n<p>En su libro <em>C\u00f3mo encontrar el camino de regreso a Dios<\/em>, los hermanos y pastores de Chicago Community Christian Church Sostengo que todos est\u00e1n en un viaje hacia Dios, pero nuestros anhelos m\u00e1s profundos pueden enga\u00f1arnos.<\/p>\n<p>En una entrevista de dos partes, hablamos con Dave sobre el libro y c\u00f3mo llegar a aquellos que quieren ser espirituales sin Dios.<\/p>\n<p><strong>En el libro, usted habla de c\u00f3mo la mayor\u00eda de la gente a\u00fan cree en Dios, pero lo han \u00abolvidado\u00bb. \u00bfQu\u00e9 quieres decir con eso?<\/strong><\/p>\n<p><em>Dave Ferguson<\/em>: Las investigaciones nos dicen que 9 de cada 10 personas en los Estados Unidos creen en Dios, lo que significa que la gran mayor\u00eda todav\u00eda cree Dios realmente existe.<\/p>\n<div class='code-block code-block-1' style='margin: 8px 0'> <\/div>\n<p>El desaf\u00edo de ayudar a las personas a encontrar el camino de regreso a Dios no es creer; el desaf\u00edo es que, si bien la abrumadora mayor\u00eda de las personas tienen una creencia cognitiva en Dios, no sienten ninguna conexi\u00f3n con Dios. La gente de hoy no sabe c\u00f3mo conectarse con Dios o c\u00f3mo encontrarlo.<\/p>\n<p><strong>Usted escribe que hay un patr\u00f3n universal de c\u00f3mo es un viaje en la direcci\u00f3n de Dios. \u00bfPodr\u00eda describir brevemente ese viaje com\u00fan?<\/strong><\/p>\n<p><em>Dave<\/em>: Al considerar nuestras propias experiencias, as\u00ed como las historias de miles de personas que han encontrado su camino de regreso a Dios en Community Christian Church, vimos muchas similitudes.<\/p>\n<p>Era casi como un campo de hierba donde la gente lo hab\u00eda cruzado, y con el tiempo se puede ver un camino muy transitado donde esas personas ha viajado. As\u00ed es como comenzaron a surgir los \u201cCinco despertares\u201d que forman la base del libro.<\/p>\n<p>Tambi\u00e9n encontramos estos cinco despertares en la historia \u00e9pica de Jes\u00fas del hijo pr\u00f3digo. Estos despertares no son solo c\u00f3mo encontrar tu camino hacia Dios por primera vez, son c\u00f3mo encuentras tu camino de regreso a Dios una y otra vez y te mantienes cerca de \u00c9l a lo largo de tu vida.<\/p>\n<p> Nuestro libro entreteje la historia del hijo pr\u00f3digo con docenas de historias de la vida real de personas como t\u00fa y yo que han encontrado el camino de regreso a Dios.<\/p>\n<p><strong>\u00bfCu\u00e1les son algunos errores comunes que cometen los cristianos y las iglesias? para tratar de llegar a los ningunos de esta cultura?<\/strong><\/p>\n<div style=\"clear:both;margin-top:0em;margin-bottom:1em\">\n<div class=\"centered-text- area\">\n<div class=\"centered-text\" style=\"float: left\">\n<div class=\"ua9b75302d63425f709f9f1ed1e06cbeb-content\">V\u00e9ase tambi\u00e9n&nbsp; El poder de los momentos ordinarios<\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p><em>Dave<\/em>: todos hemos He visto innumerables informes que indican que uno de los segmentos de personas de m\u00e1s r\u00e1pido crecimiento son los nones, aquellos que marcan \u00abninguno\u00bb cuando se les pregunta sobre su afiliaci\u00f3n religiosa. El mayor error que cometen las iglesias con respecto a los nones es suponer que <em>no<\/em> est\u00e1n interesados en Dios o que <em>no<\/em> est\u00e1n interesados en la espiritualidad. \u00a1Esto no es absolutamente cierto!<\/p>\n<p>Recuerde, el 92 por ciento de todos los estadounidenses todav\u00eda dicen que creen en Dios. \u00a1Ninguno est\u00e1 interesado! Son simplemente personas que crecieron con una etiqueta religiosa particular (metodista, presbiteriana, cat\u00f3lica, etc.) y ya no se identifican con esa etiqueta o marca de espiritualidad.<\/p>\n<p>Las iglesias y los cristianos deben entender a los nones como personas que est\u00e1n en un viaje espiritual, dejando atr\u00e1s todas las etiquetas anteriores y sin haber encontrado a\u00fan una etiqueta con la que puedan identificarse.<\/p>\n<p>En lugar de conformarse con una fe heredada, nones son personas que persiguen una fe \u00abinvestigadora\u00bb donde quieren descubrir a Dios por s\u00ed mismos. La iglesia debe abordar a los nones como un grupo demogr\u00e1fico de personas que intentan encontrar el camino de regreso a Dios.<\/p>\n<p><strong>A pesar del alejamiento de la religi\u00f3n organizada, lo \u00faltimo de Pew Research&nbsp;dice que m\u00e1s de 6 de cada 10 Los estadounidenses (62 por ciento) dicen que experimentan asombro al menos una vez al mes. Eso es un aumento del 53 por ciento en 2007. \u00bfQu\u00e9 crees que dice eso sobre nuestra composici\u00f3n espiritual como humanos?<\/strong><\/p>\n<p><em>Dave<\/em>: Todos anhelamos una experiencia trascendente con Dios y no s\u00f3lo una verdad proposicional acerca de Dios. Durante demasiado tiempo, gran parte de la iglesia ha insistido en ofrecer a las personas solo una propuesta moderna acerca de Dios en lugar de una experiencia posmoderna o incluso premoderna de Dios.<\/p>\n<p>La gente anhela amor, prop\u00f3sito y significado. , y es una relaci\u00f3n con Dios lo que nos brinda la experiencia y la maravilla del amor real, un prop\u00f3sito claro y un significado genuino.<\/p>\n<p>La gente de hoy est\u00e1 m\u00e1s abierta a una experiencia con Dios de lo que lo ha estado en muchas d\u00e9cadas. . Los cristianos deben alentar la oraci\u00f3n y la b\u00fasqueda sabiendo que Dios aparecer\u00e1 con se\u00f1ales y prodigios.<\/p>\n<p><em>En la segunda parte de la entrevista, Dave Ferguson comparte los cinco \u00abdespertares\u00bb, dice que ayuda a los vagabundos a encontrar su camino. de vuelta a Dios.<\/em><\/p>\n<div class='yarpp yarpp-related yarpp-related-website yarpp-template-thumbnails'>\n<h3>Publicaciones relacionadas:<\/h3>\n<div class=\"yarpp- thumbnails-horizontal\"> \u00bfQu\u00e9 creen los pastores sobre el fin de los tiempos? \u00bfQu\u00e9 creen los pastores sobre el libro de Apocalipsis? 3 formas de llegar a personas no religiosas en su comunidad <\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por personal \u00bfC\u00f3mo pueden las iglesias llegar al creciente n\u00famero de personas sin religi\u00f3n, es decir, aquellas que afirman no tener afiliaci\u00f3n religiosa, en Estados Unidos? Dave y Jon Ferguson dicen que podr\u00eda ser tan simple como una oraci\u00f3n de nueve palabras. En su libro C\u00f3mo encontrar el camino de regreso a Dios, los hermanos &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/por-que-nadie-quiere-una-fe-investigadora-no-una-heredada\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abPor qu\u00e9 nadie quiere una fe investigadora, no una heredada\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3942","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/3942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=3942"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/3942\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=3942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=3942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=3942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}