{"id":3950,"date":"2022-07-26T00:02:15","date_gmt":"2022-07-26T05:02:15","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/7-caracteristicas-de-las-iglesias-pequenas-saludables\/"},"modified":"2022-07-26T00:02:15","modified_gmt":"2022-07-26T05:02:15","slug":"7-caracteristicas-de-las-iglesias-pequenas-saludables","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/7-caracteristicas-de-las-iglesias-pequenas-saludables\/","title":{"rendered":"7 Caracter\u00edsticas de las iglesias peque\u00f1as saludables"},"content":{"rendered":"<div class=\"entry-content\">\n<div class=\"wp-block-image\"><\/div>\n<p><em>Por Thom S. Rainer<\/em> <\/p>\n<p>El tama\u00f1o de una iglesia no siempre es un indicador de su salud. Uno podr\u00eda argumentar que si una iglesia alcanzara efectivamente a la gente, no permanecer\u00eda peque\u00f1a. Pero ese no es siempre el caso.<\/p>\n<p>Muchas iglesias peque\u00f1as est\u00e1n en lugares con una base de poblaci\u00f3n peque\u00f1a o \u00e1reas de transici\u00f3n. Pero estas comunidades todav\u00eda necesitan iglesias, y muchos l\u00edderes fieles est\u00e1n sirviendo bien a esas comunidades.<\/p>\n<p>Algunas iglesias peque\u00f1as no son efectivas m\u00e1s all\u00e1 de los muros de la iglesia. Pero tampoco lo son algunas iglesias medianas, iglesias grandes o megaiglesias. En pocas palabras, la eficacia no siempre est\u00e1 relacionada con el tama\u00f1o. No importa el tama\u00f1o, es importante medir la salud de su iglesia.<\/p>\n<p>Aqu\u00ed hay siete caracter\u00edsticas de las iglesias saludables que se relacionan espec\u00edficamente con las iglesias peque\u00f1as pero que indican efectividad sin importar el tama\u00f1o.<\/p>\n<p> 1. Los pastores de iglesias saludables modelan el evangelismo. No hay iglesias evangel\u00edsticas de ning\u00fan tama\u00f1o en las que el pastor no est\u00e9 liderando la evangelizaci\u00f3n. El evangelio es central en las iglesias saludables.<\/p>\n<div class='code-block code-block-1' style='margin: 8px 0'> <\/div>\n<p>Compartir las buenas nuevas es natural y consecuente. Pero los l\u00edderes de estas iglesias no asumen simplemente que se est\u00e1 llevando a cabo la evangelizaci\u00f3n. Hay recordatorios constantes de la prioridad del evangelismo.<\/p>\n<p>2. Las iglesias sanas se reproducen. Cualquier tipo de organismo sano se reproduce. La reproducci\u00f3n puede ocurrir de varias maneras, pero la m\u00e1s com\u00fan entre las iglesias m\u00e1s peque\u00f1as son las clases de escuela dominical o los grupos peque\u00f1os.<\/p>\n<p>El crecimiento no tiene que ser exponencial; una nueva clase al a\u00f1o exhibir\u00eda crecimiento. \u00bfCu\u00e1l es su estrategia para crear clases de escuela dominical adicionales o grupos peque\u00f1os? \u00bfY c\u00f3mo est\u00e1 desarrollando nuevos l\u00edderes?<\/p>\n<p>3. Tienen una presencia comunitaria misional. Las iglesias saludables tienen la intenci\u00f3n de ministrar a la comunidad local y conectarse con personas fuera de la iglesia. Aman y sirven a su comunidad. Tienen relaciones profundas en su comunidad.<\/p>\n<p>Las iglesias deben encontrar las necesidades de la comunidad que no se est\u00e1n satisfaciendo y luego satisfacer esas necesidades. \u00bfQu\u00e9 dir\u00eda la gente de su comunidad acerca de su iglesia?<\/p>\n<p>4. Las iglesias peque\u00f1as y saludables aprovechan sus fortalezas. Una de las fortalezas de una iglesia peque\u00f1a son las relaciones cercanas, todos conocen a todos, as\u00ed que aprov\u00e9chalo para tu beneficio. Pero tenga cuidado de no permitir que la fuerza de esas relaciones atraiga el enfoque de su iglesia hacia adentro. No olvide comunicarse con los reci\u00e9n llegados.<\/p>\n<div style=\"clear:both;margin-top:0em;margin-bottom:1em\">\n<div class=\"centered-text-area\">\n<div class=\"centered-text\" style=\"float: left\">\n<div class=\"u2200cb7422520d51fba44da40dbf8cb9-content\">Ver tambi\u00e9n&nbsp; 4 cambios que har\u00eda si pudiera volver a empezar el ministerio<\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p>5. Las iglesias saludables hacen disc\u00edpulos. Una ventaja de las iglesias m\u00e1s peque\u00f1as es la capacidad de ver qui\u00e9n est\u00e1 siendo discipulado y qui\u00e9n no. Es esencial para cualquier iglesia tener un proceso claro para hacer disc\u00edpulos, uno que mueva a las personas hacia mayores niveles de compromiso con Jesucristo. Un gran recurso para el discipulado es Disciples Path (Lifeway.com\/DisciplesPath).<\/p>\n<p>6. Estas iglesias hacen menos ministerios pero los hacen mejor. Las iglesias peque\u00f1as y saludables se dan cuenta de que no pueden ser todo para todas las personas. As\u00ed que los l\u00edderes de estas congregaciones se enfocan en hacer menos ministerios pero haciendo esos pocos mejor de lo que podr\u00edan con una sobreabundancia de actividades.<\/p>\n<p>7. La oraci\u00f3n es el alma de las iglesias saludables. Esto es cierto para iglesias de cualquier tama\u00f1o. El liderazgo enfatiza la importancia de la oraci\u00f3n y dirige a la congregaci\u00f3n regularmente en momentos de oraci\u00f3n colectiva.<\/p>\n<p>Me doy cuenta de que muchas iglesias, especialmente las iglesias peque\u00f1as, est\u00e1n luchando. Pero estoy muy consciente de que Dios est\u00e1 haciendo un gran trabajo en muchas congregaciones. He visto iglesias con una asistencia promedio de 80 personas que exhiben cada una de estas caracter\u00edsticas saludables.<\/p>\n<p>Entonces, para todos ustedes que trabajan y sirven fielmente en iglesias peque\u00f1as, acepten mi m\u00e1s profunda gratitud por todo lo que hacen para Su gloria. . Has elegido volcar tu vida en un ministerio que recibe poco reconocimiento terrenal. Gracias por su fiel ministerio.<\/p>\n<p>En Lifeway nos esforzamos por proporcionar recursos para iglesias de todos los tama\u00f1os y asociarnos con ellas en su misi\u00f3n de hacer disc\u00edpulos. Espero que se conecte con nosotros en Lifeway.com\/Leadership, donde encontrar\u00e1 herramientas de liderazgo y enlaces a recursos para todas las \u00e1reas del ministerio dentro de la vida de una iglesia.<\/p>\n<div style=\"color:#32373c\" class=\"wp-block-genesis-blocks-gb-profile-box square gb-has-avatar gb-font-size-18 gb-block-profile gb-profile-columns\">\n<div class=\"gb-perfil-columna gb-perfil-avatar-envoltura\">\n<div class=\"gb-perfil-imagen-envoltura\"><\/div>\n<\/div>\n<div class=\"gb-perfil -column gb-perfil-contenido-envoltura\">\n<h2 class=\"gb-perfil-nombre\" style=\"color:#32373c\">Thom S. Rainer<\/h2>\n<p class=\"gb-perfil-t\u00edtulo\" style=\"color:#32373c\"><strong>@ThomRainer<\/strong><\/p>\n<div class=\"gb-profile-text\">\n<p>Thom es el ex presidente y director ejecutivo de Lifeway Christian Resources y autor de <em>Autopsia de una iglesia fallecida<\/em>.<\/p>\n<\/div>\n<ul class=\"gb-social-links\"><\/ul>\n<\/div>\n<\/div>\n<div class='yarpp relacionado con yarpp sitio web relacionado con yarpp yarpp-template-thumbnails'>\n<h3>Publicaciones relacionadas:<\/h3>\n<div class=\"yarpp-thumbnail s-horizontal\"> \u00bfQu\u00e9 creen los pastores sobre el fin de los tiempos? \u00bfQu\u00e9 creen los pastores sobre el libro de Apocalipsis? 3 formas de llegar a personas no religiosas en su comunidad <\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Thom S. Rainer El tama\u00f1o de una iglesia no siempre es un indicador de su salud. Uno podr\u00eda argumentar que si una iglesia alcanzara efectivamente a la gente, no permanecer\u00eda peque\u00f1a. Pero ese no es siempre el caso. Muchas iglesias peque\u00f1as est\u00e1n en lugares con una base de poblaci\u00f3n peque\u00f1a o \u00e1reas de transici\u00f3n. &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/7-caracteristicas-de-las-iglesias-pequenas-saludables\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab7 Caracter\u00edsticas de las iglesias peque\u00f1as saludables\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3950","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/3950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=3950"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/3950\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=3950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=3950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=3950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}