{"id":3995,"date":"2022-07-26T00:03:33","date_gmt":"2022-07-26T05:03:33","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/la-mayoria-de-los-lectores-estadounidenses-de-la-biblia-todavia-prefieren-la-version-king-james\/"},"modified":"2022-07-26T00:03:33","modified_gmt":"2022-07-26T05:03:33","slug":"la-mayoria-de-los-lectores-estadounidenses-de-la-biblia-todavia-prefieren-la-version-king-james","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/la-mayoria-de-los-lectores-estadounidenses-de-la-biblia-todavia-prefieren-la-version-king-james\/","title":{"rendered":"La mayor\u00eda de los lectores estadounidenses de la Biblia todav\u00eda prefieren la versi\u00f3n King James"},"content":{"rendered":"<div class=\"entry-content\">\n<p><em>Por Bob Smietana<\/em><\/p>\n<p>Cuando se trata de la Biblia, King James todav\u00eda gobierna.<\/p>\n<p>La venerable KVJ, que ahora tiene 403 a\u00f1os, es la Biblia favorita de m\u00e1s de la mitad (55 por ciento) de los lectores estadounidenses de la Biblia, seg\u00fan \u00abThe Bible in American Life\u00bb, un nuevo informe del Centro para el Estudio de la Religi\u00f3n y la Cultura Estadounidense.<\/p>\n<p>Los investigadores encontraron que aproximadamente la mitad de los estadounidenses dicen haber le\u00eddo la Biblia en el \u00faltimo a\u00f1o.<\/p>\n<p>Entre los que se describen a s\u00ed mismos Lectores de la Biblia, el 55 por ciento dice que prefiere la KJV, muy por delante de la segunda versi\u00f3n m\u00e1s le\u00edda: la Nueva Versi\u00f3n Internacional con un 19 por ciento.<\/p>\n<p>Alrededor del 40 por ciento de las congregaciones usan la KJV en la adoraci\u00f3n.<\/p>\n<div class='code-block code-block-1' style='margin: 8px 0'> <\/div>\n<p>\u201cClaramente, entonces, la Biblia King James est\u00e1 lejos de estar muerta\u201d, escribieron los investigadores.<br \/> Jeremy Howard, editor de Biblias en ingl\u00e9s y libros de referencia con B&amp;H Publishing , dice que una de las razones de la popularidad de la versi\u00f3n King James es que fue la primera traducci\u00f3n al ingl\u00e9s que se difundi\u00f3 ampliamente. Las iglesias comenzaron a usarlo y lo mantuvieron porque satisfac\u00eda las necesidades de los creyentes.<br \/> Luego est\u00e1 el lenguaje.<\/p>\n<p>\u201cMejor que cualquier otra traducci\u00f3n de la Biblia, la KJV transmite una sensaci\u00f3n de majestuosidad y formalidad, \u00bb \u00e9l dijo. \u201cEl lenguaje es hermoso y misterioso para los lectores modernos. La KJV est\u00e1 completamente fuera de nuestra experiencia. En realidad, esto puede servir para sosegar al lector, invit\u00e1ndolo a comprometerse seriamente con el texto de las Escrituras\u201d.<\/p>\n<p>Howard dijo que las traducciones m\u00e1s contempor\u00e1neas cumplen un papel importante en la iglesia. Pero tambi\u00e9n lo hace la versi\u00f3n King James.<\/p>\n<p>\u201cLas cosas profundas de Dios y la condici\u00f3n humana invitan al uso de las mejores im\u00e1genes y belleza que el lenguaje tiene para ofrecer\u201d, dijo. \u00abHay un lugar para el ingl\u00e9s simple y claro que refleja el uso contempor\u00e1neo\u00bb.<\/p>\n<p>\u00c9l explic\u00f3 por qu\u00e9 ese podr\u00eda ser el caso &#8220;Al igual que no querr\u00edas que un profesor de ingl\u00e9s del siglo XVII ense\u00f1e a tu ni\u00f1o c\u00f3mo escribir, es posible que no desee que un traductor de KJV ense\u00f1e la clase de escuela dominical de su hijo debido a la barrera del idioma\u201d, dijo. \u201cPero para el lector de la Biblia que quiere emocionarse no solo por las verdades eternas sino tambi\u00e9n por la belleza eterna, la KJV es la elecci\u00f3n obvia\u201d.<\/p>\n<div style=\"clear:both;margin-top:0em\">\n<div class=\"centered-text-area\">\n<div class=\"centered-text\" style=\"float: left\">\n<div class=\"uba62e28ec7bdc99f5925375c02994c7d-content\">Ver tambi\u00e9n&nbsp; Por qu\u00e9 los pastores deben reconocer sus propias necesidades<\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p>El estudio encontr\u00f3 que los fan\u00e1ticos de King James ten\u00edan menos probabilidades de lea la Biblia semanalmente.<\/p>\n<p>El setenta por ciento de los que leen la NVI lo hacen semanalmente. Ese n\u00famero se reduce a poco m\u00e1s de la mitad (54 por ciento) para los lectores de KJV.<\/p>\n<p>Entre los otros hallazgos del estudio:<\/p>\n<ul>\n<li>Los afroamericanos, las mujeres, las personas mayores y los sure\u00f1os son m\u00e1s propensos a para leer la Biblia.<\/li>\n<li>Una de cada tres personas que leen la Biblia (33 por ciento) lo hace en Internet. Uno de cada cinco (22 por ciento) usa un lector electr\u00f3nico.<\/li>\n<li>Las primeras l\u00edneas del Salmo 23 son los vers\u00edculos b\u00edblicos m\u00e1s populares, seguidas de Juan 3:16.<\/li>\n<li>Alrededor de la mitad de Los lectores de la Biblia (48 por ciento) dicen que han memorizado un vers\u00edculo de la Biblia este a\u00f1o.<\/li>\n<li>La mayor\u00eda de las personas leen la Biblia para oraci\u00f3n personal y devoci\u00f3n (72 por ciento) en lugar de orientaci\u00f3n sobre temas como la pobreza y la guerra (23 por ciento). ) o c\u00f3mo obtener riqueza (22 por ciento).<\/li>\n<li>Alrededor de la mitad de los lectores de la Biblia dicen que recurren al clero (53 por ciento), a los comentaristas (51 por ciento) o a los grupos de estudio de la Biblia (49 por ciento) para ayudarlos a comprender la Biblia. Solo el 29 por ciento busca ayuda en Internet con las Escrituras.<\/li>\n<\/ul>\n<p>Investigadores de la Universidad de Indiana-Universidad Purdue de Indian\u00e1polis esperaban que su estudio arrojara algo de luz sobre los estadounidenses&#8230; relaci\u00f3n complicada con la Biblia.<\/p>\n<p>La mayor\u00eda de los estadounidenses aman la Biblia, pero no saben mucho al respecto, dicen.<br \/> \u201cHay una paradoja en el cristianismo estadounidense\u201d, escriben los autores del estudio. <\/p>\n<p>\u201cSeg\u00fan la Encuesta social general, casi ocho de cada diez estadounidenses consideran que la Biblia es la palabra literal de Dios o que es inspirada por Dios. Al mismo tiempo, otras encuestas han revelado, y libros recientes han analizado, brechas sorprendentes en la alfabetizaci\u00f3n b\u00edblica de los estadounidenses\u201d.<\/p>\n<h3>Publicaciones relacionadas:<\/h3>\n<div class=\"yarpp-thumbnails-horizontal\"> \u00bfQu\u00e9 creen los pastores sobre el fin de los tiempos? \u00bfQu\u00e9 creen los pastores sobre el libro de Apocalipsis? 3 formas de llegar a personas no religiosas en su comunidad <\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Bob Smietana Cuando se trata de la Biblia, King James todav\u00eda gobierna. La venerable KVJ, que ahora tiene 403 a\u00f1os, es la Biblia favorita de m\u00e1s de la mitad (55 por ciento) de los lectores estadounidenses de la Biblia, seg\u00fan \u00abThe Bible in American Life\u00bb, un nuevo informe del Centro para el Estudio de &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/la-mayoria-de-los-lectores-estadounidenses-de-la-biblia-todavia-prefieren-la-version-king-james\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa mayor\u00eda de los lectores estadounidenses de la Biblia todav\u00eda prefieren la versi\u00f3n King James\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3995","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/3995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=3995"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/3995\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=3995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=3995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=3995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}