{"id":4008,"date":"2022-07-26T00:03:55","date_gmt":"2022-07-26T05:03:55","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/6-claves-para-una-predicacion-que-cambia-vidas\/"},"modified":"2022-07-26T00:03:55","modified_gmt":"2022-07-26T05:03:55","slug":"6-claves-para-una-predicacion-que-cambia-vidas","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/6-claves-para-una-predicacion-que-cambia-vidas\/","title":{"rendered":"6 Claves para una predicaci\u00f3n que cambia vidas"},"content":{"rendered":"<div class=\"entry-content\">\n<p><em>Por Dave Earley<\/em><\/p>\n<p>Pocas personas han predicado alguna vez con el poder transformador y practicidad de Juan el Bautista. Cuando predic\u00f3, se cambiaron vidas. Del serm\u00f3n de muestra descrito en Lucas 3:7\u20139 podemos aprender seis aspectos significativos de la ense\u00f1anza de la Palabra con practicidad y poder.<\/p>\n<ol>\n<li>Escuche atentamente la Palabra de Dios. Antes de que Juan pudiera dar el poderoso mensaje registrado en Lucas 3:7\u20139, ten\u00eda que obtener el mensaje de alguna parte. Esta secci\u00f3n comienza con las palabras: \u201cLa palabra de Dios vino a Juan, hijo de Zacar\u00edas, en el desierto\u201d (Lucas 3:2 NVI). Juan tuvo un gran poder en su predicaci\u00f3n porque recibi\u00f3 su mensaje de Dios. Nunca subestimes el poder de un mensaje dado por Dios. Nada le da a un predicador m\u00e1s confianza basada en Dios y audacia ungida por el Esp\u00edritu que saber que tiene un mensaje de Dios para su iglesia. Juan recibi\u00f3 su mensaje de cambio de vida de parte de Dios. Sin la Palabra del Se\u00f1or, \u00e9l no ten\u00eda nada que decir, y nosotros tampoco.<\/li>\n<li><strong>Aclare Memorablemente la Verdad Principal. <\/strong>Recorri\u00f3 todos los alrededores del Jord\u00e1n, predicando un bautismo de arrepentimiento para el perd\u00f3n de los pecados. . . . Entonces dijo a las multitudes que sal\u00edan para ser bautizadas por \u00e9l, . . . \u201cProducir fruto consistente con el arrepentimiento.\u201d (Lucas 3:3,7\u20138) El mensaje de Juan era muy simple. \u00a1Arrepentirse! Su serm\u00f3n ten\u00eda un punto principal: arrepentirse; una gran idea: arrepentirse; y un punto principal de aplicaci\u00f3n: arrepentirse. No hay nada m\u00e1s claro, m\u00e1s simple y m\u00e1s poderoso que eso. Nunca subestimes el poder de la simplicidad.<\/li>\n<li><strong>Pregunta de manera convincente. <\/strong>En su serm\u00f3n de alto impacto sobre el arrepentimiento, John atraves\u00f3 el desorden religioso en la vida de sus oyentes haciendo varias preguntas convincentes. \u00bfQu\u00e9 crees que haces desliz\u00e1ndote hasta el r\u00edo? \u00bfCrees que un poco de agua en tu piel de serpiente desviar\u00e1 el juicio de Dios?\u201d y \u201cLo que cuenta es tu vida. \u00bfEst\u00e1 verde y floreciendo? Dios us\u00f3 estas preguntas de sondeo para convencer profundamente a las multitudes de su pecado e impulsarlas a la acci\u00f3n. Nunca subestimes el impacto de una pregunta bien formulada y oportuna.<\/li>\n<li>Desaf\u00eda directamente. John le dio a su audiencia un desaf\u00edo directo. \u00c9l dijo: \u201cHaced fruto digno de arrepentimiento\u201d (Lucas 3:8 NVI). En otras palabras, \u201cLas palabras ya no son suficientes. Ustedes dicen que son verdaderos temerosos de Dios, demu\u00e9strenlo\u201d. En otras palabras, \u00abPon o c\u00e1llate\u00bb. Esto es lo que separa un serm\u00f3n de una conferencia y un comunicador poderoso de un profesor aburrido. En el mensaje sobre la oraci\u00f3n que mencion\u00e9 anteriormente, en realidad me detuve en un punto, le ped\u00ed a la audiencia que uno por uno me mirara a los ojos y dijera: \u201cTengo el desaf\u00edo de orar m\u00e1s el resto de este a\u00f1o que nunca en mi vida\u201d. vida.\u00bb Nunca subestime el poder de un desaf\u00edo directo.<\/li>\n<li><strong>Aplique espec\u00edficamente. <\/strong>El mensaje de John pas\u00f3 de muy bueno a excelente despu\u00e9s de su desaf\u00edo. Esto se debe a que no solo les dijo lo que Dios dijo: arrepentirse; qu\u00e9 hacer\u2014demostrar que se han arrepentido; les dijo c\u00f3mo hacerlo. \u00c9l les dio una aplicaci\u00f3n muy espec\u00edfica. Cada pasaje de la Escritura tiene una interpretaci\u00f3n principal, pero muchas aplicaciones. Los sermones tambi\u00e9n deben tener un punto principal de verdad que conduzca a un desaf\u00edo claro que naturalmente conduzca a varios puntos de aplicaci\u00f3n. La predicaci\u00f3n efectiva evoca cambios en el oyente. Es m\u00e1s que dar informaci\u00f3n. Es un medio de transformaci\u00f3n. La transformaci\u00f3n nunca ocurre sin la aplicaci\u00f3n.<\/li>\n<li>Al final siempre apunta a Jes\u00fas. El ministerio de Juan consist\u00eda principalmente en preparar el camino del Se\u00f1or (Lucas 3:4). El resultado final de toda predicaci\u00f3n centrada en el evangelio es exaltar a Jes\u00fas y se\u00f1alarle a la gente. De hecho, al final de su mensaje, Juan expl\u00edcita e intencionalmente se\u00f1al\u00f3 a la multitud de regreso a Jes\u00fas, diciendo: \u201cYo los bautizo con agua, pero viene uno que es m\u00e1s poderoso que yo. No soy digno de desatar la correa de sus sandalias\u201d (Lucas 3:16). Nunca subestimes el poder de Jes\u00fas.<\/li>\n<\/ol>\n<div style=\"clear:both;margin-top:0em;margin-bottom:1em\">\n<div class=\"centered-text-area\">\n<div class=\"centered-text\" style=\"float: left\">\n<div class=\"ue817a26e03c690f03fb3b068b6946950-content\">V\u00e9ase tambi\u00e9n&nbsp; Lo que deben hacer las iglesias para llegar a la Generaci\u00f3n Z<\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p>T\u00fa y yo no podemos salvar un alma. No podemos cambiar una vida. No podemos curar un coraz\u00f3n roto. No podemos arreglar un matrimonio. No podemos liberar a alguien de la adicci\u00f3n.<br \/> Pero Jes\u00fas s\u00ed puede.<\/p>\n<p>La comunicaci\u00f3n poderosa, que cambia la vida y de alto impacto es la predicaci\u00f3n que lleva a las personas a Jes\u00fas.<\/p>\n<div class='yarpp yarpp-related yarpp-related-website yarpp-template-thumbnails'>\n<h3>Publicaciones relacionadas:<\/h3>\n<div class=\"yarpp-thumbnails-horizontal\"> \u00bfQu\u00e9 creen los pastores sobre el fin de los tiempos? \u00bfQu\u00e9 creen los pastores sobre el libro de Apocalipsis? 3 formas de llegar a personas no religiosas en su comunidad <\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Dave Earley Pocas personas han predicado alguna vez con el poder transformador y practicidad de Juan el Bautista. Cuando predic\u00f3, se cambiaron vidas. Del serm\u00f3n de muestra descrito en Lucas 3:7\u20139 podemos aprender seis aspectos significativos de la ense\u00f1anza de la Palabra con practicidad y poder. Escuche atentamente la Palabra de Dios. Antes de &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/6-claves-para-una-predicacion-que-cambia-vidas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab6 Claves para una predicaci\u00f3n que cambia vidas\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4008","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=4008"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4008\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=4008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=4008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=4008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}