{"id":4015,"date":"2022-07-26T00:04:08","date_gmt":"2022-07-26T05:04:08","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/7-mentiras-que-los-pastores-suelen-creer\/"},"modified":"2022-07-26T00:04:08","modified_gmt":"2022-07-26T05:04:08","slug":"7-mentiras-que-los-pastores-suelen-creer","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/7-mentiras-que-los-pastores-suelen-creer\/","title":{"rendered":"7 mentiras que los pastores suelen creer"},"content":{"rendered":"<div class=\"entry-content\">\n<p><em>Por Ron Edmondson<\/em><\/p>\n<p>Mi coraz\u00f3n est\u00e1 para el pastor. Tal vez se deba al hecho de que pas\u00e9 m\u00e1s a\u00f1os como laico \u2014di\u00e1cono y maestro de escuela dominical\u2014 y ahora como pastor. Ahora me doy cuenta de lo mucho que no entend\u00eda sobre el puesto. El papel tiene muchas m\u00e1s expectativas y presiones de lo que imaginaba anteriormente. Siempre am\u00e9 y apoy\u00e9 al pastor, pero mirando hacia atr\u00e1s, desear\u00eda haber sido un mejor amigo del pastor.<\/p>\n<p>Una de las otras realidades, y es bastante aleccionador para m\u00ed. , es lo aislados que se sienten muchos pastores de la gente de su congregaci\u00f3n. El aislamiento casi siempre parece conducir a una incomprensi\u00f3n de la realidad. En esencia, y este es el problema y el prop\u00f3sito de esta publicaci\u00f3n, si no tenemos cuidado, podemos comenzar a creer mentiras sobre nosotros mismos o nuestros ministerios. (Eso incluso parece tener precedencia b\u00edblica: creer mentiras nos meti\u00f3 en problemas desde el principio).<\/p>\n<p>Aqu\u00ed hay 7 mentiras que a menudo creemos como pastores:<\/p>\n<ol>\n<li><strong> Tengo esto<\/strong> &#8211; Al enemigo le encanta cuando comenzamos a pensar que hemos descubierto completamente la vida o el ministerio. \u00c9l nos ama para depositar total confianza en nosotros mismos. La confianza en s\u00ed mismo, si no se controla, puede conducir a la arrogancia, un sentido de superioridad y una falta de dependencia de Dios.<\/li>\n<li><strong>Eso no me doli\u00f3<\/strong> &#8211; A veces pretendemos que lo que la persona nos dijo o nos hizo, no duele. Incluso podemos espiritualizarlo porque llevamos la &#8220;armadura de Dios&#8221;. En realidad, la mayor\u00eda de los pastores que conozco (incluido este) tienen sentimientos tiernos a veces, algunos d\u00edas m\u00e1s que otros. Somos humanos. La madurez nos ayuda a procesar las cosas m\u00e1s r\u00e1pido, pero nunca superamos cierta vulnerabilidad cuando trabajamos con personas.<\/li>\n<li><strong>Estoy por encima de eso<\/strong> &#8211; Si un pastor alguna vez piensa &#8220;eso&#8217;es demasiado peque\u00f1o para que yo me preocupe,&#8221; Est\u00e9 atento a que comiencen los fuegos artificiales. El diablo habr\u00e1 puesto unos puntos en el tablero. Igualmente peligroso, cuando nosotros, como pastores, creemos que estamos por encima de cualquier tipo de tentaci\u00f3n, tenemos toda la atenci\u00f3n del diablo.<\/li>\n<li><strong>Yo tengo el control<\/strong> &amp;# 8211; Ser\u00eda f\u00e1cil despedir a \u00e9ste con una fuerte respuesta espiritual. Por supuesto, Jes\u00fas tiene el control. Esperemos que cada pastor creyente en la Biblia que lea este &#8220;Amens&#8221; a esa verdad. Pero, \u00bfcu\u00e1ntas veces creemos que tenemos m\u00e1s autoridad de la que realmente tenemos, o deber\u00edamos? Peligro.<\/li>\n<li><strong>Estoy haciendo crecer esta iglesia<\/strong> &#8211; No me puedo imaginar que Dios dejar\u00eda pasar esta mentira por mucho tiempo sin dejarnos igualmente &#8216;creer&#8217;. (y experiencia) que estamos rechazando esta iglesia.<\/li>\n<li><strong>Si no hago esto, nadie lo har\u00e1<\/strong> &#8211; Sofocamos el crecimiento espiritual de los dem\u00e1s cuando no les permitimos usar sus dones espirituales. Negamos a la mano y al pie su posici\u00f3n en el cuerpo. Y, lamentablemente, a menudo nos agotamos a nosotros mismos y a nuestra familia.<\/li>\n<li><strong>Tengo que proteger a mi gente<\/strong> &#8211; Una vez un pastor dijo que no pod\u00eda permitir que &#8220;su&#8221; que la gente crea que Dios todav\u00eda le habla a la gente hoy en d\u00eda, aparte de a trav\u00e9s de Su Palabra, porque hay demasiadas &#8220;voces extra\u00f1as&#8221; all\u00ed afuera. Los hay y creo que la Biblia es la fuente principal de Su comunicaci\u00f3n, pero Dios todav\u00eda habla. Si no lo hace, dejemos de sugerirle a la gente que ore acerca de cu\u00e1nto quiere Dios que den para el fondo de construcci\u00f3n. Cuando tratamos de proteger &#8220;nuestro&#8221; Al apartarlos de Su provisi\u00f3n, los hacemos nuestro pueblo y evitamos que entiendan completamente que son realmente Sus hijos. Ense\u00f1\u00e9mosles, en cambio, c\u00f3mo conocer a Dios m\u00e1s \u00edntimamente y discernir su direcci\u00f3n. Sus ovejas conocen Su voz.<\/li>\n<\/ol>\n<div style=\"clear:both;margin-top:0em;margin-bottom:1em\">\n<div class=\"centered-text-area\">\n<div class=\"centered-text\" style=\"float: left\">\n<div class=\"uf43d2ad2e55061370ccd226930477ff0-content\">V\u00e9ase tambi\u00e9n&nbsp; Por qu\u00e9 los pastores deben reconocer sus propias necesidades<\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p>Estoy seguro de que hay muchas otras mentiras que pueden ser v\u00edctimas como pastores. Exponerlas puede ayudarnos a no distraernos con ellas y permitirnos invocar su fuerza para vencerlas.<\/p>\n<p>\u00bfQu\u00e9 otras mentiras has visto creer a los pastores?<\/p>\n<div class='code-block c\u00f3digo-bloque-1'> <\/div>\n<div class='yarpp yarpp-related yarpp-related-website yarpp-template-thumbnails'>\n<h3>Publicaciones relacionadas:<\/h3>\n<div class=\"yarpp-thumbnails- horizontal\"> \u00bfQu\u00e9 creen los pastores acerca de los \u00faltimos tiempos? \u00bfQu\u00e9 creen los pastores sobre el libro de Apocalipsis? 3 formas de llegar a personas no religiosas en su comunidad <\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Ron Edmondson Mi coraz\u00f3n est\u00e1 para el pastor. Tal vez se deba al hecho de que pas\u00e9 m\u00e1s a\u00f1os como laico \u2014di\u00e1cono y maestro de escuela dominical\u2014 y ahora como pastor. Ahora me doy cuenta de lo mucho que no entend\u00eda sobre el puesto. El papel tiene muchas m\u00e1s expectativas y presiones de lo &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/7-mentiras-que-los-pastores-suelen-creer\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab7 mentiras que los pastores suelen creer\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4015","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=4015"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4015\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=4015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=4015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=4015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}