{"id":4024,"date":"2022-07-26T00:04:23","date_gmt":"2022-07-26T05:04:23","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/11-practicas-para-el-desarrollo-de-jovenes-lideres\/"},"modified":"2022-07-26T00:04:23","modified_gmt":"2022-07-26T05:04:23","slug":"11-practicas-para-el-desarrollo-de-jovenes-lideres","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/11-practicas-para-el-desarrollo-de-jovenes-lideres\/","title":{"rendered":"11 Pr\u00e1cticas para el desarrollo de j\u00f3venes l\u00edderes"},"content":{"rendered":"<div class=\"entry-content\">\n<p><em>Por Scott Douglas<\/em><\/p>\n<p>A medida que la generaci\u00f3n de pastores Boomer comienza su transici\u00f3n hacia la jubilaci\u00f3n , un gran n\u00famero de pastores Millennial est\u00e1n preparados para asumir estas posiciones de liderazgo. Un estudio de Lifeway Research de 2012 encontr\u00f3 que el 35 % de los pastores estaban en edad de jubilaci\u00f3n o dentro de los 10 a\u00f1os o menos de la jubilaci\u00f3n, mientras que solo el 11 % de los pastores encuestados ten\u00edan menos de 35 a\u00f1os.<\/p>\n<p>Al igual que en el entrenamiento, donde muchos Los puestos de entrenadores en jefe son ocupados por entrenadores asistentes, ya que los pastores que se jubilan hacen la transici\u00f3n del ministerio, sus puestos probablemente ser\u00e1n ocupados por aquellos que actualmente se desempe\u00f1an como pastores asociados, ministros de j\u00f3venes, pasantes u otros roles. Entonces, \u00bfqu\u00e9 pueden hacer los pastores salientes para preparar y capacitar una base de liderazgo lista para intervenir y servir eficazmente en las iglesias?<\/p>\n<p>Aqu\u00ed hay 11 pr\u00e1cticas que he encontrado exitosas en iglesias que han manejado estas situaciones bien:<\/p>\n<ol>\n<li><strong>Contratar bien<\/strong> &#8211; Antes de que pueda ocurrir cualquier desarrollo de liderazgo, un pastor l\u00edder debe asegurarse de que las personas adecuadas est\u00e9n en su personal. Hacer la contrataci\u00f3n correcta, hacer el trabajo de fondo y asegurarse de que el candidato sea una buena opci\u00f3n es mucho m\u00e1s importante que desempe\u00f1ar un puesto. Traiga a un pastor asociado con el que pueda trabajar c\u00f3modamente, que lo estire, pero sobre todo que est\u00e9 calificado, sea competente e irreprochable.<\/li>\n<li><strong>D\u00e9les oportunidades<\/strong> &#8211; Permita que el personal ocupe el p\u00falpito, incluso si no se va de la ciudad; darles la oportunidad de sentarse en reuniones que afectan la direcci\u00f3n general de la iglesia; encontrar formas de extenderlos m\u00e1s all\u00e1 de su enfoque ministerial particular. y permitirles ser parte del equipo pastoral, incluyendo visitas al hospital y atenci\u00f3n pastoral. A medida que les brinda oportunidades, valida su capacidad como ministros y crea una cultura dentro de la iglesia que ve al personal m\u00e1s joven bajo una luz pastoral, no como ni\u00f1eras glorificadas (un sentimiento con el que muchos de los que est\u00e1n en el ministerio estudiantil est\u00e1n muy familiarizados).<\/li>\n<li><strong>Dales libertad &amp; flexibilidad<\/strong> &#8211; Cuando incorpore personal al equipo, d\u00e9les la libertad de hacer aquello para lo que han sido llamados. No mires por encima de sus hombros. Perm\u00edtales la flexibilidad para cumplir con el llamado que tienen y lo que la iglesia ha afirmado. No necesita microgestionar si contrat\u00f3 bien, y mientras eval\u00faa al personal, d\u00e9les la libertad de autodiagnosticar su propio desempe\u00f1o.<\/li>\n<li><strong>Cree metas espec\u00edficas<\/strong> &amp;#8211 ; \u00bfQue est\u00e1s tratando de hacer? \u00bfQu\u00e9 se espera de su personal? Debe establecer objetivos claros, tanto profesionales como personales, que pueda utilizar para ayudarlos a crecer. No pierda su tiempo ni el suyo; estar trabajando para lograr algo.<\/li>\n<li><strong>Hacerse amigos<\/strong> &#8211; Si solo se comunica con su personal mientras est\u00e1 en la oficina, est\u00e1 perdiendo la oportunidad de invertir realmente en ellos y sus familias. Cuando comenc\u00e9 mi primer puesto en el ministerio de tiempo completo, nuestro pastor invirti\u00f3 en m\u00ed y en mi esposa como si fu\u00e9ramos su propia familia. Nos ayud\u00f3 a crecer juntos como pareja ya ser m\u00e1s efectivos en nuestro ministerio. Tambi\u00e9n aprend\u00ed m\u00e1s de \u00e9l mientras tomaba s\u00e1ndwiches en un restaurante de buceo que en su oficina.<\/li>\n<li><strong>Mant\u00e9ngalo informal<\/strong> &#8211; El desarrollo del liderazgo no sucede a partir de un libro, sucede a trav\u00e9s de las relaciones. Jes\u00fas tom\u00f3 a 12 pescadores andrajosos y nunca les hizo leer un libro; los desarroll\u00f3 a trav\u00e9s de las relaciones y el equipamiento. Tenga una pol\u00edtica de puertas abiertas para su personal, d\u00e1ndoles acceso a usted. Gran parte de su impacto en sus vidas ocurrir\u00e1 en estas discusiones espont\u00e1neas y oportunidades para entrenarlos. Pero incluso en esas conversaciones, aseg\u00farese de que haya un enfoque intencional para ayudarlos a crecer, no solo para disparar la brisa.<\/li>\n<li><strong>Dirigir, no microgestionar<\/strong> &#8211; Palabras como \u201cequipar\u201d, \u201cempoderar\u201d, \u201chabilitar\u201d y \u201canimar\u201d deben describir lo que hace con su personal. El primer punto de contratar bien debe asegurarse de que no necesite mirar por encima de sus hombros. Esto sofoca su crecimiento y capacidad de ejecuci\u00f3n, y disminuye su capacidad de tener un impacto duradero en sus vidas.<\/li>\n<li><strong>Fomente el equilibrio<\/strong> &#8211; No sacrifiques a la familia en el altar del ministerio. Pastor l\u00edder, necesita modelar lo que significa ser esposo y padre para su equipo ministerial. No imponga cargas innecesarias sobre usted o su equipo que les impidan estar con su familia. Hacer matrimonio &amp; salud familiar como parte de su evaluaci\u00f3n de desempe\u00f1o, y anime a su equipo a tomarse un descanso despu\u00e9s de per\u00edodos intensos en la vida de la iglesia (despu\u00e9s de la EBV, campamento, etc.), y a tomar vacaciones.<\/li>\n<li><strong>Car\u00e1cter de valor<\/strong> &#8211; Aseg\u00farese de que los miembros de su equipo sean irreprensibles, prot\u00e9jalos incluso de la apariencia del mal (1 Tesalonicenses 5:22). Eche un vistazo a su manual de pol\u00edticas, \u00bfse protege a s\u00ed mismo y a su equipo en situaciones de asesoramiento? \u00bfCuenta con par\u00e1metros para garantizar que los miembros del personal nunca est\u00e9n solos con miembros del sexo opuesto? \u00bfTiene software de monitoreo\/rendici\u00f3n de cuentas en las computadoras del trabajo? \u00bfAnima y promueve las disciplinas espirituales en la vida de su equipo ministerial?<\/li>\n<li><strong>Aceptar las diferencias generacionales<\/strong> &#8211; Todo el equipo de liderazgo debe abrazar, celebrar y trabajar juntos en \u00e1reas donde la generaci\u00f3n, la experiencia y la edad pueden fomentar diferentes puntos de vista. Una parte de mi trabajo era servir como mesa de ayuda tecnol\u00f3gica de nuestro pastor interino. Todav\u00eda escrib\u00eda todo a mano, manten\u00eda sus citas en un libro negro y nunca entendi\u00f3 por qu\u00e9 usaba mi iPhone para todo. Estas diferencias son buenas porque modelan el evangelio (G\u00e1latas 3:26-29) y permiten afilarse (Proverbios 27:17) entre s\u00ed. Los miembros m\u00e1s j\u00f3venes del equipo necesitan aprender del ejemplo, la experiencia y la sabidur\u00eda de sus mentores; y los mentores deben recordar que alguna vez fueron j\u00f3venes, sin experiencia y propensos a cometer errores.<\/li>\n<li><strong>La humildad ante todo<\/strong> &#8211; He hablado con muchos miembros del personal que dijeron que no pod\u00edan hacer mucho en la iglesia porque su pastor principal se sent\u00eda intimidado por ellos y no le gustaba tener una persona m\u00e1s joven que pudiera eclipsarlos. Tambi\u00e9n he hablado con pastores mayores que lucharon para tratar con los j\u00f3venes de su personal porque pensaban que lo sab\u00edan todo y no necesitaban la experiencia del pastor mayor. Ninguna de estas actitudes honra a Dios ni refleja el evangelio. Como Jes\u00fas dio el ejemplo de humildad en el liderazgo en Mateo 20, la humildad debe impregnar todas las interacciones y actividades del personal pastoral.<\/li>\n<\/ol>\n<div style=\"clear:both;margin-top:0em;margin-bottom:1em\">\n<div class=\"centered-text-area\">\n<div class=\"centered-text\" style=\"float: left\">\n<div class=\"u2f4a48413f23e5036f2033833b1bd787-content\">V\u00e9ase tambi\u00e9n&amp;nbsp ; El grupo que es m\u00e1s probable que a\u00fan falte en su iglesia<\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p>\u00bfTiene alguna pr\u00e1ctica o ejemplo para add?<\/p>\n<div class='yarpp yarpp-related yarpp-related-website yarpp-template-thumbnails'>\n<h3>Publicaciones relacionadas:<\/h3>\n<div class=\"yarpp-thumbnails-horizontal\"> \u00bfQu\u00e9 \u00bfCreen los pastores acerca de los \u00faltimos tiempos? \u00bfQu\u00e9 creen los pastores sobre el libro de Apocalipsis? 3 formas de llegar a personas no religiosas en su comunidad <\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Scott Douglas A medida que la generaci\u00f3n de pastores Boomer comienza su transici\u00f3n hacia la jubilaci\u00f3n , un gran n\u00famero de pastores Millennial est\u00e1n preparados para asumir estas posiciones de liderazgo. Un estudio de Lifeway Research de 2012 encontr\u00f3 que el 35 % de los pastores estaban en edad de jubilaci\u00f3n o dentro de &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/11-practicas-para-el-desarrollo-de-jovenes-lideres\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab11 Pr\u00e1cticas para el desarrollo de j\u00f3venes l\u00edderes\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4024","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=4024"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4024\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=4024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=4024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=4024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}