{"id":4037,"date":"2022-07-26T00:04:45","date_gmt":"2022-07-26T05:04:45","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/7-consejos-para-lideres-introvertidos\/"},"modified":"2022-07-26T00:04:45","modified_gmt":"2022-07-26T05:04:45","slug":"7-consejos-para-lideres-introvertidos","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/7-consejos-para-lideres-introvertidos\/","title":{"rendered":"7 Consejos para l\u00edderes introvertidos"},"content":{"rendered":"<div class=\"entry-content\">\n<p>Algunas personas se sorprenden cuando, como director general de una gran empresa, confieso que soy introvertido. Es cierto que es una combinaci\u00f3n extra\u00f1a. Debo estar al frente dirigiendo y hablando todas las semanas cuando, sinceramente, prefiero estar solo.<\/p>\n<p>Ser introvertido no significa que no me guste la gente o que sea callado. todo el tiempo. La introversi\u00f3n tiene que ver con d\u00f3nde obtengo mi energ\u00eda.<\/p>\n<p>Piense en un introvertido como un autom\u00f3vil con un tanque de combustible. Cuanto m\u00e1s tiempo est\u00e1 un introvertido en una reuni\u00f3n o en un lugar p\u00fablico, m\u00e1s combustible se agota. En alg\u00fan momento, los introvertidos nos quedamos sin combustible y casi no funcionamos. Solo podemos repostar traslad\u00e1ndonos a un entorno m\u00e1s privado. Personalmente, me siento impulsado por el tiempo que paso a solas con mis pensamientos, en un estudio profundo o escribiendo.<\/p>\n<p>Los introvertidos generalmente se sienten c\u00f3modos comunic\u00e1ndose detr\u00e1s de los clics silenciosos de una computadora sin interacci\u00f3n cara a cara. Disfrutamos los momentos de soledad, reflexi\u00f3n y estudio personal.<\/p>\n<p>Sin duda, otros introvertidos pueden identificarse con mi temor de que me coloquen en una mesa donde se espera que lleve la conversaci\u00f3n. No me gusta ser el centro de atenci\u00f3n. Por el contrario, un rinc\u00f3n solitario de una habitaci\u00f3n sin que nadie se d\u00e9 cuenta me queda muy bien.<\/p>\n<p>Los introvertidos a menudo son percibidos como hostiles. No soy gregario ni extrovertido, pero soy profundamente leal a mis amigos y familiares. A\u00fan as\u00ed, tengo que trabajar en mi apariencia de hostilidad. <\/p>\n<div class='code-block code-block-1' style='margin: 8px 0'> <\/div>\n<h3>Compensar la introversi\u00f3n<\/h3>\n<p>A lo largo de los a\u00f1os, he tratado de compensar mis fuertes tendencias hacia la introversi\u00f3n. De hecho, cualquier l\u00edder debe compensar para liderar con eficacia. Aqu\u00ed hay siete principios para liderar como un l\u00edder introvertido. <\/p>\n<h3><strong>1. Practique el liderazgo caminando. <\/strong><\/h3>\n<p>No deber\u00eda quedarme confinado en las comodidades y el aislamiento de mi oficina. Debo ser visto por mi personal, as\u00ed como por los electores y clientes. Necesito estar rodeado de personas para desarrollar relaciones. Lo mismo ocurre con los pastores. Si bien un introvertido no debe planear demasiada interacci\u00f3n, obl\u00edguese a salir con los miembros de su iglesia con frecuencia, aunque solo sea por breves per\u00edodos de tiempo.<\/p>\n<div style=\"clear:both;margin-top:0em;margin-bottom:1em\">\n<div class=\"centered-text-area\">\n<div class=\"centered-text\" style=\"float: left\">\n<div class=\"u80488ce7dbd5457be1c5cc104039430e-content\">Ver tambi\u00e9n&nbsp; \u00bfSe preocupan demasiado los pastores?<\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<h3>2. Sea transparente acerca de su introversi\u00f3n.<\/h3>\n<p>Ser abierto permitir\u00e1 que la gente lo entienda mejor. Si las personas saben que usted es introvertido, ser\u00e1 menos probable que malinterpreten una naturaleza tranquila y reticente como falta de inter\u00e9s o hostilidad. <\/p>\n<h3>3. Cuando es posible, trato de que las reuniones sean breves.<\/h3>\n<p>Cuanto m\u00e1s larga es una reuni\u00f3n, m\u00e1s me agoto. <\/p>\n<h3>4. En la medida de lo posible, trato de tener un extrovertido conmigo cuando estoy en lugares p\u00fablicos o grupales.<\/h3>\n<p>Ese extrovertido puede ayudar a llevar la conversaci\u00f3n. Puedo asentir con la cabeza y sonre\u00edr. <\/p>\n<h3>5. S\u00e9 responsable ante un extrovertido. <\/h3>\n<p>Es importante tener a alguien en quien conf\u00edes que pueda hablarte con la verdad y recordarte cuando te est\u00e9s hundiendo en una introversi\u00f3n extrema. Si parezco actuar como un idiota desinteresado, ese amigo no duda en dec\u00edrmelo. Me dice c\u00f3mo pueden ser percibidas mis acciones o falta de acciones. <\/p>\n<h3>6. Usa las redes sociales como tu voz. <\/h3>\n<p>Los introvertidos a menudo luchan por ser sociables en persona, pero por lo general no les importa escribir. Cuantas m\u00e1s personas te vean en Facebook, Twitter o un blog, m\u00e1s sentir\u00e1n que te conocen, aunque no tengas una interacci\u00f3n personal con ellos. Las redes sociales son una gran herramienta para los introvertidos. <\/p>\n<h3>7. Programe tiempo para recuperarse. <\/h3>\n<p>Si no recargo mis bater\u00edas con frecuencia, me convierto en un l\u00edder in\u00fatil. Pero no puedo sucumbir a la tentaci\u00f3n de perpetuar mi tiempo de inactividad. Debo volver a todos los principios establecidos anteriormente.<\/p>\n<p>Es posible que los introvertidos lideren. Pero requiere esfuerzo. No permita que su personalidad sea una excusa que le impida hacer lo que Dios le ha llamado a hacer. <\/p>\n<p><strong>THOM S. RAINER <\/strong><em>(@ ThomRainer) es presidente de Lifeway Christian Resources. Obtenga m\u00e1s informaci\u00f3n en ThomRainer.com.<\/em><\/p>\n<div class='yarpp yarpp-related yarpp-related-website yarpp-template-thumbnails'>\n<h3>Publicaciones relacionadas:<\/h3>\n<div class=\"yarpp-thumbnails-horizontal\"> \u00bfQu\u00e9 creen los pastores sobre el fin de los tiempos? \u00bfQu\u00e9 creen los pastores sobre el libro de Apocalipsis? 3 formas de llegar a personas no religiosas en su comunidad <\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Algunas personas se sorprenden cuando, como director general de una gran empresa, confieso que soy introvertido. Es cierto que es una combinaci\u00f3n extra\u00f1a. Debo estar al frente dirigiendo y hablando todas las semanas cuando, sinceramente, prefiero estar solo. Ser introvertido no significa que no me guste la gente o que sea callado. todo el tiempo. &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/7-consejos-para-lideres-introvertidos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab7 Consejos para l\u00edderes introvertidos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4037","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=4037"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4037\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=4037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=4037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=4037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}