{"id":4045,"date":"2022-07-26T00:04:59","date_gmt":"2022-07-26T05:04:59","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/comprender-el-evangelio-y-la-cultura\/"},"modified":"2022-07-26T00:04:59","modified_gmt":"2022-07-26T05:04:59","slug":"comprender-el-evangelio-y-la-cultura","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/comprender-el-evangelio-y-la-cultura\/","title":{"rendered":"Comprender el evangelio y la cultura"},"content":{"rendered":"<div class=\"entry-content\">\n<p><em>Por Ed Stetzer<\/em><\/p>\n<p>Me encanta la investigaci\u00f3n. Soy un poco nerd en ese sentido. Tambi\u00e9n amo a la Iglesia. As\u00ed que dirigir una gran organizaci\u00f3n de investigaci\u00f3n cristiana comprometida con la producci\u00f3n de resultados que sirvan a la Iglesia funciona bien para m\u00ed. Recientemente, me preguntaron c\u00f3mo los l\u00edderes de la iglesia deber\u00edan usar los datos que producimos, lo que pens\u00e9 que era una pregunta astuta que justificaba una respuesta.<\/p>\n<p>La participaci\u00f3n en la misi\u00f3n de Dios requiere una comprensi\u00f3n aguda de dos componentes: el evangelio y la cultura. . El evangelio es la buena noticia de la encarnaci\u00f3n de Cristo. Este fue el advenimiento del reino de Dios en los reinos del mundo, cada uno de los cuales cuenta con su propia cultura particular. No importa la cultura, la venida de Cristo es ciertamente una buena noticia; pero los detalles de c\u00f3mo fueron las buenas noticias var\u00edan de una cultura a otra.<\/p>\n<p>El problema es que no sabemos qui\u00e9n resuena con qu\u00e9 aspectos de las buenas noticias a menos que conozcamos a qui\u00e9nes somos. tomando el evangelio. As\u00ed es como esperamos que los pastores usen la investigaci\u00f3n que presentamos a las iglesias: para comprender la cultura que los rodea y c\u00f3mo les est\u00e1 yendo para involucrarlos con el evangelio.<\/p>\n<p>Dos grupos de personas a los que se hace referencia en la Biblia ilustran lo que debemos hacer para ser efectivos en nuestro compromiso cultural impulsado por el evangelio. En Hechos 17:10-11, Lucas alaba a los bereanos porque se dedicaron al estudio de las Escrituras. Se enraizaron profundamente en la Palabra de Dios y eso afect\u00f3 la forma en que viv\u00edan.<\/p>\n<p>Necesitamos ser como los de Berea: firmemente arraigados en la Palabra para que las ense\u00f1anzas que contiene nos gu\u00eden. En pocas palabras, primero debemos entender y vivir a la luz de las buenas nuevas antes de que podamos persuadir a otros de sus bondades (2 Corintios 5:11).<\/p>\n<div class='code-block code-block-1'> <\/div>\n<p>El segundo grupo, que se encuentra en 1 Cr\u00f3nicas 12:32, puede ser m\u00e1s oscuro. Al hablar de los ej\u00e9rcitos de hombres que se unieron a David cuando hu\u00eda de Sa\u00fal, nos encontramos con los hombres de Isacar que \u201ccomprend\u00edan los tiempos y sab\u00edan lo que Israel deb\u00eda hacer\u201d. Esa es una caracterizaci\u00f3n profunda, y esos hombres habr\u00edan sido excepcionalmente valiosos para David cuando \u00e9l y sus ej\u00e9rcitos llevaron a cabo sus misiones.<\/p>\n<div style=\"clear:both;margin-top:0em;margin-bottom:1em\">\n<div class=\"centered-text-area\">\n<div class=\"centered-text\" style=\"float: left\">\n<div class=\"u3afbb16c0c2be46222e4ec8482067346-content\">Ver tambi\u00e9n&nbsp; Por qu\u00e9 los pastores deben reconocer sus propias necesidades<\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p>De la misma manera, necesitamos entender los momentos en que estamos adentro. Necesitamos entender a las personas a las que Dios nos est\u00e1 enviando por causa del evangelio, para saber c\u00f3mo involucrarlos.<\/p>\n<p>Necesitamos ser personas que entiendan tanto el evangelio como la cultura. <br \/> La Palabra de Dios nos da nuestra misi\u00f3n, mientras que los datos nos ayudan a saber c\u00f3mo podemos lograr mejor nuestra tarea: involucrar a las personas con el evangelio.<\/p>\n<p>Hay extremos en ambos extremos del espectro, uno que ignora la cultura y otro que ignora las Escrituras. Hay aquellos cuyo enfoque en cualquier cultura es ignorar los datos, amar a las personas y simplemente presentar el evangelio. Si no entienden la cultura, es imposible que interact\u00faen con ella y eventualmente se vuelvan irrelevantes.<\/p>\n<p>Lo contrario tambi\u00e9n es cierto en el sentido de que hay quienes no est\u00e1n atados a la Palabra sino que son impulsados por los datos. . Se enamoran tanto de la cultura que pierden el car\u00e1cter distintivo del reino de Dios. Eventualmente tambi\u00e9n se vuelven irrelevantes, porque no hay diferencia entre ellos y la cultura de las personas que los rodean.<\/p>\n<p>Cada uno de estos resultados es tr\u00e1gico, y cada uno ocurre porque las personas por defecto se consuelan, o ignoran la cultura o ajustarse a ella. Hay tensi\u00f3n en vivir el car\u00e1cter de un reino dentro de otro.<\/p>\n<p>Mi deseo como creyente e investigador es que los cristianos seamos fieles a las Escrituras y estudiosos de la cultura que nos rodea, lo que conducir\u00eda a m\u00e1s esfuerzos fruct\u00edferos en la misi\u00f3n. Nuestra investigaci\u00f3n se produce con esa esperanza en mente: alentarlos y capacitarlos para que sean personas fieles de Berea e Isacar, que son fruct\u00edferas porque est\u00e1n atados a la Palabra y pueden discernir los tiempos.<\/p>\n<p>Ed Stetzer es presidente de Lifeway Research.<\/p>\n<div class='yarpp yarpp-related yarpp-related-website yarpp-template-thumbnails'>\n<h3>Publicaciones relacionadas:<\/h3>\n<div class=\"yarpp-thumbnails-horizontal \"> \u00bfQu\u00e9 creen los pastores acerca de los \u00faltimos tiempos? \u00bfQu\u00e9 creen los pastores sobre el libro de Apocalipsis? 3 formas de llegar a personas no religiosas en su comunidad <\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Ed Stetzer Me encanta la investigaci\u00f3n. Soy un poco nerd en ese sentido. Tambi\u00e9n amo a la Iglesia. As\u00ed que dirigir una gran organizaci\u00f3n de investigaci\u00f3n cristiana comprometida con la producci\u00f3n de resultados que sirvan a la Iglesia funciona bien para m\u00ed. Recientemente, me preguntaron c\u00f3mo los l\u00edderes de la iglesia deber\u00edan usar los &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/comprender-el-evangelio-y-la-cultura\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComprender el evangelio y la cultura\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4045","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=4045"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4045\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=4045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=4045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=4045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}