{"id":4054,"date":"2022-07-26T00:05:15","date_gmt":"2022-07-26T05:05:15","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/la-iglesia-y-la-justicia\/"},"modified":"2022-07-26T00:05:15","modified_gmt":"2022-07-26T05:05:15","slug":"la-iglesia-y-la-justicia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/la-iglesia-y-la-justicia\/","title":{"rendered":"La Iglesia y la Justicia"},"content":{"rendered":"<div class=\"entry-content\">&nbsp; <\/p>\n<p>Por Ann-Margret Hovsepian<\/p>\n<p>Ya sea lanzando iniciativas de base o respondiendo a proyectos de arriba hacia abajo, los cristianos en Am\u00e9rica del Norte est\u00e1n cada vez m\u00e1s involucrados en temas relacionados con la justicia, como la pobreza, la trata de personas, los refugiados, los hu\u00e9rfanos y la salud. cuidado.<br \/> Sharon Mall de Janesville, Wis., sirve como catalizador para las Iniciativas de Justicia Alcance Global de Asia de la Iglesia Evang\u00e9lica Libre de Am\u00e9rica. Ella dice que un cristiano \u201cno puede demostrar a Cristo sin hacer justicia social. Cuando nos preocupamos genuinamente por las personas, entonces tambi\u00e9n les compartiremos a Cristo\u201d.<\/p>\n<p>Ella descubri\u00f3 que en \u00e1reas de vulnerabilidad, ya sea en Am\u00e9rica del Norte o en Asia, cuando los creyentes desarrollan una plataforma a trav\u00e9s de ministerios de misericordia, se abren las puertas para que presenten el evangelio. Las personas que no creen en la oraci\u00f3n responden con notable positividad cuando alguien muestra compasi\u00f3n y se ofrece a orar por sus necesidades. <\/p>\n<h3>\u00bfA qui\u00e9n le importa?<\/h3>\n<p>Jane Forster, miembro de la Iglesia Evang\u00e9lica Libre Rockpoint en Lake Elmo, Minnesota, dice que compartir el evangelio es crucial porque \u201cah\u00ed es donde est\u00e1 la esperanza\u201d, pero que demostrar el evangelio tambi\u00e9n es importante. Ella y su esposo, Steve, est\u00e1n involucrados con el Centro Brydges, una instituci\u00f3n de tres sucursales que brinda refugio, alimentos y educaci\u00f3n a ni\u00f1os hu\u00e9rfanos, sin hogar y empobrecidos en todo Kenia. \u201cA la gente no le importa cu\u00e1nto sabes hasta que saben cu\u00e1nto te importa\u201d, dice Forster. \u201cTenemos que amarlos en el Reino, y lo hacemos satisfaciendo primero sus necesidades f\u00edsicas y sociales. Tenemos que mostrarle a la gente que los amamos porque eso es lo que Jes\u00fas nos llamar\u00eda a hacer\u201d.<\/p>\n<p>Lifeway Research realiz\u00f3 una serie de encuestas entre pastores protestantes (tanto evang\u00e9licos como tradicionales), de 2008 a 2012, espec\u00edficamente sobre el tema de la pobreza sino tambi\u00e9n de la acci\u00f3n social en general. Esta investigaci\u00f3n revel\u00f3 que las iglesias m\u00e1s grandes tienden a involucrarse m\u00e1s activamente en temas de justicia social. A medida que aumenta la asistencia semanal promedio a la iglesia, tambi\u00e9n aumenta la probabilidad de que una iglesia aborde la pobreza a nivel local, hable sobre la pobreza, se interese en la acci\u00f3n social o movilice a sus miembros \u201cpara involucrarse y cuidar directamente a los pobres\u201d en su comunidad.<\/p>\n<p>Pero en general, la mayor\u00eda (95 por ciento) de los encuestados estuvo de acuerdo en que \u00abel evangelio exige cuidar a los pobres\u00bb.<\/p>\n<div> <\/div>\n<p>\u201cCuando los pastores creen esto, sus iglesias tienden a preocuparse m\u00e1s por los problemas de justicia social\u201d, dice Ed Stetzer, presidente de Lifeway Research. \u201cHemos visto un aumento en el porcentaje de iglesias comprometidas con el cuidado de los pobres desde 2009 del 76 % al 90 % en 2012\u201d.<\/p>\n<p>Entre todos los encuestados, el 25 % mencion\u00f3 la pobreza como el m\u00e1s importante de cinco problemas \u201cque enfrenta nuestro pa\u00eds hoy\u201d. Las otras cuatro opciones fueron el aborto (24 por ciento), el matrimonio entre personas del mismo sexo (20 por ciento), la atenci\u00f3n m\u00e9dica (19 por ciento) y el medio ambiente (3 por ciento). El nueve por ciento respondi\u00f3 \u00abNinguno\/No estoy seguro\u00bb.<br \/> Las iglesias en las grandes ciudades (63 por ciento) tienen m\u00e1s probabilidades de abordar la pobreza a nivel local que las iglesias en \u00e1reas rurales (53 por ciento). Los resultados de la encuesta indican diferencias entre las iglesias tradicionales y las evang\u00e9licas, entre los pastores dem\u00f3cratas y republicanos, y entre los pastores con t\u00edtulo universitario y los que no lo tienen. En cada caso, el primero estaba m\u00e1s interesado o involucrado con la acci\u00f3n social que el segundo.<\/p>\n<p>\u201cNuestra investigaci\u00f3n muestra que el nivel de compromiso que tienen las iglesias en el cuidado de los pobres puede estar influenciado por la frecuencia con la que los pastores hablan con sus congregaciones sobre la pobreza\u201d, dice Stetzer. M\u00e1s de un tercio de los pastores protestantes hablan sobre la pobreza varias veces al a\u00f1o o m\u00e1s.<\/p>\n<p>\u201cPero los pastores protestantes no solo hablan de preocuparse por los dem\u00e1s, sino que est\u00e1n guiando a sus iglesias a tomar medidas\u201d, dice Stetzer.  <\/p>\n<h3>Llevando esperanza a los marginados<\/h3>\n<p>Cuando el Centro Brydges fue fundado en 1995 por Rosemary Eve Wafula, una keniata, su objetivo inicial era brindar orientaci\u00f3n espiritual y comidas. A medida que aumentaba el apoyo y el n\u00famero de voluntarios, el Centro comenz\u00f3 a ayudar a los ni\u00f1os de formas m\u00e1s sustanciales. Actualmente, el Centro atiende a 150 ni\u00f1os y apoya a 40 j\u00f3venes cada a\u00f1o a trav\u00e9s de programas de desarrollo de habilidades. Los Forster escucharon que el Centro necesitaba una asociaci\u00f3n y, en febrero de 2012, viajaron a Nairobi con otra pareja de Rockpoint para explorar c\u00f3mo su iglesia podr\u00eda ayudar.<\/p>\n<div style=\"clear:both;margin-top:0em;margin-bottom:1em\">\n<div class=\"centered-text-area\">\n<div class=\"centered-text\" style=\"float: left\">\n<div class=\"u9ff640deac941be02876e6b6a2ec2d54-content\">V\u00e9ase tambi\u00e9n&amp;nbsp ; \u00bfQu\u00e9 despierta la generosidad evang\u00e9lica? Discipulado<\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p>\u201cRegresamos con un trozo de nuestro coraz\u00f3n\u201d, dice Jane. \u201cCuando la gente se dio cuenta del impacto que tuvo en nosotros, preguntaron: &#8216;\u00bfQu\u00e9 podemos hacer?&#8217;\u201d. En un fin de semana, recaudaron $26,000 para construir un molino de viento para el Centro. Forster dice que eventualmente les gustar\u00eda construir un centro de capacitaci\u00f3n para pastores \u00aby tal vez tener una iglesia en el lugar para que el proyecto complete el c\u00edrculo hacia el objetivo real\u00bb.<\/p>\n<p>La falta de vivienda puede no ser tan grave en Am\u00e9rica del Norte como lo es en muchas naciones empobrecidas de todo el mundo y, sin embargo, sigue siendo una realidad en muchos centros urbanos.<\/p>\n<p>Todos los lunes por la noche en Uptown Baptist Church en Chicago, unos cientos de hombres y mujeres sin hogar llenan el s\u00f3tano de la iglesia donde reciben una comida caliente. La iglesia ha estado cuidando a las personas sin hogar de la ciudad durante a\u00f1os.<\/p>\n<p>\u201cLa necesidad m\u00e1s profunda de la humanidad es conocer a Dios y reconectarse con Dios\u201d, dice el pastor Michael Allen. \u201cCualquiera que sea el problema superficial que est\u00e9 sucediendo a nuestro alrededor, las oportunidades est\u00e1n ah\u00ed para ser una luz, para ser un testigo y compartir las buenas nuevas del evangelio en palabras y hechos\u201d. <\/p>\n<h3>Una mala D\u00eda de los malvados<\/h3>\n<p>Algunos cristianos pueden rehuir los problemas de justicia social porque los perciben en el \u00e1mbito pol\u00edtico en lugar del espiritual, sugiere Debbie Johnson, fundadora y directora ejecutiva de Without Permission en Modesto, California. ., un ministerio que atiende a las v\u00edctimas de la trata de personas despu\u00e9s de que son rescatadas por la polic\u00eda local. \u201cPero cuando hablamos de trata de personas, en realidad estamos hablando de la fortaleza demon\u00edaca sexual. Este ha sido un problema del tercer mundo durante d\u00e9cadas. Dios est\u00e1 despertando a la iglesia para que diga: &#8216;Esto est\u00e1 en tu pa\u00eds a niveles de epidemia&#8217;\u201d. Johnson se refiere a Proverbios 21:15 y dice: \u201cCuando se hace justicia, la ciudad se regocija. \u00a1Es un mal d\u00eda para los malvados!\u201d<\/p>\n<p>Sin permiso se asegura de que su trabajo se centre en una de las tres cosas que, seg\u00fan Johnson, son necesarias para erradicar la trata de personas: enjuiciamiento, protecci\u00f3n y prevenci\u00f3n. El ministerio no intenta rescatar a las ni\u00f1as atrapadas en el tr\u00e1fico sexual. <\/p>\n<p>\u201cAtendemos a los socorristas que las rescatan\u201d, explica Johnson. Without Permission entrena y equipa a \u00abnavegantes\u00bb para que se sienten con ni\u00f1as rescatadas por la polic\u00eda. Las ni\u00f1as reciben una \u201cBolsa de Compasi\u00f3n\u201d que contiene un animal de peluche y una manta, junto con art\u00edculos personales.<\/p>\n<p>\u201cHablamos con ellas. Les decimos que estamos ah\u00ed para ayudarlos. Oramos con ellas\u201d.<br \/> A veces, Sin Permiso alberga a ni\u00f1as, paga su viaje de regreso a casa y habla con sus padres. Al apoyar a estas ni\u00f1as, Without Permission libera a las fuerzas del orden p\u00fablico para encontrar y procesar a los proxenetas. \u201cCualquiera puede hacer esto\u201d, agrega Johnson, \u201cincluso sin una organizaci\u00f3n\u201d.<\/p>\n<p>Stetzer dice que la investigaci\u00f3n es alentadora. \u201cLos n\u00fameros muestran que cada vez m\u00e1s iglesias est\u00e1n captando una visi\u00f3n para cuidar a los olvidados, privados de sus derechos y oprimidos. Jes\u00fas nos ha llamado a preocuparnos por la justicia, y cada vez m\u00e1s los l\u00edderes de la iglesia ven la obra del reino no solo como la proclamaci\u00f3n del evangelio, sino tambi\u00e9n como la demostraci\u00f3n del evangelio\u201d.<\/p>\n<p>Ann-Margret Hovsepian es una escritora que vive en Montreal, Quebec.<\/p>\n<div class='yarpp yarpp-related yarpp-related-website yarpp-template-thumbnails'>\n<h3>Publicaciones relacionadas:<\/h3>\n<div class=\"yarpp-thumbnails-horizontal\"> cristianos, teor\u00edas de conspiraci\u00f3n, y credibilidad: por qu\u00e9 nuestras palabras de hoy son importantes para la eternidad 3 formas de llegar a las personas no religiosas de su comunidad <\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Por Ann-Margret Hovsepian Ya sea lanzando iniciativas de base o respondiendo a proyectos de arriba hacia abajo, los cristianos en Am\u00e9rica del Norte est\u00e1n cada vez m\u00e1s involucrados en temas relacionados con la justicia, como la pobreza, la trata de personas, los refugiados, los hu\u00e9rfanos y la salud. cuidado. Sharon Mall de Janesville, Wis., &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/la-iglesia-y-la-justicia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa Iglesia y la Justicia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4054","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=4054"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4054\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=4054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=4054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=4054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}