{"id":4060,"date":"2022-07-26T00:05:25","date_gmt":"2022-07-26T05:05:25","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/10-mandamientos-para-usar-ipads-en-la-iglesia\/"},"modified":"2022-07-26T00:05:25","modified_gmt":"2022-07-26T05:05:25","slug":"10-mandamientos-para-usar-ipads-en-la-iglesia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/10-mandamientos-para-usar-ipads-en-la-iglesia\/","title":{"rendered":"10 Mandamientos para usar iPads en la Iglesia"},"content":{"rendered":"<div class=\"entry-content\">\n<p> <em>Por Aaron Earls<\/em><\/p>\n<p>Los himnarios y las Biblias est\u00e1n siendo reemplazados en muchos bancos de iglesia por iPads y Kindles. Las pantallas de iPhone y Droid iluminan santuarios, auditorios y arenas los domingos por la ma\u00f1ana.<\/p>\n<p>Cuando est\u00e9 pensando en usar un tel\u00e9fono inteligente o una tableta durante el servicio de la iglesia, aqu\u00ed hay 10 mandamientos divertidos pero importantes que debe tener en cuenta. <\/p>\n<h3 style=\"text-align: center\"><strong>10 mandamientos para usar iPads en la iglesia<\/strong><\/h3>\n<p><strong>10. Deber\u00e1s tener instalada la aplicaci\u00f3n de la Biblia.<\/strong><br \/> En serio, tiene m\u00e1s de cien millones de descargas. No creo que sea posible amar a Jes\u00fas y no tener YouVersion en tu tel\u00e9fono inteligente o tableta.<\/p>\n<p><strong>9. Debes mirar hacia arriba de vez en cuando solo para que el pastor sepa que est\u00e1s escuchando.<\/strong><br \/> Si tus ojos est\u00e1n bajos durante todo el serm\u00f3n, est\u00e1s dormido o revisando tu cuenta de Instagram. Vamos, no mientas. Estabas tocando dos veces esa linda foto de beb\u00e9.<\/p>\n<p><strong>8. No gritar\u00e1s, &#8220;\u00a1S\u00ed!&#8221;<\/strong><br \/> Incluso si est\u00e1s respondiendo a un punto que plante\u00f3 el pastor, todos pensar\u00e1n que acabas de superar un momento realmente dif\u00edcil. nivel en Candy Crush.<\/p>\n<div class='code-block code-block-1' style='margin: 8px 0'> <\/div>\n<p><strong>7. No deber\u00e1s twittear, a menos que se trate del serm\u00f3n.<\/strong><br \/> No env\u00edes tweets sobre d\u00f3nde vas a almorzar. Y, definitivamente, no retuitees una cita de un serm\u00f3n de la iglesia del otro lado de la ciudad. Sabes que tu pastor te sigue en Twitter.<\/p>\n<p><strong>6. Debes eliminar cualquier aplicaci\u00f3n de visualizaci\u00f3n de TV durante la temporada de la NFL.<\/strong><br \/> A veces, la tentaci\u00f3n es demasiado grande. Ni siquiera querr\u00e1s tener la opci\u00f3n de echar un vistazo a los programas previos al juego si el serm\u00f3n dura mucho.<\/p>\n<p><strong>5. Tendr\u00e1s que apagar el volumen.<\/strong><br \/> Nadie necesita escuchar tu extra\u00f1o sonido de notificaci\u00f3n por correo electr\u00f3nico. Adem\u00e1s, si infringe el mandamiento n\u00famero 6 con el sonido &#8230; tu equipo va a perder.<\/p>\n<div style=\"clear:both;margin-top:0em;margin-bottom:1em\">\n<div class=\"centered-text-area\">\n<div class=\"centered-text\" style=\"float: left\">\n<div class=\"u2609fb41b240a9abe1b5edf97af17a84-content\">V\u00e9ase tambi\u00e9n&nbsp; Video: Navegando el cambio en la iglesia<\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p><strong>4. No atesorar\u00e1s el WiFi de la iglesia.<\/strong><br \/> No hay mucho ancho de banda para todos. No seas el tipo que espera hasta llegar a la iglesia para descargar las actualizaciones de la aplicaci\u00f3n correspondientes a un mes. Algunas personas est\u00e1n tratando de transmitir el juego, er, el serm\u00f3n.<\/p>\n<p><strong>3. No deber\u00e1s traer un cargador para enchufarlo a un tomacorriente de pared.<\/strong><br \/> \u00bfRealmente vas a poner en peligro la vida de quienes acepten la oferta porque te asustas cuando la vida \u00fatil de la bater\u00eda cae por debajo del 75 %?<\/p>\n<p>2. Honre a sus compa\u00f1eros de banco para que la duraci\u00f3n de la bater\u00eda sea larga en esta tierra.<\/strong><br \/> Aten\u00fae el brillo de la pantalla para no cegar a todos los que est\u00e1n sentados cerca de usted. Afortunadamente, ning\u00fan barco necesita tu iPad para que sirva de faro y los ayude a mantenerse alejados del edificio de tu iglesia.<\/p>\n<p><strong>1. No tendr\u00e1s otros gadgets antes que t\u00fa.<\/strong><br \/> Hay un l\u00edmite estricto de uno por vuelta. Si tiene su tableta afuera, mantenga su tel\u00e9fono inteligente en su bolsillo. \u00bfUsas tu Kindle? No saques tu iPad. En ese punto, solo est\u00e1s presumiendo y claramente infringiendo el mandamiento 4 y probablemente algunos otros.<\/p>\n<p><em>\u00bfQu\u00e9 reglas me perd\u00ed? \u00bfQu\u00e9 leyes tecnol\u00f3gicas pondr\u00edas en tus dos tabletas de piedra?<\/em><\/p>\n<p><strong>AARON EARLS (@WardrobeDoor)<\/strong> es editor en l\u00ednea de Facts &amp; Tendencias.<\/p>\n<div class='yarpp yarpp-related yarpp-related-website yarpp-template-thumbnails'>\n<h3>Publicaciones relacionadas:<\/h3>\n<div class=\"yarpp-thumbnails-horizontal\"> Qu\u00e9 \u00bfCreen los pastores acerca de los \u00faltimos tiempos? \u00bfQu\u00e9 creen los pastores sobre el libro de Apocalipsis? 3 formas de llegar a personas no religiosas en su comunidad <\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Aaron Earls Los himnarios y las Biblias est\u00e1n siendo reemplazados en muchos bancos de iglesia por iPads y Kindles. Las pantallas de iPhone y Droid iluminan santuarios, auditorios y arenas los domingos por la ma\u00f1ana. Cuando est\u00e9 pensando en usar un tel\u00e9fono inteligente o una tableta durante el servicio de la iglesia, aqu\u00ed hay &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/10-mandamientos-para-usar-ipads-en-la-iglesia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab10 Mandamientos para usar iPads en la Iglesia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4060","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=4060"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4060\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=4060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=4060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=4060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}