{"id":4070,"date":"2022-07-26T00:05:42","date_gmt":"2022-07-26T05:05:42","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/deberiamos-dejar-de-pedirle-a-jesus-que-entre-en-nuestros-corazones\/"},"modified":"2022-07-26T00:05:42","modified_gmt":"2022-07-26T05:05:42","slug":"deberiamos-dejar-de-pedirle-a-jesus-que-entre-en-nuestros-corazones","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/deberiamos-dejar-de-pedirle-a-jesus-que-entre-en-nuestros-corazones\/","title":{"rendered":"\u00bfDeber\u00edamos dejar de pedirle a Jes\u00fas que entre en nuestros corazones?"},"content":{"rendered":"<div class=\"entry-content\">\n<p>Por JD Greear<\/p>\n<p>Si hubiera un r\u00e9cord en el Libro Guinness de r\u00e9cords mundiales por \u00abcantidad de veces haber pedido a Jes\u00fas que entre en tu coraz\u00f3n\u201d, estoy bastante seguro de que lo mantendr\u00eda.<br \/> Para cuando cumpl\u00ed los 18 a\u00f1os, probablemente hab\u00eda \u201cpedido a Jes\u00fas que entrara en mi coraz\u00f3n\u201d 5000 veces.<\/p>\n<p>Empec\u00e9 alrededor de los 4 a\u00f1os cuando me acerqu\u00e9 a mis padres un s\u00e1bado por la ma\u00f1ana y les pregunt\u00e9 c\u00f3mo alguien pod\u00eda saber que iba al cielo.<\/p>\n<p>Con cuidado me guiaron por el \u00abcamino de los romanos a la salvaci\u00f3n\u00bb y les di Jes\u00fas Su primera invitaci\u00f3n a mi coraz\u00f3n.<\/p>\n<p>Tanto mis padres como mi pastor se sintieron seguros de mi sinceridad y mi comprensi\u00f3n de los detalles, as\u00ed que fui bautizado.<\/p>\n<p>Escribimos la fecha en mi Biblia, y viv\u00ed en paz al respecto durante casi una d\u00e9cada.<\/p>\n<div class='code-block code-block-1' style='margin: 8px 0'> <\/div>\n<p>Sin embargo, un viernes por la noche durante mi noveno grado, mi maestro de escuela dominical nos dijo que, seg\u00fan Mateo 7:21\u201323, muchas personas que creen que conocen a Jes\u00fas despertar\u00e1n en ese \u00faltimo d\u00eda a la realidad de que nunca los conoci\u00f3 realmente.<\/p>\n<p>Aunque hab\u00edan orado una oraci\u00f3n para recibir a Jes\u00fas, en realidad nunca hab\u00edan nacido de nuevo y nunca hab\u00edan tomado en serio el se\u00f1or\u00edo de Jes\u00fas. Ser\u00edan, explic\u00f3 mi maestro, apartados del cielo hacia el castigo eterno con las desastrosas palabras: \u201c\u00a1Nunca los conoc\u00ed! \u00a1Apartaos de m\u00ed, transgresores de la ley!\u201d<\/p>\n<p>\u00bfSer\u00eda yo uno de esos rechazados? \u00bfRealmente me hab\u00eda arrepentido de mis pecados? \u00bfY realmente podr\u00eda haber sabido lo que estaba haciendo a los cuatro a\u00f1os?<\/p>\n<p>As\u00ed que le ped\u00ed a Jes\u00fas que viniera a mi coraz\u00f3n nuevamente, esta vez con la resoluci\u00f3n de ser mucho m\u00e1s intencional con respecto a mi fe. Solicit\u00e9 volver a bautizarme y di un testimonio muy conmovedor frente a nuestra congregaci\u00f3n acerca de tomarnos en serio con Dios.<\/p>\n<p>Poco despu\u00e9s me encontr\u00e9 pregunt\u00e1ndome nuevamente: \u00bfRealmente me arrepent\u00ed lo suficiente de mi pecado este vez?<\/p>\n<p>Hab\u00eda algunos pecados en los que parec\u00eda volver a caer una y otra vez, sin importar cu\u00e1ntas resoluciones tomara para hacerlo mejor. \u00bfRealmente me arrepent\u00ed de esos pecados? \u00bfFue esa oraci\u00f3n un momento de entrega total?<\/p>\n<p>As\u00ed que rec\u00e9 la oraci\u00f3n del pecador nuevamente. Y otra vez. Y otra vez. Cada vez tratando de hacerlo bien, cada vez tratando de decirlo en serio.<\/p>\n<p>Camin\u00e9 muchos pasillos durante esos d\u00edas. Creo que he sido salvo por lo menos una vez en cada denominaci\u00f3n. He sido bautizado cuatro veces. Honestamente, se puso bastante vergonzoso. Me convert\u00ed en un elemento b\u00e1sico en los servicios de bautismo de nuestra iglesia. Consegu\u00ed mi propio casillero en el vestidor bautismal.<\/p>\n<p>Fue una experiencia horrible. Mi vida espiritual se caracteriz\u00f3 por ciclos de duda, caminar por el pasillo y sumergirme en el agua. No pod\u00eda encontrar la seguridad de la salvaci\u00f3n sin importar cu\u00e1ntas veces o cu\u00e1n sinceramente le ped\u00ed a Jes\u00fas que entrara en mi coraz\u00f3n.<\/p>\n<p>Sol\u00eda pensar que estaba solo en esta lucha, pero a medida que comparto mi historia a lo largo de los a\u00f1os, muchos se han presentado para decirme que mi experiencia fue la de ellos (por lo general menos los bautismos y las tendencias del TOC) que he concluido que este problema es una epidemia en la iglesia. <\/p>\n<p> Los falsamente seguros<\/p>\n<p>Por otro lado, las Escrituras indican que hay un gran n\u00famero de personas que parecen estar seguras de una salvaci\u00f3n que en realidad no poseen.<\/p>\n<p>Mi maestro de escuela dominical me dec\u00eda nosotros la verdad: seg\u00fan Mateo 7, Jes\u00fas rechazar\u00e1 en ese \u00faltimo d\u00eda a \u201cmuchos\u201d que pensaban que le pertenec\u00edan. No hay duda de que muchos de ellos habr\u00e1n rezado la oraci\u00f3n de un pecador.<br \/> En Su par\u00e1bola sobre los diferentes tipos de suelo, Jes\u00fas habl\u00f3 de un grupo que escuch\u00f3 Su palabra y dio una respuesta inicial y alentadora de fe, solo para desvanecerse. con el tiempo.<\/p>\n<p>\u00c9stos son aquellos, explic\u00f3 Jes\u00fas, que escuchan el evangelio y responden positivamente a \u00e9l: hacen la oraci\u00f3n, caminan por el pasillo, se bautizan o hacen cualquier cosa que hagan los nuevos conversos en su iglesia.<\/p>\n<p>Permanecen en la iglesia por un tiempo. Pero no perseveran cuando sale el sol de la persecuci\u00f3n y al final no se salvar\u00e1n (Lucas 8:13).<\/p>\n<p>Estas historias aleccionadoras nos ense\u00f1an que muchos se dirigen al juicio eterno bajo el enga\u00f1o de ir al cielo Se les dijo que si rezaban la oraci\u00f3n, Jes\u00fas los salvar\u00eda, los sellar\u00eda y nunca los dejar\u00eda ni los abandonar\u00eda.<br \/> Un estudio de Barna de 2011 muestra que casi la mitad de todos los adultos en Estados Unidos han rezado tal oraci\u00f3n y, posteriormente, creen que ir\u00e1n al cielo, aunque muchos de ellos rara vez asisten a una iglesia, leen la Biblia personalmente o tienen estilos de vida que difieren de manera significativa de los que est\u00e1n fuera de la iglesia.<\/p>\n<p>Si los grupos descritos en Mateo 7 y Lucas 8 no se refieren a ellos, no s\u00e9 a qui\u00e9n se podr\u00edan estar refiriendo. <\/p>\n<p>\u00bfUn clich\u00e9 in\u00fatil del evangelio?<\/p>\n<p>Tengo comenzado a preguntarse si ambos problemas, la duda innecesaria y la falsa seguridad, se ven exacerbados por las formas clich\u00e9 en las que nosotros (como evang\u00e9licos) hablamos sobre el evangelio (es decir, \u00abpide a Jes\u00fas en tu coraz\u00f3n\u00bb, \u00abacepta a Jes\u00fas como Se\u00f1or y Salvador\u00bb o \u00bb dale tu coraz\u00f3n a Jes\u00fas.\u201d)<\/p>\n<div style=\"clear:both;margin-top:0em;margin-bottom:1em\">\n<div class=\"centered-text-area\">\n<div class=\"texto centrado\" style=\"float: left\">\n<div class=\"u365b5fca746313df1a3195a5637180e9-content\">Ver tambi\u00e9n&nbsp; El poder de los momentos ordinarios<\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p>Estas frases pueden no estar equivocadas, pero la Biblia nunca nos dice , espec\u00edficamente, para buscar la salvaci\u00f3n de esa manera. El resumen b\u00edblico de una respuesta salvadora hacia Cristo es el arrepentimiento y la fe en el evangelio.<\/p>\n<p>Creer significa reconocer que Dios dijo la verdad acerca de Jes\u00fas, es decir, que \u00c9l es el Se\u00f1or y que ha terminado para siempre la obra de nuestro salvaci\u00f3n. El arrepentimiento significa actuar de acuerdo con esa creencia: invertir tu direcci\u00f3n en funci\u00f3n de qui\u00e9n entiendes que es Jes\u00fas.<\/p>\n<p>El arrepentimiento y la fe son fundamentalmente posturas del coraz\u00f3n hacia Dios. Puedes \u00abpedir a Jes\u00fas que entre en tu coraz\u00f3n\u00bb sin arrepentirte ni creer, y puedes arrepentirte y creer sin articular tal oraci\u00f3n.<\/p>\n<p>La salvaci\u00f3n no es una oraci\u00f3n que haces en una ceremonia \u00fanica y luego sigues adelante. de; la salvaci\u00f3n es una postura de arrepentimiento y fe que comienzas en un momento y mantienes por el resto de tu vida.<\/p>\n<p>La conversi\u00f3n a Cristo es como sentarse en una silla. Si ahora mismo est\u00e1s sentado, hubo un momento en el que trasladaste el peso de tu cuerpo de tus piernas a la silla. Puede que ni siquiera recuerdes haber tomado esa decisi\u00f3n, pero el hecho de que est\u00e9s sentado ahora prueba que lo hiciste.<\/p>\n<p>Cuando asumes esa posici\u00f3n por primera vez, puedes expresarla en una oraci\u00f3n. O puede que no. La postura es en s\u00ed misma un clamor a Dios por salvaci\u00f3n, ya sea que la articules o no.<\/p>\n<p>Pero solo porque oraste la oraci\u00f3n no significa que asumiste la postura, como tampoco decirle a una silla que est\u00e1s estar a punto de sentarse equivale a realmente sentarse.<\/p>\n<p>Entonces, cuando se trata de seguridad, la \u00fanica pregunta real es: \u00bfEst\u00e1s sentado en arrepentimiento hacia el Se\u00f1or\u00edo de Jes\u00fas y la fe en Su obra terminada ahora? <\/p>\n<h3>Dos cosas que no estoy diciendo<br \/> <\/h3>\n<p>No estoy diciendo que invitar a Jes\u00fas a tu coraz\u00f3n sea una herej\u00eda. <\/p>\n<p>Cuando somos \u00absalvos\u00bb, Jes\u00fas ciertamente \u00abentra en nuestros corazones\u00bb, al menos como una forma de hablar (Romanos 8:9\u201311; Efesios 3:17; Colosenses 1:27\u201328). ; G\u00e1latas 2:20).<\/p>\n<p>\u201cPedir a Jes\u00fas que entre en tu coraz\u00f3n\u201d es uno de los res\u00famenes m\u00e1s b\u00edblicos de la salvaci\u00f3n, si se entienden los conceptos detr\u00e1s de las palabras. \u201cCoraz\u00f3n\u201d en la Biblia (Proverbios 4:23) es el asiento de la persona.<\/p>\n<p>Hacer que Jes\u00fas entre en tu coraz\u00f3n, en ese sentido, significar\u00eda que \u00c9l se funde en lo m\u00e1s profundo de quien eres. son: que descanses tus esperanzas en Su justicia, te apoyes en \u00c9l para obtener fortaleza y te sometas a Su Se\u00f1or\u00edo en lo m\u00e1s profundo de tu ser. <\/p>\n<p>Tampoco estoy diciendo que no debamos presionar para que se tome una decisi\u00f3n. cuando presentamos el evangelio. <\/p>\n<p>El evangelio es de hecho una invitaci\u00f3n y cada vez que se predica esa invitaci\u00f3n debe extenderse de alguna forma (p. ej., Juan 1:12; Mateo 11:28; Apocalipsis 22:17). De hecho, si no instamos al oyente a responder personalmente a la oferta de Dios en Cristo, no creo que hayamos predicado el evangelio en su totalidad.<br \/> En \u00faltima instancia, mi preocupaci\u00f3n no es qu\u00e9 palabras o acciones podr\u00edamos usar para expresar nuestra fe en Cristo, pero que no sustituyamos esas palabras o acciones por el arrepentimiento y la fe.<\/p>\n<p>Para muchos, \u00abrezar la oraci\u00f3n del pecador\u00bb se ha convertido en algo as\u00ed como un ritual protestante por el que la gente pasa para entrar. cielo. Por encima de todo, debemos enfatizar la absoluta indispensabilidad del arrepentimiento y la fe para la salvaci\u00f3n.<\/p>\n<p>Me gustar\u00eda decirles a aquellos que, como yo, han invitado a Jes\u00fas a sus corazones miles de veces, que pueden \u201c deja de pedirle a Jes\u00fas que entre en su coraz\u00f3n\u201d y comienza a descansar en la obra terminada de Cristo.<\/p>\n<p>La salvaci\u00f3n no viene porque oraste correctamente, sino porque has apoyado las esperanzas de tu alma en la obra terminada de Cristo. .<br \/> Las frases abreviadas para el evangelio pueden tener un buen prop\u00f3sito, en la medida en que todos sepan exactamente lo que significan.<\/p>\n<p>Pero en vista del hecho de que tantos en nuestra naci\u00f3n parecen estar seguros de la salvaci\u00f3n, no dan evidencia de tener debido a una oraci\u00f3n que oraron, y tantos otros no pueden encontrar seguridad sin importar cu\u00e1n a menudo oren esa oraci\u00f3n, creo que es hora de dejar de lado la taquigraf\u00eda y predicar simplemente la salvaci\u00f3n por el arrepentimiento hacia Dios y la fe. en la obra consumada de Cristo.<br \/> O, al menos, tener cuidado de explicar e exactamente lo que queremos decir cuando pedimos una respuesta al evangelio.<\/p>\n<p><em>JD Greear es pastor principal en Summit Church en Raleigh-Durham, Carolina del Norte, y autor del libro <\/em> Deja de pedirle a Jes\u00fas que entre en tu coraz\u00f3n: c\u00f3mo saber con seguridad que eres salvo <em>(B&amp;H) del cual se extrajo este art\u00edculo.<\/em><\/p>\n<div class='yarpp -website yarpp-template-thumbnails'>\n<h3>Publicaciones relacionadas:<\/h3>\n<div class=\"yarpp-thumbnails-horizontal\"> 12 verdades de construir una cultura de oraci\u00f3n en su iglesia Deje de hacer que Jes\u00fas parezca aburrido 3 formas de Llegue a personas no religiosas en su comunidad <\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por JD Greear Si hubiera un r\u00e9cord en el Libro Guinness de r\u00e9cords mundiales por \u00abcantidad de veces haber pedido a Jes\u00fas que entre en tu coraz\u00f3n\u201d, estoy bastante seguro de que lo mantendr\u00eda. Para cuando cumpl\u00ed los 18 a\u00f1os, probablemente hab\u00eda \u201cpedido a Jes\u00fas que entrara en mi coraz\u00f3n\u201d 5000 veces. Empec\u00e9 alrededor de &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/deberiamos-dejar-de-pedirle-a-jesus-que-entre-en-nuestros-corazones\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfDeber\u00edamos dejar de pedirle a Jes\u00fas que entre en nuestros corazones?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4070","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=4070"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4070\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=4070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=4070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=4070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}