{"id":4087,"date":"2022-07-26T00:06:11","date_gmt":"2022-07-26T05:06:11","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/ofrendas-del-siglo-xxi-diez-razones-para-considerar-la-posibilidad-de-hacerlo-en-linea\/"},"modified":"2022-07-26T00:06:11","modified_gmt":"2022-07-26T05:06:11","slug":"ofrendas-del-siglo-xxi-diez-razones-para-considerar-la-posibilidad-de-hacerlo-en-linea","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/ofrendas-del-siglo-xxi-diez-razones-para-considerar-la-posibilidad-de-hacerlo-en-linea\/","title":{"rendered":"Ofrendas del siglo XXI: Diez razones para considerar la posibilidad de hacerlo en l\u00ednea"},"content":{"rendered":"<div class=\"entry-content\">\n<p>Las iglesias se est\u00e1n sumando a la tendencia de las donaciones en l\u00ednea en cifras r\u00e9cord. La mayor\u00eda considera que es una forma segura y eficiente de ayudar a sus miembros con una mayordom\u00eda constante. \u00bfSu iglesia ya comenz\u00f3 a ofrecerlo?<\/p>\n<p>Aqu\u00ed hay 10 razones por las que su iglesia podr\u00eda querer considerar las donaciones en l\u00ednea.<\/p>\n<ol>\n<li>Sus miembros apreciar\u00e1n que la iglesia les facilite dar. Y muchas de las personas de su congregaci\u00f3n ya est\u00e1n acostumbradas al proceso de usar tarjetas de cr\u00e9dito o d\u00e9bito en l\u00ednea.<\/li>\n<li>Muchas de las personas m\u00e1s j\u00f3venes de su congregaci\u00f3n no llevan efectivo ni chequeras.<\/li>\n<li>No son solo los pastores j\u00f3venes los que hacen esto. Seg\u00fan un estudio de Lifeway Research, el 62 por ciento de las iglesias que utilizan donaciones en l\u00ednea tienen pastores mayores de 50 a\u00f1os.<\/li>\n<li>La gente gasta dinero en l\u00ednea; \u00bfPor qu\u00e9 no alentarlos a dar dinero en l\u00ednea?<\/li>\n<li>La Reserva Federal dijo que la cantidad de cheques emitidos entre 2006 y 2009 disminuy\u00f3 en m\u00e1s del 7 por ciento. En el mismo per\u00edodo, los pagos electr\u00f3nicos aumentaron m\u00e1s del 9 por ciento. Los pagos electr\u00f3nicos representaron m\u00e1s del 75 por ciento de todas las transacciones financieras en 2010.<\/li>\n<li>Es f\u00e1cil recordarle a la gente en su sitio web, en su bolet\u00edn o en su bolet\u00edn informativo que las donaciones en l\u00ednea son una opci\u00f3n.<\/li>\n<li>Si no se siente c\u00f3modo sugiriendo que las personas usen tarjetas de cr\u00e9dito para dar, todav\u00eda tiene opciones. Pueden usar tarjetas de d\u00e9bito, giros bancarios autom\u00e1ticos, donaciones m\u00f3viles, pago de facturas en l\u00ednea, etc.<\/li>\n<li>Las donaciones en l\u00ednea pueden ayudar a los miembros a mantener sus donaciones constantes durante la &#8220;recesi\u00f3n&#8221; momentos como las temporadas de vacaciones y los veranos. Cuando se registran para pagos autom\u00e1ticos, pueden ser obedientes en sus ofrendas si tienen que faltar a la iglesia por alguna raz\u00f3n. Y tambi\u00e9n permite a los miembros confinados en el hogar la oportunidad de donar incluso cuando no pueden asistir.<\/li>\n<li>Muchos de sus miembros ya est\u00e1n donando en l\u00ednea a otras organizaciones ben\u00e9ficas.<\/li>\n<li>Si bien solo alrededor El 4 por ciento de los estadounidenses practica el diezmo, las donaciones en l\u00ednea pueden ayudar a los miembros de la iglesia a ser m\u00e1s consistentes en sus donaciones a trav\u00e9s de retiros autom\u00e1ticos de sus cuentas bancarias o tarjetas de cr\u00e9dito.<\/li>\n<\/ol>\n<div class='yarpp yarpp-related yarpp-related -website yarpp-template-thumbnails'>\n<div style=\"clear:both;margin-top:0em;margin-bottom:1em\">\n<div class=\"centered-text-area\">\n<div class=\"centered -text\" style=\"float: left\">\n<div class=\"uf0c5cc40d0c618df8ad497c724ca9561-content\">Ver tambi\u00e9n&nbsp; \u00bfEs un &#8216;fracaso del ministerio&#8217; ver a un consejero?<\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<h3>Publicaciones relacionadas:<\/h3>\n<div class=\"yarpp-thumbnails-horizontal\"> \u00bfQu\u00e9 despierta la generosidad evang\u00e9lica? Las iglesias de discipulado soportan dificultades financieras en a\u00f1os de pandemia, son optimistas para el futuro El cambio tecnol\u00f3gico m\u00e1s impactante que su iglesia puede hacer La mitad de los pastores ven un impacto econ\u00f3mico negativo para la iglesia <\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Las iglesias se est\u00e1n sumando a la tendencia de las donaciones en l\u00ednea en cifras r\u00e9cord. La mayor\u00eda considera que es una forma segura y eficiente de ayudar a sus miembros con una mayordom\u00eda constante. \u00bfSu iglesia ya comenz\u00f3 a ofrecerlo? Aqu\u00ed hay 10 razones por las que su iglesia podr\u00eda querer considerar las donaciones &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/ofrendas-del-siglo-xxi-diez-razones-para-considerar-la-posibilidad-de-hacerlo-en-linea\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abOfrendas del siglo XXI: Diez razones para considerar la posibilidad de hacerlo en l\u00ednea\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4087","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=4087"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/4087\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=4087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=4087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=4087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}