{"id":46725,"date":"2022-08-03T13:12:02","date_gmt":"2022-08-03T18:12:02","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/rc-sproul-te-preocupas-por-las-viudas\/"},"modified":"2022-08-03T13:12:02","modified_gmt":"2022-08-03T18:12:02","slug":"rc-sproul-te-preocupas-por-las-viudas","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/rc-sproul-te-preocupas-por-las-viudas\/","title":{"rendered":"RC Sproul: \u00bfTe preocupas por las viudas?"},"content":{"rendered":"<p>En t\u00e9rminos b\u00edblicos, ser religioso no significa necesariamente que seas piadoso. Ser religioso puede significar simplemente que est\u00e1s involucrado en las trampas de la religi\u00f3n, que puedes ser miembro de una religi\u00f3n falsa. Sin embargo, las Escrituras a veces hablan de la religi\u00f3n en un sentido positivo, en el sentido de la pr\u00e1ctica que es el fruto de la verdadera fe en Cristo y el compromiso con Su Palabra.<\/p>\n<p>El ap\u00f3stol Santiago se enfoca en la religi\u00f3n como la pr\u00e1ctica de aquellos que tienen verdadera fe en Jes\u00fas, y \u00e9l dice que la verdadera religi\u00f3n demuestra la presencia de la confianza salvadora en el Se\u00f1or (Santiago 2:14\u201326). El aspecto de la verdadera piedad, nos dice, no es un asunto de simplemente aferrarnos a la doctrina correcta con nuestras mentes, aunque eso es esencial. No, la verdadera piedad significa que la doctrina da forma a nuestras vidas a tal grado que manifestamos el tipo de vida que Dios quiere que vivamos. Y Santiago nos da una definici\u00f3n sucinta de la verdadera religi\u00f3n, de la verdadera piedad: \u201cLa religi\u00f3n pura y sin m\u00e1cula delante de Dios el Padre es esta: Visitar a los hu\u00e9rfanos y a las viudas en sus tribulaciones, y guardarse sin mancha del mundo\u201d. James eleva la actividad de cuidar de las viudas y los hu\u00e9rfanos como la esencia misma de la religi\u00f3n pura y sin mancha. Eso me parece muy significativo, y es una idea que se descuida en la iglesia de hoy.<\/p>\n<p>En este art\u00edculo, quiero enfocarme particularmente en las viudas. Las viudas y su cuidado ocupan un lugar destacado en la agenda que Dios ha establecido para su iglesia. Uno de los primeros problemas que surgieron en la iglesia apost\u00f3lica fue que las viudas estaban siendo desatendidas. Y si eso era un problema en la iglesia del primer siglo, \u00bfcu\u00e1nto m\u00e1s probable es que nosotros, veinte siglos despu\u00e9s, seamos culpables de descuidar a las viudas entre nosotros?<\/p>\n<p>Despu\u00e9s de que mi abuelo muri\u00f3, mi mi abuela se mud\u00f3 a nuestra casa y vivi\u00f3 con nosotros durante muchos a\u00f1os mientras yo crec\u00eda. En varias ocasiones, me hablaba tarde en la noche y lloraba, cont\u00e1ndome la carga de dolor que ten\u00eda al sentir que no solo hab\u00eda perdido a su esposo sino que tambi\u00e9n hab\u00eda perdido su lugar en la comunidad. Una vez que su esposo falleci\u00f3, de repente se sinti\u00f3 excluida de las cosas en las que estaba \u00edntimamente involucrada junto a \u00e9l mientras estaba vivo. Cuando una persona pierde a su compa\u00f1ero de toda la vida, es como perder una parte \u00edntima e integral de uno mismo porque el esposo y la esposa, se nos dice, en el misterio del matrimonio son una sola carne. Entonces, el dolor de la viudez trae una dimensi\u00f3n \u00fanica de soledad. Es molesto estar solo de repente cuando uno ha estado acostumbrado a la compa\u00f1\u00eda constante con su c\u00f3nyuge durante un largo per\u00edodo de tiempo. Dado que Dios es el gran Consolador de Su pueblo, tiene sentido que se preocupe tanto por las viudas dado el dolor que experimentan.<\/p>\n<p>Ahora, \u00bfpor qu\u00e9 Santiago no menciona a los viudos? Despu\u00e9s de todo, el viudo tambi\u00e9n experimenta la misma punzada de sufrimiento que acompa\u00f1a a la p\u00e9rdida de un compa\u00f1ero de toda la vida. Bueno, todos los hombres con los que he hablado siempre dicen que quieren ir primero porque no pueden imaginar vivir la vida sin sus esposas. No puedo probarlo, pero creo que esa es una de las razones por las que la esperanza de vida normal del hombre es m\u00e1s corta que la esperanza de vida de la mujer, porque Dios es misericordioso con nosotros los hombres y sabe que no somos tan fuertes como mujeres. Pero lo que s\u00ed s\u00e9 con certeza es que las viudas siempre han experimentado dificultades particulares en cada \u00e9poca y cultura. Enfrentaron problemas particulares en el mundo antiguo. No hab\u00eda programas de seguros, rentas vitalicias u otro tipo de cosas, y sin marido, la viuda sol\u00eda ser la persona m\u00e1s vulnerable e indefensa de la comunidad. Las viudas ten\u00edan pocos o ning\u00fan medio de sustento en las sociedades antiguas. As\u00ed, el cuidado de las viudas le fue dado a la iglesia tanto en el Antiguo Testamento como en el Nuevo.<\/p>\n<p>Jes\u00fas frecuentemente presta atenci\u00f3n a las viudas en Su ense\u00f1anza. Solo considere la historia del \u00f3bolo de la viuda en Marcos 12:41\u201345. \u00bfQui\u00e9n es el que normalmente llama la atenci\u00f3n en la iglesia? Las personas que son los grandes donantes, aquellas cuyas donaciones son tan importantes para la financiaci\u00f3n continua del presupuesto de la iglesia. Pocos prestan atenci\u00f3n a la persona azotada por la pobreza que hace una peque\u00f1a donaci\u00f3n que es insignificante para el resultado final del presupuesto. Pero Jes\u00fas not\u00f3 lo que todos los dem\u00e1s pasaban por alto. Les dijo a sus oyentes que miraran a la viuda pobre. Aunque la mujer dio solo el equivalente de dos centavos al templo, ella ech\u00f3 m\u00e1s que todo el resto de la gente que don\u00f3 mucho al tesoro porque al dar de su propia pobreza, dio por su devoci\u00f3n a Dios. <\/p>\n<p>Uno de los momentos m\u00e1s tiernos registrados en el Nuevo Testamento se encuentra en Juan 19:16b\u201327. Mientras Cristo estaba en la cruz, mir\u00f3 en direcci\u00f3n a su madre, quien fue testigo ocular de su pasi\u00f3n, y le dijo: \u201cMujer, ah\u00ed tienes a tu hijo\u201d. No le estaba pidiendo a su madre que lo mirara. Obviamente, ella ya lo estaba mirando. Entonces, Jes\u00fas le dijo a Juan: \u201c\u00a1Ah\u00ed tienes a tu madre!\u201d En sus \u00faltimos momentos, Jes\u00fas estaba encomendando el cuidado de su madre viuda a su amado disc\u00edpulo Juan. En la cruz, Jes\u00fas le dijo a Juan: \u201cJuan, cuida a mi madre. Ella es viuda, as\u00ed que d\u00e9jala ser para ti como tu propia madre\u201d. A Mar\u00eda le dijo: \u201cMadre, que Juan sea para ti como tu propio hijo\u201d.<\/p>\n<p>\u00bfPara qu\u00e9 son los hijos? Para cuidar de sus madres. \u00bfPara qu\u00e9 est\u00e1n las madres sino para cuidar a sus hijos? Cuando piensas en todos los a\u00f1os y las oportunidades en que las madres han cuidado a sus hijos cuando entran en su soledad, la primera l\u00ednea de cuidado debe ser la familia sobreviviente. Pero de ninguna manera se detiene all\u00ed, porque la familia m\u00e1s grande es la iglesia. Santiago, el hermano de Jes\u00fas, ve este mandato de cuidar a las viudas tan importante que lo usa para describir la esencia cristalizada de la verdadera religi\u00f3n. \u00bfCrees que eres religioso, pero no te importan las viudas? Su religi\u00f3n es un ejercicio in\u00fatil, porque Santiago dice que la religi\u00f3n pura y sin mancha es el cuidado de las viudas y los hu\u00e9rfanos en tiempos de angustia.<\/p>\n<p><em>Este art\u00edculo se public\u00f3 originalmente aqu\u00ed y se usa con permiso. <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En t\u00e9rminos b\u00edblicos, ser religioso no significa necesariamente que seas piadoso. Ser religioso puede significar simplemente que est\u00e1s involucrado en las trampas de la religi\u00f3n, que puedes ser miembro de una religi\u00f3n falsa. Sin embargo, las Escrituras a veces hablan de la religi\u00f3n en un sentido positivo, en el sentido de la pr\u00e1ctica que es &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/rc-sproul-te-preocupas-por-las-viudas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abRC Sproul: \u00bfTe preocupas por las viudas?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-46725","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/46725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=46725"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/46725\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=46725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=46725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=46725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}