{"id":46726,"date":"2022-08-03T13:12:04","date_gmt":"2022-08-03T18:12:04","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/7-pecados-de-los-lideres-egoistas\/"},"modified":"2022-08-03T13:12:04","modified_gmt":"2022-08-03T18:12:04","slug":"7-pecados-de-los-lideres-egoistas","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/7-pecados-de-los-lideres-egoistas\/","title":{"rendered":"7 Pecados de los l\u00edderes ego\u00edstas"},"content":{"rendered":"<p class=\"first-child\">Los l\u00edderes a menudo sucumben a la tentaci\u00f3n de hacer todo sobre ellos. Se trata de sus objetivos, su carrera y su reconocimiento. Se convierten en l\u00edderes ego\u00edstas.<\/p>\n<p>Pero Dios nos ha llamado a ser un tipo diferente de l\u00edder. Dios nos ha llamado a ser mayordomos de las personas. Y en lugar de tomar de nuestro equipo, \u00c9l nos ha llamado a darnos a nuestro equipo. \u00c9l nos ha llamado a ser l\u00edderes generosos. Pero, \u00bfc\u00f3mo se ve eso?<\/p>\n<p>Veamos siete de los pecados m\u00e1s comunes de los l\u00edderes ego\u00edstas y c\u00f3mo superarlos:<\/p>\n<ol>\n<li><strong>Disfrutar de la atenci\u00f3n. <\/strong>En su lugar, d\u00e9 cr\u00e9dito. Se\u00f1ala a los dem\u00e1s. El \u00e9xito de un l\u00edder nunca se trata de \u00e9l. Se trata de ellos. Si bien es f\u00e1cil empaparse de los elogios de los dem\u00e1s, d\u00e9 cr\u00e9dito a quien lo merece. Recuerde que su \u00e9xito es su \u00e9xito.<\/li>\n<\/ol>\n<ol start=\"2\">\n<li><strong>Escatimar en el pago. <\/strong>En su lugar, d\u00e9 un salario justo. No pague intencionalmente de menos a los que supervisa. No se aproveche de la ingenuidad de una persona. Haz lo mejor que puedas cuando puedas. Y cuando pueda, p\u00e9rese en un salario generoso.<\/li>\n<\/ol>\n<ol start=\"3\">\n<li><strong>Autoridad limitada.<\/strong> En su lugar, asigne m\u00e1s responsabilidad. Cuando un miembro del equipo lo est\u00e1 haciendo bien, aumente su alcance. Hay algunas maneras en que esto puede suceder. Puede delegar algunas de sus responsabilidades actuales. Puede cambiar las responsabilidades existentes que tienen un bajo rendimiento en otras \u00e1reas. O puede agregar responsabilidades que no existen actualmente pero que son necesarias.<\/li>\n<\/ol>\n<ol start=\"4\">\n<li><strong>Estimular el trabajo sobre la familia. <\/strong>En su lugar, d\u00e9 tiempo a los miembros del equipo para cuidar de sus familias. H\u00e1gales saber a los miembros de su equipo que tienen la libertad de hacerse cargo de sus responsabilidades familiares. Si un ni\u00f1o est\u00e1 enfermo y nadie m\u00e1s puede cuidarlo, d\u00edgale que se vaya. Cuida a ese ni\u00f1o. Si hay una muerte en la familia, d\u00edgales que se vayan. Consuela a la familia. No te preocupes. No se aprovechar\u00e1n de usted. Conf\u00eda en m\u00ed, su c\u00f3nyuge no querr\u00e1 que pierdan un trabajo donde su familia es lo primero.<\/li>\n<\/ol>\n<ol start=\"5\">\n<li><strong>Acaparamiento de informaci\u00f3n. <\/strong>En cambio, da conocimiento. No oculte informaci\u00f3n que considere pertinente para el \u00e9xito de los miembros del equipo. A algunos l\u00edderes les gusta acumular conocimiento porque los hace sentir poderosos. Esto es rid\u00edculo. Proporcione a su equipo cualquier conocimiento que pueda ayudarlos. Comparta cualquier dato, investigaci\u00f3n, literatura o informaci\u00f3n que sea beneficiosa para ellos.<\/li>\n<\/ol>\n<ol start=\"6\">\n<li><strong>Aislarse. <\/strong>En su lugar, d\u00e9 tiempo. Aseg\u00farese de que la puerta de su oficina est\u00e9 abierta m\u00e1s de lo que est\u00e1 cerrada. Aseg\u00farate de que tu equipo sepa que quieres saber de ellos. Incluso si no lo aceptan, su disponibilidad para ellos les comunicar\u00e1 algo importante.<\/li>\n<\/ol>\n<ol start=\"7\">\n<li><strong>Retener la gratitud. <\/strong>En su lugar, aprecie. Di \u201cgracias\u201d a menudo. Trato de escribir cinco notas de agradecimiento todos los d\u00edas de trabajo. Esto tambi\u00e9n puede funcionar para usted. Si no es as\u00ed, trate de encontrar alguna manera de inculcar la gratitud en su rutina diaria.<\/li>\n<\/ol>\n<p>Esfu\u00e9rcese por ser un l\u00edder generoso. Los l\u00edderes son mayordomos de las personas. Entr\u00e9gate a ellos y ellos se entregar\u00e1n a ti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los l\u00edderes a menudo sucumben a la tentaci\u00f3n de hacer todo sobre ellos. Se trata de sus objetivos, su carrera y su reconocimiento. Se convierten en l\u00edderes ego\u00edstas. Pero Dios nos ha llamado a ser un tipo diferente de l\u00edder. Dios nos ha llamado a ser mayordomos de las personas. Y en lugar de tomar &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/7-pecados-de-los-lideres-egoistas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab7 Pecados de los l\u00edderes ego\u00edstas\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-46726","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/46726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=46726"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/46726\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=46726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=46726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=46726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}