{"id":47894,"date":"2022-08-03T13:58:44","date_gmt":"2022-08-03T18:58:44","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/el-espiritu-santo-en-el-antiguo-testamento\/"},"modified":"2022-08-03T13:58:44","modified_gmt":"2022-08-03T18:58:44","slug":"el-espiritu-santo-en-el-antiguo-testamento","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/el-espiritu-santo-en-el-antiguo-testamento\/","title":{"rendered":"El Esp\u00edritu Santo en el Antiguo Testamento"},"content":{"rendered":"<p>El Esp\u00edritu Santo en el Antiguo Testamento est\u00e1 presente y obra de manera significativa, comenzando en el relato de la creaci\u00f3n de G\u00e9nesis 1. Mientras que la deidad y el car\u00e1cter del Esp\u00edritu Santo obviamente no han cambiado, la obra del Esp\u00edritu Santo era distinta en el Antiguo Testamento (pacto) en comparaci\u00f3n con Su obra despu\u00e9s de la muerte, sepultura y resurrecci\u00f3n de Cristo, como se describe en el Nuevo Testamento (pacto).<\/p>\n<p>Toda salvaci\u00f3n, ya sea para aquellos que fueron justificados en el Antiguo Testamento o en el Nuevo Testamento, solo es posible por el Esp\u00edritu Santo, debido a la obra consumada de Cristo y sobre la base de la fe, aunque los santos del Antiguo Testamento no tuvieron la revelaci\u00f3n completa de la obra de Cristo. (Ver Romanos 3:21-4:25). En cierto sentido, los santos del Antiguo Testamento fueron salvos \u201ca cr\u00e9dito\u201d. 1 Se ve al Esp\u00edritu Santo \u201cluchando con los hombres\u201d en G\u00e9nesis 6:3, trayendo as\u00ed a los pecadores a la convicci\u00f3n (una obra descrita tambi\u00e9n en Juan 16:8).<\/p>\n<p>La palabra principal del Antiguo Testamento para el Esp\u00edritu Santo es ruah, usado aproximadamente 388 veces. La palabra principal del Nuevo Testamento para el Esp\u00edritu Santo es Pneuma, usada 378 veces. Sin embargo, el Nuevo Testamento tiene una cuarta parte de extensi\u00f3n, lo que significa que la obra del Esp\u00edritu se menciona aproximadamente cuatro veces m\u00e1s a menudo. El Nuevo Testamento da mayor \u00e9nfasis a la santidad del Esp\u00edritu (94 veces). Algunas asociaciones del Antiguo Testamento con la obra del Esp\u00edritu como juicio, ardor, entendimiento, consejo, poder, conocimiento y s\u00faplicas no se enfatizan en el Nuevo Testamento. Por otro lado, el Nuevo Testamento habla \u00fanicamente de los conceptos de vida, verdad, adopci\u00f3n, poder, fe, promesa y eternidad en conexi\u00f3n con la obra del Esp\u00edritu Santo. 2<\/p>\n<p>En el Antiguo Testamento, la obra m\u00e1s notable del Esp\u00edritu era el empoderamiento especial para tareas o asignaciones espec\u00edficas. Por ejemplo, el Esp\u00edritu del Se\u00f1or \u201cvino sobre\u201d los jueces (Jueces 3:10, 6:34, 11:29, 13:2-5, 14:6 y 19, 15:14). El Esp\u00edritu tambi\u00e9n descendi\u00f3 sobre los artesanos escogidos por Dios para trabajar en el tabern\u00e1culo o Templo (\u00c9xodo 31:3-6; 1 Cr\u00f3nicas 28:11, 12; 1 Reyes 7:13, 14). Los administradores civiles tambi\u00e9n experimentaron el empoderamiento del Esp\u00edritu. Esto inclu\u00eda a Mois\u00e9s y los 70 ancianos (N\u00fameros 11:17), Josu\u00e9 (N\u00fameros 27:18), Sa\u00fal (1 Samuel 11:6) y David (1 Samuel 16:13). Sabemos que el Esp\u00edritu Santo se apart\u00f3 de Sa\u00fal (1 Samuel 18:10) y David tem\u00eda una partida similar como lo expresamos en el Salmo 51:11.<\/p>\n<p>El Esp\u00edritu tambi\u00e9n llen\u00f3 temporalmente a algunos profetas del Antiguo Testamento para sus tareas asignadas. tareas (2 Cr\u00f3nicas 15:17, 20:1, 14-17,22, 23, 24:20; N\u00fameros 24:2; 1 Cr\u00f3nicas 12:18). Algunos profetas parec\u00edan estar continuamente empoderados por el Esp\u00edritu Santo, como El\u00edas, Eliseo, Miqueas y Ezequiel. No se hizo referencia espec\u00edfica a otros profetas como empoderados o llenos del Esp\u00edritu Santo, pero sabemos que de hecho fueron \u00abimpulsados por el Esp\u00edritu Santo\u00bb para escribir las Escrituras (2 Pedro 1:21).<\/p>\n<p> En resumen, el Antiguo Testamento demuestra que el Esp\u00edritu Santo fue dado de forma selectiva e incluso temporal para morar en ciertos individuos. Un vers\u00edculo clave para distinguir la diferencia de la obra del Esp\u00edritu del nuevo pacto se encuentra en la declaraci\u00f3n de Jes\u00fas a los disc\u00edpulos en Juan 14:17, \u201cel Esp\u00edritu de verdad, al cual el mundo no puede recibir, porque no le ve ni le conoce\u201d. . Lo conoc\u00e9is, porque mora con vosotros y estar\u00e1 en vosotros\u201d. Jes\u00fas hace una distinci\u00f3n primordial. Los disc\u00edpulos entendieron que el Esp\u00edritu Santo hab\u00eda estado con ellos, y los santos del Antiguo Testamento. Ahora, por la obra de Cristo, \u00c9l estar\u00eda en ellos para siempre. (Juan 14:16)<\/p>\n<p>Entonces, debido a la obra de Cristo, el Nuevo Testamento ense\u00f1a que el Esp\u00edritu Santo mora en los creyentes universal y permanentemente. El nuevo pacto incorpora las realidades \u00fanicas de todos los creyentes siendo bautizados en el cuerpo de Cristo (1 Corintios 12:13), habitados (Romanos 8:9) y sellados permanentemente por Dios a trav\u00e9s del Esp\u00edritu Santo hasta el D\u00eda de la Redenci\u00f3n (2 Corintios 1 :21-22; Efesios 4:30). Cada creyente (en contraste con solo ciertos individuos en el Antiguo Testamento) est\u00e1 facultado por el Esp\u00edritu para el servicio sobrenatural a trav\u00e9s de los dones espirituales (1 Corintios 12:4-11). Estas promesas y su permanencia nos brindan una gran confianza en todas las ense\u00f1anzas del Nuevo Testamento sobre la obra de adentro hacia afuera del Esp\u00edritu Santo para santificarnos, transformarnos, guiarnos, iluminarnos, capacitarnos y usarnos para la gloria de Cristo.<\/p>\n<p>1. Ver Robert Jeffress: https:\/\/www.youtube.com\/watch?v=XHjJkSWJAyk<\/p>\n<p>2. Leon J. Wood, The Holy Spirit in the Old Testament. (Grand Rapids: Zondervan, 1976) 20 \u2013 22<\/p>\n<p><em>Este art\u00edculo sobre el Esp\u00edritu Santo en el Antiguo Testamento apareci\u00f3 originalmente aqu\u00ed.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Esp\u00edritu Santo en el Antiguo Testamento est\u00e1 presente y obra de manera significativa, comenzando en el relato de la creaci\u00f3n de G\u00e9nesis 1. Mientras que la deidad y el car\u00e1cter del Esp\u00edritu Santo obviamente no han cambiado, la obra del Esp\u00edritu Santo era distinta en el Antiguo Testamento (pacto) en comparaci\u00f3n con Su obra &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/el-espiritu-santo-en-el-antiguo-testamento\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEl Esp\u00edritu Santo en el Antiguo Testamento\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-47894","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/47894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=47894"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/47894\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=47894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=47894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=47894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}