{"id":47905,"date":"2022-08-03T13:59:07","date_gmt":"2022-08-03T18:59:07","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/8-pasos-para-comunicar-con-exito-la-politica-de-mascarillas-de-su-iglesia\/"},"modified":"2022-08-03T13:59:07","modified_gmt":"2022-08-03T18:59:07","slug":"8-pasos-para-comunicar-con-exito-la-politica-de-mascarillas-de-su-iglesia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/8-pasos-para-comunicar-con-exito-la-politica-de-mascarillas-de-su-iglesia\/","title":{"rendered":"8 pasos para comunicar con \u00e9xito la pol\u00edtica de mascarillas de su iglesia"},"content":{"rendered":"<p><strong>La unidad en la iglesia local est\u00e1 bajo ataque.<\/strong> Hemos superado los himnos frente a la m\u00fasica de alabanza. Actualmente, los pastores est\u00e1n lidiando con problemas como reapertura versus virtual y el momento de esas decisiones, elementos raciales y el momento, contenido e intensidad de esos mensajes, seguridad versus servicios, protestas p\u00fablicas pero no servicios p\u00fablicos de adoraci\u00f3n, y si eso no fuera suficiente. , usar m\u00e1scaras versus no usar m\u00e1scaras al reabrir. Los pastores necesitan ayuda con la pol\u00edtica de m\u00e1scaras de su iglesia.<\/p>\n<p><strong>El domingo pasado asist\u00ed al servicio de reapertura de Fellowship Bible Church en Roswell, GA.<\/strong> Fue una experiencia absolutamente maravillosa . Anteriormente escrib\u00ed sobre el sorprendente mensaje del pastor principal Crawford Lorrits en la publicaci\u00f3n 39 citas sobre c\u00f3mo convertirse en un l\u00edder carism\u00e1tico y m\u00e1s indulgente. Deber\u00eda echarle un vistazo.<\/p>\n<p>Adem\u00e1s del mensaje de Crawford,<strong> una de las razones por las que fue un gran servicio fue el esp\u00edritu de los asistentes, particularmente en el tema del uso de mascarillas<\/strong>. TODOS usaban m\u00e1scaras, pero no era un problema. Esto se debe a c\u00f3mo se manej\u00f3 en las semanas previas a su reapertura. Como siempre, te preparar\u00e1s o reparar\u00e1s como l\u00edder.<\/p>\n<p>Si eres un pastor que se enfrenta a este problema, los siguientes son principios que obtuve del fin de semana pasado.<\/p>\n<h2><strong>8 Pasos para comunicar con \u00e9xito la pol\u00edtica de mascarillas de su iglesia sobre el uso de mascarillas en los servicios religiosos<\/strong><\/h2>\n<h3>1. El pastor debe ser la autoridad moral y visionario para usar m\u00e1scaras.<\/h3>\n<p>As\u00ed va el l\u00edder, as\u00ed va la gente. Comenzando varias semanas antes de la reapertura del servicio, Crawford proporcion\u00f3 videos semanales discutiendo varias cosas en su coraz\u00f3n. Estos iban desde noticias est\u00e1ndar de la iglesia hasta art\u00edculos de reconciliaci\u00f3n racial y el uso de m\u00e1scaras cuando comenzaron a reunirse nuevamente. Hablar\u00e9 m\u00e1s sobre su contenido a continuaci\u00f3n, pero Crawford comunic\u00f3 claramente que usar\u00eda una m\u00e1scara y por qu\u00e9. Para la unidad dentro del cuerpo de la iglesia, el pastor debe liderar comunicando claramente la postura de la iglesia sobre este tema. No se puede delegar a otro miembro del personal ni ocultarse en un correo electr\u00f3nico semanal. El liderazgo determina la direcci\u00f3n. La organizaci\u00f3n determina el potencial. Las personas, con la ayuda de Dios, determinan el \u00e9xito. Pero no puedo enfatizar esto lo suficiente, todo comienza con el pastor principal.<\/p>\n<h3>2. Usar una m\u00e1scara es un acto de amor.<\/h3>\n<p>Crawford reconoci\u00f3 que habr\u00eda una variedad de opiniones entre los miembros de Fellowship sobre el uso de m\u00e1scaras. Sin embargo, para proporcionar un entorno seguro para TODOS los que deseen asistir a los servicios en vivo, todos usar\u00e1n m\u00e1scaras, comenzando por \u00e9l. En resumen, Crawford dijo que la Ley del Amor se demuestra al dejar de lado tus preferencias y opiniones personales por el bien de los dem\u00e1s. Usar una m\u00e1scara durante el servicio ser\u00eda una se\u00f1al de que amabas a tus vecinos que estaban sentados cerca de ti.<\/p>\n<h3>3. Opte por las reglas, no por las pautas.<\/h3>\n<p>El lenguaje es un gran problema. Frases como \u00abpreferimos\u00bb o \u00abestamos poniendo a disposici\u00f3n m\u00e1scaras si elige usar una\u00bb o \u00abestamos preguntando\u00bb o \u00ablos CDC recomiendan\u00bb dan a las personas la oportunidad de rechazar. Las pautas son sugerencias. Las reglas proporcionan claridad. La gente necesita y aprecia la claridad. En este caso, si realiz\u00f3 los puntos 1 y 2 correctamente, la claridad sobre este tema deja de ser un problema.<\/p>\n<h3>4. Valore a las personas por encima del proceso.<\/h3>\n<p>Las reglas sin relaci\u00f3n conducen a la rebeli\u00f3n. Si amas a tu gente, con gusto seguir\u00e1n el proceso. El objetivo no es que la gente entre en su edificio. El objetivo no es hacer que las personas usen una m\u00e1scara o distanciamiento social. El objetivo es ser anfitri\u00f3n. Cuando recibes a alguien en tu casa, quieres que se sienta bienvenido. Despu\u00e9s de todo, no has visto a estas personas en meses. Primero, deber\u00edas estar realmente emocionado de verlos. Luego puede implementar sus procesos.<\/p>\n<h3>5. El pastor dirige desde el frente.<\/h3>\n<p>Crawford estaba en el vest\u00edbulo, con una mascarilla y dando la bienvenida a la gente. Si la gente ve que el pastor dirige de manera apropiada, gustosamente seguir\u00e1n su ejemplo. Los pastores no pueden estar en la sala verde mientras las iglesias reabren.<\/p>\n<h3>6. El enfoque lo es todo. Cantar con una m\u00e1scara. Escuche Predicaci\u00f3n sin mascarilla.<\/h3>\n<p>A las personas que tienen dificultades para usar una mascarilla, d\u00e9les permiso para quit\u00e1rsela durante la predicaci\u00f3n. Esto proporciona un alivio bienvenido. Este enfoque demuestra que se aprecian todas las opiniones y puntos de vista.<\/p>\n<h3>7. Diga \u201cGracias\u201d temprano y con frecuencia.<\/h3>\n<p>La amabilidad es una cualidad muy atractiva. Al comienzo de su mensaje, Crawford agradeci\u00f3 amablemente a todos por el distanciamiento social y por adherirse a la postura de la iglesia sobre el uso de m\u00e1scaras. Tambi\u00e9n estaba genuinamente emocionado de ver a todos. Dijo con humor: \u00ab\u00a1No me dejes!\u00bb Cuando los l\u00edderes expresan aprecio, la mayor\u00eda de la gente los seguir\u00e1 a cualquier parte.<\/p>\n<h3>8. Salir por filas, no por secciones.<\/h3>\n<p>Al final del servicio, se agradeci\u00f3 nuevamente a la congregaci\u00f3n (recuerde, temprano y con frecuencia) por amar a sus vecinos usando m\u00e1scaras. Luego se les indic\u00f3 que salieran de los servicios poni\u00e9ndose las m\u00e1scaras y saliendo de la \u00faltima fila hacia el frente. Al salir por tramos no se produce el distanciamiento social y se quita el esp\u00edritu de seguridad.<\/p>\n<p>\u00bfC\u00f3mo llevas el tema del uso de mascarilla?<\/p>\n<p><em>Este art\u00edculo sobre la pol\u00edtica de mascarillas de su iglesia apareci\u00f3 originalmente aqu\u00ed.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La unidad en la iglesia local est\u00e1 bajo ataque. Hemos superado los himnos frente a la m\u00fasica de alabanza. Actualmente, los pastores est\u00e1n lidiando con problemas como reapertura versus virtual y el momento de esas decisiones, elementos raciales y el momento, contenido e intensidad de esos mensajes, seguridad versus servicios, protestas p\u00fablicas pero no servicios &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/8-pasos-para-comunicar-con-exito-la-politica-de-mascarillas-de-su-iglesia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab8 pasos para comunicar con \u00e9xito la pol\u00edtica de mascarillas de su iglesia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-47905","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/47905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=47905"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/47905\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=47905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=47905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=47905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}