{"id":58611,"date":"2022-08-03T23:58:36","date_gmt":"2022-08-04T04:58:36","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/iglesias-sin-edificios-en-usa-today\/"},"modified":"2022-08-03T23:58:36","modified_gmt":"2022-08-04T04:58:36","slug":"iglesias-sin-edificios-en-usa-today","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/iglesias-sin-edificios-en-usa-today\/","title":{"rendered":"Iglesias sin edificios en USA Today"},"content":{"rendered":"<p>Las iglesias sin edificios est\u00e1n en las noticias, en la portada de USA Today, nada menos.<\/p>\n<p>El fen\u00f3meno es cada vez m\u00e1s com\u00fan. El domingo, con humor&nbsp;envi\u00e9 un blog sobre nuestra propia experiencia esta semana. Incluso hay un libro llamado &nbsp;<em>La Iglesia N\u00f3mada<\/em>.<\/p>\n<p>La&nbsp;USA Today&nbsp;historia cita algunos hechos r\u00e1pidos que incluyen:<\/p>\n<blockquote>\n<p>&amp;bull ; Una mirada de USA TODAY a los cinco distritos escolares m\u00e1s grandes y los cinco de m\u00e1s r\u00e1pido crecimiento en los EE. UU. continentales encontr\u00f3 que los 10 hab\u00edan otorgado permisos para que las congregaciones religiosas celebraran cultos de fin de semana.<\/p>\n<\/blockquote>\n<blockquote>\n<p>Nueva York La ciudad, la m\u00e1s grande, es t\u00edpica: las iglesias cristianas son los principales clientes porque los musulmanes y los jud\u00edos celebran el culto los viernes y s\u00e1bados, cuando los espacios escolares generalmente se utilizan para actividades estudiantiles.<\/p>\n<\/blockquote>\n<blockquote>\n<p>&amp;bull ; Acts 29 Network, una coalici\u00f3n evang\u00e9lica interconfesional con sede en Seattle que ha iniciado 350 iglesias en todo el pa\u00eds en los \u00faltimos cinco a\u00f1os, estima que alrededor del 16 % de estas se re\u00fanen en espacios escolares.<\/p>\n<p>&#8220; No tenemos una agenda oculta. Nuestro coraz\u00f3n es servir a la comunidad al igual que las escuelas sirven a la comunidad. &#8230; Est\u00e1n dise\u00f1adas para grupos grandes, y cuentan con estacionamiento,&#8221; dice Scott Thomas, presidente de Acts 29.<\/p>\n<p>&bull; Una encuesta nacional de 2007 de iglesias protestantes reci\u00e9n establecidas encontr\u00f3 que el 12 % se reun\u00eda en las escuelas, seg\u00fan LifeWay, una agencia de investigaci\u00f3n cristiana con sede en Nashville.<\/p>\n<\/blockquote>\n<p>Aseg\u00farese de leer el art\u00edculo completo en&nbsp; USA Today.<\/p>\n<p>M\u00e1s detalles del estudio mencionado se pueden encontrar en&nbsp;Viral Churches&nbsp;y provienen de un estudio que hicimos en el Center for Missional Research. Puede descargar ese informe&nbsp;aqu\u00ed.<\/p>\n<p>Obviamente, hay algunos problemas legales aqu\u00ed. No soy abogado y nunca he interpretado uno en la televisi\u00f3n, pero creo que el problema con el fallo de la escuela de Nueva York es que discrimina sobre la base del \u00abcontenido del discurso\u00bb. En otras palabras, alquilan a otros grupos, pero quieren prohibir las iglesias porque las iglesias hablan de Dios.<\/p>\n<p>Una pol\u00edtica mejor, y que espero que la Corte Suprema defienda, es la de acceso equitativo. La Corte Suprema tiene un historial de defender la igualdad de acceso en casos como&nbsp;Lamb&#8217;s Chapel v. Center Moriches School District&nbsp;y&nbsp;Good News Club v. Milford Central School. He escrito m\u00e1s sobre esto en mi libro,&nbsp;<em>Plantando iglesias misionales<\/em>, pero haga clic en los enlaces para ver los res\u00famenes de esos fallos.<\/p>\n<p>Tenga en cuenta que este \u00faltimo El fallo no es de la Corte Suprema, sino de un tribunal de circuito. Por lo tanto, no es la ley de todo el pa\u00eds, todav\u00eda. Este caso puede ser escuchado a nivel de la Corte Suprema (si se le otorga lo que se llama &#8220;cert&#8220;). Mi expectativa es que la Corte Suprema se ponga del lado de precedentes anteriores y revoque el fallo de la Corte de Apelaciones del Segundo Circuito. Los verdaderos expertos legales (a diferencia de m\u00ed) tienden a estar de acuerdo en&nbsp;una historia \u00fatil&nbsp;Christianity Today&nbsp;sobre el tema.<\/p>\n<p>En pocas palabras, creo que si alquila su escuela p\u00fablica al club Kiwanis, tiene para alquilarlo tambi\u00e9n a grupos religiosos (y, s\u00ed, eso incluye iglesias y de otras religiones tambi\u00e9n). Los edificios p\u00fablicos deben ser accesibles al p\u00fablico por igual.<\/p>\n<p>La junta escolar no es el lugar para decidir si los que alquilan una escuela est\u00e1n utilizando o no un discurso aceptable para el gobierno. Mientras ese discurso sea legal, no deber\u00eda ser discriminado.<\/p>\n<p>Esto no est\u00e1 exento de dificultades, ya que eso significa que tienes que alquilar a personas que quiz\u00e1s no te gusten o no aprueben, pero eso es todo. parte de la libertad de expresi\u00f3n.<\/p>\n<p>Mi madre, directora de escuela jubilada, ten\u00eda una opini\u00f3n diferente. Ella cree que alquilar su escuela a una iglesia significa que tambi\u00e9n tiene que alquilar su escuela a otros grupos religiosos que luego se convertir\u00edan en una distracci\u00f3n para su trabajo: educar a los ni\u00f1os. Por ello, cree que lo mejor es no alquilar a nadie.<\/p>\n<p><em>\u00bfQui\u00e9n tiene raz\u00f3n? \u00bfMi madre, yo, el Segundo Circuito o la Corte Suprema? Comparta sus pensamientos en los comentarios.<\/em><\/p>\n<p>Republicado con permiso de&nbsp;Edstetzer.com. Puede comentar a continuaci\u00f3n o, si desea interactuar con Ed, comentar en la publicaci\u00f3n original de su blog&nbsp;aqu\u00ed.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las iglesias sin edificios est\u00e1n en las noticias, en la portada de USA Today, nada menos. El fen\u00f3meno es cada vez m\u00e1s com\u00fan. El domingo, con humor&nbsp;envi\u00e9 un blog sobre nuestra propia experiencia esta semana. Incluso hay un libro llamado &nbsp;La Iglesia N\u00f3mada. La&nbsp;USA Today&nbsp;historia cita algunos hechos r\u00e1pidos que incluyen: &amp;bull ; Una mirada &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/iglesias-sin-edificios-en-usa-today\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abIglesias sin edificios en USA Today\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-58611","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/58611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=58611"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/58611\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=58611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=58611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=58611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}