{"id":58616,"date":"2022-08-03T23:58:49","date_gmt":"2022-08-04T04:58:49","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/tratando-de-lucir-bien-el-domingo\/"},"modified":"2022-08-03T23:58:49","modified_gmt":"2022-08-04T04:58:49","slug":"tratando-de-lucir-bien-el-domingo","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/tratando-de-lucir-bien-el-domingo\/","title":{"rendered":"Tratando de lucir bien el domingo"},"content":{"rendered":"<p>Me gusta conducir a la iglesia con m\u00fasica de adoraci\u00f3n puesta. A menudo ayuda a guiar mi mente al lugar correcto. A veces lo veo como poner mi &ldquo;cara de juego&rdquo; para la adoraci\u00f3n En otras palabras, me estoy poniendo la m\u00e1scara.<\/p>\n<p>El domingo pasado me di cuenta de que eso puede ser un problema.<\/p>\n<p>El hecho de que siento la necesidad de convertirme de alguna manera en alguien diferente es una indicaci\u00f3n de que no siempre vivo mi d\u00eda a d\u00eda en contacto con el Esp\u00edritu de Dios. Si bien es bueno que al menos pueda darme cuenta y tomar medidas para volver a sintonizarme con Dios, \u00bfsolo estoy tomando estas medidas cuando estoy en camino a adorar a Dios en una habitaci\u00f3n llena de hermanos cristianos?<\/p>\n<p>Me viene a la mente la palabra hip\u00f3crita.<\/p>\n<p>Honestamente, todo este proceso es una de las razones por las que voy a la iglesia: necesito recordatorios y responsabilidad para mantenerme conectado con Dios. Adorar en comunidad me recuerda que debo buscar a Dios, incluso si no encuentro que la mayor\u00eda de los servicios de la iglesia hoy en d\u00eda sean particularmente \u00fatiles para, ya sabes, encontrarme con Dios. Tienden a estar bastante ocupados.<\/p>\n<p>Por lo que puedo ver, mis luchas con la hipocres\u00eda tienen un lado positivo. Al menos recibo una indicaci\u00f3n de cu\u00e1ndo no estoy en la misma sinton\u00eda con Dios. El truco es preocuparse solo por lo que Dios piensa acerca de esto.<\/p>\n<p>Todos necesitamos ser edificados por tiempo con Dios. Necesitamos ser fortalecidos por el poder del Esp\u00edritu, ya sea que estemos solos todo el d\u00eda o&nbsp; interact\u00fao con cientos de personas.<\/p>\n<p>Cuando siento ese tir\u00f3n para obtener mi &ldquo;acto&rdquo; espiritual; juntos para la iglesia, tengo una idea de mi necesidad de Dios. El truco es confesar mis motivaciones equivocadas. Necesito m\u00e1s de Dios todo el tiempo, no solo cuando estoy con otros cristianos.<\/p>\n<p>Ese es el problema con la hipocres\u00eda. Por lo general, nos lleva a hacer cosas buenas por razones equivocadas. En el caso del cristianismo, la hipocres\u00eda puede ser agotadora y aterradora. Nos preocupamos por lo que los dem\u00e1s pensar\u00e1n de nosotros si descubren qui\u00e9nes somos en realidad. Olvid\u00e9 que, por lo general, no tengo problemas para pasar por alto los defectos de los dem\u00e1s, pero si alguien realmente me mir\u00f3, todo se acab\u00f3.<\/p>\n<p>Ser\u00e9 honesto contigo, siento ese tir\u00f3n para sentarme contigo Dios ahora mismo. Estoy sentado en mi sala de estar un martes por la ma\u00f1ana. Nadie ver\u00e1 el impacto inmediato de Dios en mi vida, pero espero que a medida que Dios me cambie y yo viva para \u00e9l, esos pasos graduales me convertir\u00e1n en el tipo de persona que puede llegar a la iglesia en paz con Dios, sin preocuparse por la forma en que aparecer\u00e9 ante los dem\u00e1s.<\/p>\n<p>A\u00fan llevar\u00e9 mi reproductor de mp3 por si tengo ganas de escuchar m\u00fasica. esto &hellip; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Me gusta conducir a la iglesia con m\u00fasica de adoraci\u00f3n puesta. A menudo ayuda a guiar mi mente al lugar correcto. A veces lo veo como poner mi &ldquo;cara de juego&rdquo; para la adoraci\u00f3n En otras palabras, me estoy poniendo la m\u00e1scara. El domingo pasado me di cuenta de que eso puede ser un problema. &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/tratando-de-lucir-bien-el-domingo\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abTratando de lucir bien el domingo\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-58616","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/58616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=58616"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/58616\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=58616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=58616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=58616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}