{"id":58675,"date":"2022-08-04T00:01:49","date_gmt":"2022-08-04T05:01:49","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/deberian-los-cristianos-evitar-harry-potterotra-vez\/"},"modified":"2022-08-04T00:01:49","modified_gmt":"2022-08-04T05:01:49","slug":"deberian-los-cristianos-evitar-harry-potterotra-vez","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/deberian-los-cristianos-evitar-harry-potterotra-vez\/","title":{"rendered":"\u00bfDeber\u00edan los cristianos evitar Harry Potter&#8230;Otra vez?"},"content":{"rendered":"<p>Como esta semana&nbsp;presenta la instalaci\u00f3n final de la muy popular serie de pel\u00edculas <em>Harry Potter<\/em>, los cristianos nuevamente se preguntan si deben evitar las historias y las pel\u00edculas. Despu\u00e9s de todo, los personajes principales son brujas y brujos que lanzan hechizos y realizan actos m\u00e1gicos casi constantemente. Sacerdote episcopal y Ph.D. de la Universidad de Boston. la candidata Danielle Tumminio imparte un seminario en Yale sobre teolog\u00eda cristiana y la serie <em>Harry Potter<\/em>, y recientemente escribi\u00f3 un comentario para Religion News Service sobre este tema.<\/p>\n<p>Tumminio compar\u00f3 las pel\u00edculas con otras historias de fantas\u00eda como <em>El Se\u00f1or de los Anillos<\/em> y <em>Las Cr\u00f3nicas de Narnia<\/em> en el sentido de que deben evaluarse con un &#8220;enfoque global&#8221; y no simplemente sobre la base de sus detalles. De la misma manera, dice, los cristianos no pueden tomar algunos vers\u00edculos de la Biblia y afirmar que solo representan una cosmovisi\u00f3n cristiana. \u201cEl cristianismo se define por mucho m\u00e1s que su postura sobre la brujer\u00eda. Se trata de c\u00f3mo amar bien, si hay vida despu\u00e9s de la muerte, si nuestros errores pueden ser perdonados y qu\u00e9 tipo de esperanza hay para el futuro.<\/p>\n<p>M\u00e1s all\u00e1 del escenario de la pel\u00edcula, dice Tumminio, los personajes de la serie <em>Harry Potter<\/em> est\u00e1n en un viaje de fe que busca aprender sobre la confianza, el amor, el poder y la amistad. &#8220;&#8230;No es coincidencia que Harry juegue como Buscador en el equipo de Quidditch de Hogwarts. En muchos sentidos, est\u00e1 buscando no solo la snitch dorada, sino tambi\u00e9n una forma de ser fiel al concepto del amor, que a su vez se manifiesta en su lucha por amar a sus vecinos y honrar a sus padres. Tumminio&nbsp;dijo&nbsp;que sus estudiantes usaron la experiencia en su seminario ya que los cin\u00e9filos podr\u00edan usar la pel\u00edcula como una oportunidad para hablar sobre la fe con sus padres y compa\u00f1eros.&nbsp;&nbsp; esto &hellip; <\/p>\n<p><strong>\u00bfQu\u00e9 opinas? \u00bfLa serie de libros y pel\u00edculas de <em>Harry Potter<\/em> brinda la oportunidad de hablar sobre temas de fe, o promueven el mal y, por lo tanto, deben evitarse? Presente sus pensamientos a continuaci\u00f3n.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como esta semana&nbsp;presenta la instalaci\u00f3n final de la muy popular serie de pel\u00edculas Harry Potter, los cristianos nuevamente se preguntan si deben evitar las historias y las pel\u00edculas. Despu\u00e9s de todo, los personajes principales son brujas y brujos que lanzan hechizos y realizan actos m\u00e1gicos casi constantemente. Sacerdote episcopal y Ph.D. de la Universidad de &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/deberian-los-cristianos-evitar-harry-potterotra-vez\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfDeber\u00edan los cristianos evitar Harry Potter&#8230;Otra vez?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-58675","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/58675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=58675"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/58675\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=58675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=58675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=58675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}