{"id":58679,"date":"2022-08-04T00:01:59","date_gmt":"2022-08-04T05:01:59","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/nueva-pelicula-ofrece-el-primer-heroe-abiertamente-ateo\/"},"modified":"2022-08-04T00:01:59","modified_gmt":"2022-08-04T05:01:59","slug":"nueva-pelicula-ofrece-el-primer-heroe-abiertamente-ateo","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/nueva-pelicula-ofrece-el-primer-heroe-abiertamente-ateo\/","title":{"rendered":"Nueva pel\u00edcula ofrece el primer h\u00e9roe abiertamente ateo"},"content":{"rendered":"<p><strong>8 de julio de 2011<\/strong><\/p>\n<p>CNN BeliefBlog inform\u00f3 sobre un nuevo largometraje de suspenso que se estrenar\u00e1 en Los \u00c1ngeles y Nueva York esta semana llamada <em>The Ledge<\/em>, que IMDb llama &#8220;un thriller en el que una batalla de filosof\u00edas entre un fundamentalista cristiano y un ateo se convierte en una letal batalla de voluntades&#8221;. El productor de la pel\u00edcula, Matthew Chapman, un ateo ac\u00e9rrimo, dice que la pel\u00edcula presenta al primer h\u00e9roe abiertamente ateo de Hollywood y que \u00absu misi\u00f3n es ayudar a crear una imagen m\u00e1s positiva del ate\u00edsmo, lo cual dice a menudo se malinterpreta y se difama.&#8221; La pel\u00edcula presenta un elenco de primer nivel que incluye a Liv Tyler, Terrence Howard y Patrick Wilson y cuenta la historia de un esposo cristiano conservador y un ateo que sedujeron a la esposa cristiana del hombre religioso. &#8220;No hice la pel\u00edcula para los ateos, sino para la gente del centro del pa\u00eds que se pregunta de qu\u00e9 se trata &#8221; dijo Chapman. La pel\u00edcula fue nominada a Mejor Drama en el Festival de Cine de Sundance de 2011.&nbsp;&nbsp; esto &hellip; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>8 de julio de 2011 CNN BeliefBlog inform\u00f3 sobre un nuevo largometraje de suspenso que se estrenar\u00e1 en Los \u00c1ngeles y Nueva York esta semana llamada The Ledge, que IMDb llama &#8220;un thriller en el que una batalla de filosof\u00edas entre un fundamentalista cristiano y un ateo se convierte en una letal batalla de voluntades&#8221;. &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/nueva-pelicula-ofrece-el-primer-heroe-abiertamente-ateo\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abNueva pel\u00edcula ofrece el primer h\u00e9roe abiertamente ateo\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-58679","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/58679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=58679"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/58679\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=58679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=58679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=58679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}