{"id":8592,"date":"2022-07-26T10:49:36","date_gmt":"2022-07-26T15:49:36","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/que-les-pasa-a-nuestras-mujeres\/"},"modified":"2022-07-26T10:49:36","modified_gmt":"2022-07-26T15:49:36","slug":"que-les-pasa-a-nuestras-mujeres","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/que-les-pasa-a-nuestras-mujeres\/","title":{"rendered":"\u00bfQu\u00e9 les pasa a nuestras&nbsp;mujeres?"},"content":{"rendered":"<div class='resource__body'>\n<p>No nos cuesta mucho pensar en los hombres como depravados. Despu\u00e9s de todo, son responsables de la gran mayor\u00eda de los delitos violentos. <\/p>\n<ul>\n<li>90 % de los asesinatos<\/li>\n<li>98 % de las agresiones sexuales<\/li>\n<li>93 % de los robos a mano armada<\/li>\n<li>88 % de las agresiones simples <\/li>\n<\/ul>\n<p>Es impresionante. Y podr\u00eda llevarte razonablemente a pensar que los hombres son m\u00e1s malos y, por lo tanto, m\u00e1s culpables y necesitados ante Dios. Pero la palabra fiel de Dios nos ense\u00f1a lo contrario.<\/p>\n<p>John Piper habl\u00f3 recientemente sobre la necesidad espiritual de las mujeres y la renovaci\u00f3n que pueden encontrar en el evangelio. En solo 15 minutos, mostr\u00f3 que todos nosotros, hombres y mujeres, estamos total y completamente desesperados separados de Cristo, que nuestra depravaci\u00f3n secuestra a hombres y mujeres de manera diferente, y que Cristo m\u00e1s que restaura y renueva la verdadera feminidad de una mujer cuando la hace una parte de su novia.<\/p>\n<div class='resource__video'>\n<div class='video-embed'> <\/div>\n<\/p><\/div>\n<p>Este mensaje fue uno de los ocho mensajes cortos que se dieron en el Conferencia Nacional del Consejo para la Masculinidad y la Feminidad B\u00edblicas.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>No nos cuesta mucho pensar en los hombres como depravados. Despu\u00e9s de todo, son responsables de la gran mayor\u00eda de los delitos violentos. 90 % de los asesinatos 98 % de las agresiones sexuales 93 % de los robos a mano armada 88 % de las agresiones simples Es impresionante. Y podr\u00eda llevarte razonablemente a &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/que-les-pasa-a-nuestras-mujeres\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfQu\u00e9 les pasa a nuestras&nbsp;mujeres?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8592","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/8592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=8592"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/8592\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=8592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=8592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=8592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}