{"id":8593,"date":"2022-07-26T10:49:38","date_gmt":"2022-07-26T15:49:38","guid":{"rendered":"https:\/\/www.biblia.work\/articulos\/el-legado-que-quiero-dejar\/"},"modified":"2022-07-26T10:49:38","modified_gmt":"2022-07-26T15:49:38","slug":"el-legado-que-quiero-dejar","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos\/el-legado-que-quiero-dejar\/","title":{"rendered":"El legado que quiero dejar"},"content":{"rendered":"<div class='resource__body'>\n<p>Durante la mayor parte de mi vida pastoral, anunci\u00e9 las maravillas de lo que vi en la Biblia. <\/p>\n<p>Trat\u00e9 de hacer esto de tal manera que la gente pudiera ver que las maravillas realmente ven\u00edan de la Biblia, y no de m\u00ed. Pero rara vez me enfoqu\u00e9 en <em>c\u00f3mo<\/em> ve\u00eda las espectaculares verdades de las Escrituras. Mi predicaci\u00f3n y mis escritos apuntaban principalmente a llevar a la gente a un banquete, no a llevarla a la cocina.<\/p>\n<p>Cuando pienso en las pr\u00f3ximas generaciones, no me conformo con dejarles solamente un dep\u00f3sito de libros y sermones que celebrar las glorias de Dios y las maravillas del hedonismo cristiano. Un gran maestro me dijo una vez que ignorara las conclusiones de los comentarios y solo buscara sus argumentos. He intentado dar buenos argumentos. <\/p>\n<p>Pero debajo de todos los argumentos est\u00e1 el Libro. La biblia. Si las generaciones futuras solo aprenden <em>lo<\/em> que vimos, y no <em>c\u00f3mo<\/em> verlo por s\u00ed mismas, ser\u00e1n personas de segunda mano. Y los de segunda mano no pueden durar. Se aburren y aburren. El ministerio poderoso, que preserva la verdad, glorifica a Dios, exalta a Cristo, embelesa el alma y hace avanzar la misi\u00f3n se sustenta en el poder de ver por s\u00ed mismo las glorias de la palabra de Dios.<\/p>\n<p>As\u00ed que tengo una nueva y pasi\u00f3n enfocada en ayudar a las personas a ver realmente las riquezas de la palabra de Dios por s\u00ed mismas, y eso tiene implicaciones nuevas y emocionantes para m\u00ed y para el ministerio de Desiring God.<\/p>\n<h2 id=\"aprender-a-leer-la-biblia -for-yourself\" data-linkify=\"true\">Aprenda a leer la Biblia por s\u00ed mismo<\/h2>\n<p>Primero, dedicar\u00e9 mucha energ\u00eda y tiempo para guiar a otros sobre c\u00f3mo encontrar significado en la Biblia. No predicar\u00e9 todos los fines de semana, sino que llevar\u00e9 a los estudiantes de Minneapolis, y a miles m\u00e1s de ustedes a trav\u00e9s de desiringGod.org, a profundizar conmigo en las alegr\u00edas del descubrimiento b\u00edblico. Para los estudiantes de la ciudad, esto suceder\u00e1 a trav\u00e9s de mi ense\u00f1anza en Bethlehem College and Seminary. Es un cambio significativo para m\u00ed, de heraldo semanal del banquete a entrenador semanal en la cocina.<\/p>\n<p>Pero, \u00bfqu\u00e9 pasa con otros de ustedes que nunca ir\u00e1n a seminario? En Deseando a Dios, hemos desarrollado dos nuevas respuestas que me parecen realmente emocionantes. <\/p>\n<p>Hemos lanzado Look at the Book, un nuevo m\u00e9todo en l\u00ednea para ense\u00f1ar la Biblia. <em>Mira el libro<\/em> es una serie continua de interacciones de video de 5 a 8 minutos con la Biblia en la que la c\u00e1mara est\u00e1 en el texto, no el maestro. Oir\u00e1s mi voz y ver\u00e1s c\u00f3mo mi pluma se abre paso en el significado del texto. Se\u00f1alo, hago un c\u00edrculo y subrayo el pasaje, mientras hablo sobre <em>c\u00f3mo<\/em> veo lo que veo.<\/p>\n<p>Nuestro objetivo principal es crear h\u00e1bitos de mente y formas de ver la Biblia que les ayuden a encontrar las riquezas de las Escrituras por s\u00ed mismos. Realmente creemos que los cristianos serios pueden ver m\u00e1s maravillas en la palabra de Dios de lo que alguna vez pensaron que podr\u00edan. Look at the Book es nuestro esfuerzo por darle vida a esa creencia.<\/p>\n<h2 id=\"un-simple-h\u00e1bito-que-podr\u00eda-cambiar-su-vida\" data-linkify=\"true\">A H\u00e1bito simple que podr\u00eda cambiar tu vida<\/h2>\n<p>Debo mi teolog\u00eda, mi ministerio y mi vida a este h\u00e1bito simple: Mirar el Libro. Por supuesto que es todo de gracia. Dios da el deseo. Dios da los ojos. Dios da la mente. Y cuando todo nuestro trabajo de estudio cuidadoso y expectante est\u00e1 hecho, fue Dios quien dio el trabajo y las riquezas. <\/p>\n<p>Pero eso no nos hace perezosos o distra\u00eddos. Saber que Dios mismo ha hablado completa e infaliblemente en la Biblia nos lleva a mirar y mirar y mirar, sin distraernos, asiduamente, persistentemente, en oraci\u00f3n, desesperadamente, hasta que veamos y hasta que nuestros corazones ardan. Como dijo Mart\u00edn Lutero, golpeamos el texto con nuestros ojos y nuestra mente y nuestro coraz\u00f3n y nuestra oraci\u00f3n hasta que produzca lo que Dios hizo que produzca. Luchamos con eso, como Jacob y el \u00e1ngel: \u201cNo te dejar\u00e9 ir hasta que me bendigas\u201d. <\/p>\n<p>Creemos que una clave para la fortaleza de la iglesia, la autenticidad de su adoraci\u00f3n, la profundidad de su compa\u00f1erismo y el coraje de la misi\u00f3n global, es que el pueblo de Dios tenga acero en su columna espiritual, que se forja en el horno de su propio trato de primera mano con Dios en la Biblia. Los veh\u00edculos de segunda mano no funcionar\u00e1n en estos tiempos dif\u00edciles.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durante la mayor parte de mi vida pastoral, anunci\u00e9 las maravillas de lo que vi en la Biblia. Trat\u00e9 de hacer esto de tal manera que la gente pudiera ver que las maravillas realmente ven\u00edan de la Biblia, y no de m\u00ed. Pero rara vez me enfoqu\u00e9 en c\u00f3mo ve\u00eda las espectaculares verdades de las &hellip; <a href=\"https:\/\/www.biblia.work\/articulos\/el-legado-que-quiero-dejar\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEl legado que quiero dejar\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8593","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/8593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/comments?post=8593"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/posts\/8593\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/media?parent=8593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/categories?post=8593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos\/wp-json\/wp\/v2\/tags?post=8593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}