{"id":11648,"date":"2022-06-19T22:53:48","date_gmt":"2022-06-20T03:53:48","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-1-cronicas-244-exegesis-y-hermeneutica-de-la-biblia-2\/"},"modified":"2022-06-19T22:53:48","modified_gmt":"2022-06-20T03:53:48","slug":"comentario-de-1-cronicas-244-exegesis-y-hermeneutica-de-la-biblia-2","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-1-cronicas-244-exegesis-y-hermeneutica-de-la-biblia-2\/","title":{"rendered":"Comentario de 1 Cr\u00f3nicas 24:4 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>Los hijos de Eleazar resultaron ser m\u00e1s numerosos que los de Itamar en cuanto a hombres principales, por lo que los organizaron as\u00ed: De los hijos de Eleazar hab\u00eda diecis\u00e9is jefes de casas paternas, y de los hijos de Itamar hab\u00eda ocho, seg\u00fan sus casas paternas.<\/i><\/b><\/h3>\n<p><b><i>m\u00e1s varones principales.<\/i><\/b> <span class='bible'>1Cr 15:6-12<\/span>.<\/p>\n<p>\n<b><i>hijos de Eleazar.<\/i><\/b> <span class='bible'>N\u00fam 25:11-13<\/span>.<\/p>\n<p><b><i>por sus casas paternas.<\/i><\/b> <span class='bible'>1Cr 23:24<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">Cuando se identific\u00f3 a los descendientes de las dos l\u00edneas, hubo\u00a0<b>diecis\u00e9is<\/b>\u00a0divisiones familiares de Eleazar y s\u00f3lo\u00a0<b>ocho<\/b>\u00a0de Itamar. Esto complic\u00f3 el proceso de divisi\u00f3n imparcial de las asignaciones de servicio. La soluci\u00f3n fue asignar los deberes por grupos. Evidentemente las descendencias sacerdotales servir\u00edan en turnos, pero el orden de sucesi\u00f3n se determinaba\u00a0<b>por suerte<\/b>.<\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p>Los deberes sacerdotales se repartieron en tiempos de David en veinticuatro grupos, diecis\u00e9is correspondientes a Eleazar, y ocho a Itamar. Las razones de que la familia de Eleazar tuviera el doble de grupos son: 1) que hab\u00eda recibido la primogenitura desde que sus hermanos mayores, Nadab y Abi\u00fa, hab\u00edan sido muertos (<span class='bible'>Lev 10:1-20<\/span>), 2) que ten\u00eda m\u00e1s descendientes, y 3) que sus descendientes ten\u00edan m\u00e1s capacidad como dirigentes. Estas divisiones serv\u00edan cada una de ellas bien 1) por dos per\u00edodos semanales anualmente, o, m\u00e1s probable, 2) por un per\u00edodo de un mes cada dos a\u00f1os (cp. <span class='bible'>1Cr 27:1-15<\/span>). Estos grupos vuelven a aparecer de nuevo en <span class='bible'>Neh 10:2-8<\/span>; <span class='bible'>Neh 12:1-7<\/span>; <span class='bible'>Neh 12:12-21<\/span>, y se extienden incluso hasta la \u00e9poca de Cristo (cp. <span class='bible'>Luc 1:5-9<\/span>). El resto del tiempo ministraban al pueblo en sus propias poblaciones.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p>NOTAS<\/p>\n<p>(1) \u201cSus (de ellos)\u201d, Sy y cinco mss heb.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p><p> los dividieron.  Los sacerdotes estaban divididos en 24 grupos. Cada grupo servir\u00eda por dos semanas cada a\u00f1o.<\/p>\n<p><h3 align='right'><i><b>Fuente: La Biblia de las Am\u00e9ricas<\/b><\/i><\/h3>\n<p>La divisi\u00f3n de los sacerdotes en 24 grupos significaba que cada grupo servir\u00eda dos semanas por a\u00f1o. De la forma en que el a\u00f1o jud\u00edo estaba dividido significaba que el servicio ser\u00eda rotativo. Este arreglo fue reinstituido despu\u00e9s del exilio y continu\u00f3 en tiempo del NT (v\u00e9ase nota en <span class='bible'>Luc 1:5<\/span>).<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio Anotada por Ryrie<\/b><\/i><\/h3>\n<p> Lit., <i>hijos<\/i> <\/p>\n<h3 align='right'><i><b>Fuente: La Biblia de las Am\u00e9ricas<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Los hijos de Eleazar resultaron ser m\u00e1s numerosos que los de Itamar en cuanto a hombres principales, por lo que los organizaron as\u00ed: De los hijos de Eleazar hab\u00eda diecis\u00e9is jefes de casas paternas, y de los hijos de Itamar hab\u00eda ocho, seg\u00fan sus casas paternas. m\u00e1s varones principales. 1Cr 15:6-12. hijos de Eleazar. N\u00fam &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-1-cronicas-244-exegesis-y-hermeneutica-de-la-biblia-2\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de 1 Cr\u00f3nicas 24:4 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11648","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/11648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=11648"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/11648\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=11648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=11648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=11648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}